{"id":9261,"date":"2022-06-18T11:15:48","date_gmt":"2022-06-18T10:15:48","guid":{"rendered":"https:\/\/www.siegfriedhagl.com\/?p=9261"},"modified":"2025-02-23T12:26:36","modified_gmt":"2025-02-23T11:26:36","slug":"die-spezielle-kultur-der-walser","status":"publish","type":"post","link":"https:\/\/www.siegfriedhagl.com\/ru\/%d1%81%d1%82%d1%80%d0%b0%d0%bd%d0%bd%d1%8b%d0%b5-%d0%b8%d1%81%d1%82%d0%be%d1%80%d0%b8%d0%b8\/the-special-culture-of-walser\/","title":{"rendered":"\u041e\u0441\u043e\u0431\u0430\u044f \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u0430 \u0412\u0430\u043b\u044c\u0437\u0435\u0440\u0430"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>Vom harten \u00dcberleben in den Alpen<\/strong><\/h4>\n\n\n\n<p>Zu den interessantesten Landschaften Europas geh\u00f6ren zweifellos die Alpen. Als Riegel schieben sie sich zwischen den Mittelmeerraum und die n\u00f6rdlicheren Bereiche Mitteleuropas. \u00dcber Jahrtausende galten sie als h\u00e4sslich, gef\u00e4hrlich, ungeeignet f\u00fcr die Landwirtschaft und als Hindernis f\u00fcr den Transitverkehr. Die Alpenp\u00e4sse wurden zwar schon vor Jahrtausenden \u00fcberschritten, doch die Besiedelung der Alpen erfolgte langsam und relativ sp\u00e4t.<\/p>\n\n\n\n<p>Als das Land in den Ebenen knapper wurde, drangen Siedler von allen Seiten auch in den Alpenraum vor. Diese Besiedelungsgeschichte erstreckte sich \u00fcber lange Zeitr\u00e4ume, sie ist h\u00f6chst kompliziert und wurde lange wenig beachtet.<\/p>\n\n\n\n<p>Vom 18. Jahrhundert an, als das Interesse der Wissenschaftler, sp\u00e4ter dann auch der Touristen, an den Alpen langsam erwachte, begannen Volkskundler sich auch f\u00fcr die Alpenbewohner mit ihrem, nicht selten einzigartigem Brauchtum zu interessieren.<\/p>\n\n\n\n<p>Unter den Bewohnern der Alpen gibt es eine besondere Gruppe, die erst sp\u00e4t Siedlungsm\u00f6glichkeiten in den Alpen suchte und dann auf Hochlagen ausweichen musste, da die Tallagen l\u00e4ngst besetzt waren: Die \u201eWalser\u201c mit ihren speziellen Traditionen.<\/p>\n\n\n\n<p>Seit Ende des 20. Jahrhunderts sind besonders Bergwanderer an den Walsern interessiert. Viele machen sich nun auf die Spurensuche nach Relikten aus einer Zeit, in der die Walser besondere Techniken entwickeln mussten, die es ihnen erlaubten, hoch im Gebirge zu \u00fcberleben.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Wer ist heute ein Walser?<\/strong><br>Die Walser sind urspr\u00fcnglich eine einfache bergb\u00e4uerliche Sprach- und Schicksalsgemeinschaft alemannischer Herkunft. Aber die neue Zeit hat ihre Lebensgrundlagen v\u00f6llig ver\u00e4ndert. Als ein \u201eWalser\u201c mag sich heute mit Recht betrachten, wer in der alten Heimat oder in den tieferen T\u00e4lern Walserdeutsch spricht oder wer einer Walsersippe angeh\u00f6rt. <\/p><cite>Paul Zinsli. (5, S. 874).<\/cite><\/blockquote>\n\n\n\n<p><strong>Woher kommen die Walser?<\/strong> <br>Der Name Walser kommt von Walliser. Sie gelten als deutschsprachiger Stamm, der einst aus dem Wallis eingewandert ist; \u00fcber die Gebirgsp\u00e4sse oder von S\u00fcden \u00fcber die T\u00e4ler. Vielleicht sind die Walser sogar der Rest des Gotenvolkes, das sich nach der Schlacht am Milchberg (552) dem Byzantinischen Feldherrn Narses unterwerfen musste. Vermutungen \u00fcber ihre Herkunft gibt es viele, sogar dass es sich zum Teil um versprengte Katharer und sonstige Religions-Fl\u00fcchtlinge gehandelt haben k\u00f6nnte. <br>Im Unterschied zu den im Oberwallis sesshaft gewordenen Alemannen, die man Walliser nennt, bezeichnet man die im Hochmittelalter aus dem obersten Rhone-Tal abgewanderten Kolonisten als Walser. &nbsp;&nbsp;<\/p>\n\n\n\n<p>Einigerma\u00dfen gut belegt scheint, dass die Walser nach dem 11. Jahrhundert in den Alpenraum eingewandert sind. Ihre Religion ist meist katholisch<a id=\"_ednref1\" href=\"#_edn1\">[i]<\/a>. Ihre verschiedenen Mundarten, die man noch heute h\u00f6ren kann, sind Abwandlungen der deutschen Sprache. Unterschiede in den Walserdialekten Italiens und Graub\u00fcndens (Schweiz) lassen auf verschiedene Einwanderungswellen schlie\u00dfen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Walser und Waldenser<\/strong> <br>Die \u201eWalser\u201c sind nicht zu verwechseln mit den \u201eWaldensern\u201c. <br>Die Waldenser sind eine, von dem Reformator Petrus Waldes aus Lyon (gest. vor 1218) im 12. Jahrhundert gegr\u00fcndete, protestantische Kirche, die von der Inquisition rigoros verfolgt wurde. Eines ihrer R\u00fcckzugsgebiete waren die schwer zug\u00e4nglichen \u201eWaldensert\u00e4ler\u201c der Westalpen (in Piemont an der Grenze zu Savoyen, Nordwestitalien). Zuerst in diesen T\u00e4lern toleriert, wurden sie im 17. Jahrhundert, im Zuge der Gegenreformation, auch hier verfolgt, so dass es heute nur noch wenige Bekenner dieser Religion gibt.<br>Die Waldenser werden gelegentlich mit den Katharern verglichen, doch sind die religi\u00f6sen Lehren dieser beiden christlichen Gemeinschaften keineswegs identisch. (Zum Thema &#8222;Katharer&#8220; lesen Sie unter &#8222;Kurz, knapp, kurios&#8220; auf Seite 302 &#8222;&#8220;Der Albigenser Kreuzzug&#8220;)<\/p><cite>(Wikipedia)<\/cite><\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\">Die Besiedlung der Alpen <\/h4>\n\n\n\n<p>Die ersten dauerhaften Bewohner von Hochlagen \u00fcber 1000 m waren im 7.\/8. Jahrhundert M\u00f6nche.<\/p>\n\n\n\n<p>Im Hochmittelalter folgte eine Zeit der Kriege und Wirren mit politischen Fl\u00fcchtlingen. Aber es gab auch neue Ideen, Verbesserungen der landwirtschaftlichen Anbaumethoden und bessere Arbeitsger\u00e4te.<\/p>\n\n\n\n<p>In der mittelalterlichen Warmzeit, von 12. Jahrhundert an, wurde das Klima milder, und die Vegetationsgrenze vorschob sich um etwa 200 H\u00f6henmeter. Getreideanbau und Viehzucht wurde auch in h\u00f6heren Lagen m\u00f6glich. Die Bev\u00f6lkerung war deutlich gewachsen. Kl\u00f6ster und weltliche F\u00fcrsten ermunterten abenteuerlustige Siedler, in bislang allenfalls als Weiden genutzte Hochlagen einzuwandern, W\u00e4lder zu roden, Felder anzulegen, Vieh zu z\u00fcchten, Siedlungen zu bauen und sich so eine neue Heimat zu schaffen. Verschiedene Verg\u00fcnstigungen, z. B. geringe Steuern oder Befreiung vom Wehrdienst, wurden versprochen. So zogen Gruppen von alemannischen Bauernfamilien vom Oberlauf der Rhone in verschiedenen Sch\u00fcben \u00fcber die Gebirgsp\u00e4sse und gr\u00fcndeten eine Vielzahl verstreuter Siedlungen im heutigen Italien, der Schweiz und \u00d6sterreich. Sie standen vor der Aufgabe, ein bisher nur tempor\u00e4r genutztes Gebiet ganzj\u00e4hrig zu bewohnen. Walsersiedlungen liegen daher h\u00e4ufig in Hocht\u00e4lern oder sogar in ausgesetztem Gel\u00e4nde, weil gutes Land in tieferen Lagen schon l\u00e4ngst von der alteinheimischen Bev\u00f6lkerung genutzt wurde.<\/p>\n\n\n\n<p>Diese Walserwanderungen begannen Ende des 12. Jahrhunderts und kamen um die Wende vom 15. zum 16. Jahrhundert zum Abschluss.<\/p>\n\n\n\n<p>Die Kolonisation der Walser gilt im Wesentlichen als \u201efriedliche Eroberung mit Axt und Sense\u201c. Doch ganz ohne Zusammenst\u00f6\u00dfe mit der einheimischen Bev\u00f6lkerung, die viele der nun von den Walsern besetzten Hochlagen l\u00e4ngst als Sommerweiden nutzte, wird es nicht abgegangen sein. Die historischen Quellen berichten kaum von derartigen Streitigkeiten; zu einem ernsthaften Eroberungskrieg kann es bei den kleinen Gruppen der Betroffenen nicht gekommen sein.<\/p>\n\n\n\n<p>Als dann Mitte des 16. Jahrhunderts die Kleine Eiszeit mit Gletschervorst\u00f6\u00dfen einsetzte, mussten etliche Walsersiedlungen aufgegeben werden, und ihre Bewohner ins Tal ziehen. Als Minderheiten inmitten der romanischen Bev\u00f6lkerung wurden sie dort bald assimiliert.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u00dcberleben im Gebirge<\/h4>\n\n\n\n<p>Die Wanderungen der Walser fielen in eine Epoche des \u00dcbergangs von der Kleintierzucht (Schafe und Ziegen) zur Rinderhaltung. Die Walserbauern f\u00fchrten bei ihren Wanderungen wohl nur Schafe und Ziegen mit, und sie blieben diesen Nutztieren Jahrhunderte lang treu. In der Tat sind Schafe und Ziegen im steilen Berggel\u00e4nde leichter zu halten als die schwereren Rinder. Diese sind allerdings als Tauschware f\u00fcr die M\u00e4rkte im Tal geeigneter. Die Walser belieferten die lokalen M\u00e4rkte mit Vieh, Butter, K\u00e4se und Trockenfleisch. Daf\u00fcr konnten sie Getreide, Leder, Salz, Werkzeuge wie Sensen, Wein usw. eintauschen.<\/p>\n\n\n\n<p>Um in den Hochlagen zurechtzukommen, half eine f\u00fcr die Walser typische Erfindung: Die Walserbauern im Osten brachten das Futter von den Hochalmen nicht hinab in die Siedlungen. Um l\u00e4ngere Transportwege einzusparen, wurde das im Sommer geerntete Heu in Stallscheunen eingelagert, die sich auf den Almen befanden. Im Herbst zog dann das Vieh etappenweise bergab in diese \u201eAusf\u00fctterungsst\u00e4lle\u201c. Diese verf\u00fcgten meist noch \u00fcber einen bescheidenen Wohnteil. Dann erst ging es hinab in die eigentliche Siedlung zum \u00dcberwintern.<\/p>\n\n\n\n<p>Inneralpine T\u00e4ler erhalten oft \u2013 im Gegensatz zu den Randbereichen \u2013 wenig Niederschlag. Daher mussten mancherorts die von den Gletschern abflie\u00dfenden B\u00e4che angezapft, und ihr Wasser auf die Felder verteilt werden<a href=\"#_edn2\" id=\"_ednref2\">[ii]<\/a>.<\/p>\n\n\n\n<p>Es war ein hartes Leben, und wer die eine oder andere Walsersiedlung aufgesucht hat, und sich das dortige Leben vor Jahrhunderten vorstellt, ist beeindruckt von dem \u00dcberlebenswillen und dem harten \u00dcberlebenskampf der Walser.<\/p>\n\n\n\n<p>Noch heute ist die kleine Walser-Siedlung Juf in 2126 m \u00fcber dem Meer (bei Avers in Graub\u00fcnden\/Schweiz) das h\u00f6chstgelegene, dauerhaft besiedelte Dorf Europas<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Die Walser heute<\/h4>\n\n\n\n<p>Heute finden sich noch rund 150 Walser-Siedlungen mit ca. 40.000 Menschen, die \u00fcber 300 km Luftlinie vom s\u00fcdwalserischen Gressoney im Aostatal (Italien) bis zum ostwalserischen Mittelberg (Allg\u00e4uer Alpen) verstreut liegen. F\u00fcr die wenigen, noch in den alten Gebirgssiedlungen lebenden Walser hat sich das Leben grundlegend ge\u00e4ndert. Die Siedlungen sind mit Elektrizit\u00e4t versorgt, auf Stra\u00dfen erreichbar, und landwirtschaftliche Maschinen bestimmen die Bewirtschaftung auf den noch rentabel gebliebenen Fl\u00e4chen oder H\u00e4ngen im Gebirge.<\/p>\n\n\n\n<p>Zunehmende Beachtung finden neuerdings die Walser bei Bergwanderern. Diese sp\u00fcren den Relikten aus dem harten Leben der Walser im Hochgebirge nach, bewundern die alten Holzh\u00e4user in Blockbauweise, nicht selten aus L\u00e4rchenholz, manchmal noch mit Granitplatten gedeckt, und lassen sich vom speziellen alten Brauchtum der Walser berichten. Nicht zu vergessen die f\u00fcr das Wallis und die Walser typischen Speicher mit den charakteristischen \u201eM\u00e4useplatten\u201c, die das Eindringen von Ratten und M\u00e4usen verhindern.<\/p>\n\n\n\n<p>Wer das freundliche Volk der Walser genauer kennen lernen will, der kann auf alten Walserwegen durch das Gebirge wandern; z. B. auf dem \u201eGro\u00dfen Walserweg\u201c (2). Dieser f\u00fchrt auf 29 Etappen von Zermatt nach Mittelberg. Die wenigsten werden ihn ganz gehen, aber auch die eine oder andere Etappe ist eine Wanderung wert.<\/p>\n\n\n\n<p>So hat auch der Tourismus in den D\u00f6rfern der Walser Einzug gehalten und es fehlt nicht an Hotels, Restaurants, Cafes und L\u00e4den f\u00fcr Reiseandenken.<\/p>\n\n\n\n<p><strong>Literatur:<\/strong> <br>(1) Balmer Emil, Die Walser im Piemont, A. Francke, Bern, 1949. <br>(2) Irlinger Bernhard, Der grosse Walserweg, J. Berg, M\u00fcnchen. 1996. <br>(3) Waibel Max, Unterwegs zu den Walsern, Huber, CH-8501 Frauenfeld, 2003. <br>(4) Welte Adalbert, Die gro\u00dfe Flucht (Roman), \u00d6sterreichische Buchgemeinschaft, 1952. <br>(5) Zinsli Paul, Handbuch der Schweizerischen Volkskultur, Band 2, 1992. <br>(6) http;\/\/www.kleinwalsertal.com\/tal-walser\/die-walser.html. <br> (7) <a href=\"http:\/\/www.walserweg.com\/\">http:\/\/www.walserweg.com<\/a>. <\/p>\n\n\n\n<p><strong>Endnoten: <\/strong><br>[<a id=\"_edn1\" href=\"#_ednref1\">i]<\/a> Nur einzelne Gemeinden schlossen sich der Reformation an. <br><a id=\"_edn2\" href=\"#_ednref2\">[ii]<\/a> Die kompliziertesten Anlagen dieser Art waren die \u201eheiligen Wasser\u201c des Wallis. Hier wurden Wasserleitungen (Suonen genannt) manchmal hoch an Felsw\u00e4nden entlang gef\u00fchrt. Die Reparaturen der steinschlag- und lawinengef\u00e4hrdeten Leitungen waren nicht selten lebensgef\u00e4hrlich. Der Roman \u201eAn heiligen Wassern\u201c von Jakob Christoph Heer von 1898 hat dieses Thema dichterisch verarbeitet. Dieser Roman wurde 1960 verfilmt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Vom harten \u00dcberleben in den Alpen Zu den interessantesten Landschaften Europas geh\u00f6ren zweifellos die Alpen. Als Riegel schieben sie sich zwischen den Mittelmeerraum und die n\u00f6rdlicheren Bereiche Mitteleuropas. \u00dcber Jahrtausende galten sie als h\u00e4sslich, gef\u00e4hrlich, ungeeignet f\u00fcr die Landwirtschaft und als Hindernis f\u00fcr den Transitverkehr. Die Alpenp\u00e4sse wurden zwar schon vor Jahrtausenden \u00fcberschritten, doch die [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-9261","post","type-post","status-publish","format-standard","hentry","category-merkwuerdige-geschichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die spezielle Kultur der Walser &#8211; SiegfriedHagl.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siegfriedhagl.com\/ru\/\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0435-\u0438\u0441\u0442\u043e\u0440\u0438\u0438\/the-special-culture-of-walser\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die spezielle Kultur der Walser &#8211; SiegfriedHagl.com\" \/>\n<meta property=\"og:description\" content=\"Vom harten \u00dcberleben in den Alpen Zu den interessantesten Landschaften Europas geh\u00f6ren zweifellos die Alpen. Als Riegel schieben sie sich zwischen den Mittelmeerraum und die n\u00f6rdlicheren Bereiche Mitteleuropas. \u00dcber Jahrtausende galten sie als h\u00e4sslich, gef\u00e4hrlich, ungeeignet f\u00fcr die Landwirtschaft und als Hindernis f\u00fcr den Transitverkehr. Die Alpenp\u00e4sse wurden zwar schon vor Jahrtausenden \u00fcberschritten, doch die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siegfriedhagl.com\/ru\/\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0435-\u0438\u0441\u0442\u043e\u0440\u0438\u0438\/the-special-culture-of-walser\/\" \/>\n<meta property=\"og:site_name\" content=\"SiegfriedHagl.com\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-18T10:15:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-23T11:26:36+00:00\" \/>\n<meta name=\"author\" content=\"siegfriedhagl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c\" \/>\n\t<meta name=\"twitter:data1\" content=\"siegfriedhagl\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/die-spezielle-kultur-der-walser\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/die-spezielle-kultur-der-walser\\\/\"},\"author\":{\"name\":\"siegfriedhagl\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"headline\":\"Die spezielle Kultur der Walser\",\"datePublished\":\"2022-06-18T10:15:48+00:00\",\"dateModified\":\"2025-02-23T11:26:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/die-spezielle-kultur-der-walser\\\/\"},\"wordCount\":1524,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"articleSection\":[\"Merkw\u00fcrdige Geschichten\"],\"inLanguage\":\"ru-RU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/die-spezielle-kultur-der-walser\\\/\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/die-spezielle-kultur-der-walser\\\/\",\"name\":\"Die spezielle Kultur der Walser &#8211; SiegfriedHagl.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\"},\"datePublished\":\"2022-06-18T10:15:48+00:00\",\"dateModified\":\"2025-02-23T11:26:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/die-spezielle-kultur-der-walser\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/die-spezielle-kultur-der-walser\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/die-spezielle-kultur-der-walser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die spezielle Kultur der Walser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\",\"name\":\"SiegfriedHagl.com\",\"description\":\"Artikel und Blog von Siegfried Hagl\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\",\"name\":\"siegfriedhagl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"caption\":\"siegfriedhagl\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.hagl.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041e\u0441\u043e\u0431\u0430\u044f \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u0430 \u0412\u0430\u043b\u044c\u0437\u0435\u0440\u0430 - SiegfriedHagl.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siegfriedhagl.com\/ru\/\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0435-\u0438\u0441\u0442\u043e\u0440\u0438\u0438\/the-special-culture-of-walser\/","og_locale":"ru_RU","og_type":"article","og_title":"Die spezielle Kultur der Walser &#8211; SiegfriedHagl.com","og_description":"Vom harten \u00dcberleben in den Alpen Zu den interessantesten Landschaften Europas geh\u00f6ren zweifellos die Alpen. Als Riegel schieben sie sich zwischen den Mittelmeerraum und die n\u00f6rdlicheren Bereiche Mitteleuropas. \u00dcber Jahrtausende galten sie als h\u00e4sslich, gef\u00e4hrlich, ungeeignet f\u00fcr die Landwirtschaft und als Hindernis f\u00fcr den Transitverkehr. Die Alpenp\u00e4sse wurden zwar schon vor Jahrtausenden \u00fcberschritten, doch die [&hellip;]","og_url":"https:\/\/www.siegfriedhagl.com\/ru\/\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0435-\u0438\u0441\u0442\u043e\u0440\u0438\u0438\/the-special-culture-of-walser\/","og_site_name":"SiegfriedHagl.com","article_published_time":"2022-06-18T10:15:48+00:00","article_modified_time":"2025-02-23T11:26:36+00:00","author":"siegfriedhagl","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c":"siegfriedhagl","\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"9 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/die-spezielle-kultur-der-walser\/#article","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/die-spezielle-kultur-der-walser\/"},"author":{"name":"siegfriedhagl","@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"headline":"Die spezielle Kultur der Walser","datePublished":"2022-06-18T10:15:48+00:00","dateModified":"2025-02-23T11:26:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/die-spezielle-kultur-der-walser\/"},"wordCount":1524,"publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"articleSection":["Merkw\u00fcrdige Geschichten"],"inLanguage":"ru-RU"},{"@type":"WebPage","@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/die-spezielle-kultur-der-walser\/","url":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/die-spezielle-kultur-der-walser\/","name":"\u041e\u0441\u043e\u0431\u0430\u044f \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u0430 \u0412\u0430\u043b\u044c\u0437\u0435\u0440\u0430 - SiegfriedHagl.com","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/#website"},"datePublished":"2022-06-18T10:15:48+00:00","dateModified":"2025-02-23T11:26:36+00:00","breadcrumb":{"@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/die-spezielle-kultur-der-walser\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/die-spezielle-kultur-der-walser\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/die-spezielle-kultur-der-walser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.siegfriedhagl.com\/"},{"@type":"ListItem","position":2,"name":"Die spezielle Kultur der Walser"}]},{"@type":"WebSite","@id":"https:\/\/www.siegfriedhagl.com\/#website","url":"https:\/\/www.siegfriedhagl.com\/","name":"SiegfriedHagl.com","description":"\u0421\u0442\u0430\u0442\u044c\u044f \u0438 \u0431\u043b\u043e\u0433 \u0417\u0438\u0433\u0444\u0440\u0438\u0434\u0430 \u0425\u0430\u0433\u043b\u044f","publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siegfriedhagl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":["Person","Organization"],"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f","name":"\u0437\u0438\u0433\u0444\u0440\u0438\u0434\u0445\u0430\u0433\u043b\u044c","image":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","caption":"siegfriedhagl"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.hagl.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/9261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/comments?post=9261"}],"version-history":[{"count":15,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/9261\/revisions"}],"predecessor-version":[{"id":9290,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/9261\/revisions\/9290"}],"wp:attachment":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/media?parent=9261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/categories?post=9261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/tags?post=9261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}