{"id":8440,"date":"2021-12-27T12:05:40","date_gmt":"2021-12-27T11:05:40","guid":{"rendered":"https:\/\/www.siegfriedhagl.com\/?p=8440"},"modified":"2022-05-14T10:45:34","modified_gmt":"2022-05-14T09:45:34","slug":"der-echte-robinson","status":"publish","type":"post","link":"https:\/\/www.siegfriedhagl.com\/ru\/%d1%81%d1%82%d1%80%d0%b0%d0%bd%d0%bd%d1%8b%d0%b5-%d0%b8%d1%81%d1%82%d0%be%d1%80%d0%b8%d0%b8\/%d0%bd%d0%b0%d1%81%d1%82%d0%be%d1%8f%d1%89%d0%b8%d0%b9-%d1%80%d0%be%d0%b1%d0%b8%d0%bd%d0%b7%d0%be%d0%bd\/","title":{"rendered":"\u041d\u0430\u0441\u0442\u043e\u044f\u0449\u0438\u0439 \u0420\u043e\u0431\u0438\u043d\u0437\u043e\u043d"},"content":{"rendered":"\n<p>Zu der Zeit als ich zur Schule ging, kannte fast jedes Kind den \u201eRobinson Crusoe\u201c von Daniel Defoe (ca. 1660-1731). Das Buch gab es in etlichen Ausgaben, darunter auch vereinfachte Fassungen f\u00fcr Kinder, und \u201eRobinson\u201c wurde zum Synonym f\u00fcr einen Einsiedler auf einsamer Insel.<br>Der Bestseller fand Nachahmer, und die \u201eRobinsonaden\u201c \u2013 Abenteuergeschichten um Segelschiffe, Schiffbr\u00fcchige und einsame Inseln \u2013 wurden zu einer eigenen Literaturgattung. Der englische Seeoffizier Frederick Marryat (1792-1848) als Beispiel, lie\u00df in seinem \u201eSigismund R\u00fcstig\u201c sogar eine ganze Familie an einer einsamen Inseln stranden, wo sie sich durchk\u00e4mpfen und sogar gegen blutr\u00fcnstige Eingeborene verteidigen musste.<\/p>\n\n\n\n<p>Defoes \u201eRobinson Crusoe\u201c war allerdings keine reine Phantasiegestalt, sondern hatte ein reales Vorbild:<\/p>\n\n\n\n<p><strong>Alexander Selkirk (1676-1721)<br><\/strong>Der geb\u00fcrtige Schotte war ein etwas wilder, erfahrener Seemann, der z. B. als Segelmeister[1] auf etlichen Schiffen, darunter auch Kaperschiffen, diente.<br>Im Oktober 1704 landete sein Schiff auf der \u201eIsla Mas a Tierra\u201c (im heutigen Juan-Fernandez-Archipel, westlich von Chile im Pazifik), um nach Trinkwasser zu suchen. Keine unentdeckte, doch sch\u00f6ne Insel mit ausreichend Vorr\u00e4ten f\u00fcr etliche Bewohner und reichlich Wasser. Das Klima ist ganzj\u00e4hrig ausgeglichen. Heute leben dort etwa 600 Menschen, vor allem Langustenfischer.<\/p>\n\n\n\n<p>Nach der Landung zeigte sich, dass der Schiffsrumpf stark von Bohrmuscheln[2] besch\u00e4digt war. Nach Selkirks Meinung konnte das Schiff den n\u00e4chsten Hafen nicht mehr erreichen. Der Kapit\u00e4n war anderer Meinung als der als Hitzkopf bekannte Selkirk und es kam zum Streit, der damit endete, dass Selkirk alleine auf der Insel zur\u00fcckblieb.<br>Das rettete ihm wahrscheinlich das Leben. Denn das Schiff war tats\u00e4chlich so stark besch\u00e4digt, dass es bald darauf kenterte und der gr\u00f6\u00dfte Teil der Besatzung ertrank.<\/p>\n\n\n\n<p>Selkirks bescheidene Ausr\u00fcstung bestand aus einer Muskete mit Munition, Feuerstein, etwas Tabak, Ersatzkleidung, einem Beil, einem Kochtopf und einer Bibel. Hinzu kam ein Messer, wie es jeder Seemann bei sich trug.<\/p>\n\n\n\n<p>Er kampierte zuerst am Strand, wohl in einer H\u00f6hle. Sp\u00e4ter fand er eine sch\u00f6ne Quelle, an der er sich eine H\u00fctte bauen konnte. \u00c4rger machten von einem Schiff eingeschleppte Ratten, die ihn so lange bel\u00e4stigten, bis es ihm gelang, ebenfalls angelandete Katzen zu z\u00e4hmen, die ihn dann sch\u00fctzen konnten.<\/p>\n\n\n\n<p>Die Ressourcen der Insel verstand er sehr geschickt zu nutzen:<br>* Am Strand gab es Schalentiere, aber auch gro\u00dfe, nicht ungef\u00e4hrliche Seel\u00f6wen. In einer Lagune konnte er Langusten und Fische erbeuten.<br>* Im Inneren der Insel fanden sich gl\u00fccklicherweise Ziegen, die Fleisch, Milch und Felle lieferten. Manche Kapit\u00e4ne setzten damals einige Ziegen auf einsamen Inseln aus. Als Notproviant f\u00fcr Schiffbr\u00fcchige oder als willkommene Zusatzkost f\u00fcr anlandende Schiffe. Ohne nat\u00fcrliche Feinde kamen diese Ziegen meist gut zurecht und vermehrten sich.<br>* Auch mit Pflanzen kannte sich Selkirk aus: Er fand wildwachsende Pastinaken mit karotten\u00e4hnlichen Wurzeln, die Gem\u00fcse lieferten, sowie Rettiche, Krauter und Pfefferbeeren als Erg\u00e4nzung zu seiner Fleischnahrung. Nur Salz vermisste er sehr. Durch seine abwechslungsreiche Nahrung blieb er gesunder als viele Seefahrer der Zeit, die oft unter Skorbut litten.<br>* Als seine Kleidung total verschlissen war, musste er sich mit selbst gebastelter Kleidung aus Ziegenfellen behelfen. L\u00f6cher konnte er wohl mit einem, sp\u00e4ter von Arch\u00e4ologen gefundenen Stechzirkel (ein f\u00fcr einen Segelmeister typisches Hilfsmittel) in die Felle stechen. Den Zwirn mussten Ziegen-Sehnen ersetzen. Schuhe wusste er nicht anzufertigen, nachdem die seinigen restlos abgetragen waren. Doch seine F\u00fc\u00dfe waren inzwischen so mit Hornhaut bedeckt, dass er auf Schuhe verzichten konnte.<br>* Er schaffte es sogar, aus den Reifen eines am Strand gefundenen Fasses, ein Messer zu schmieden. Dazu musste er zuerst Holzkohle erzeugen, f\u00fcr ein ausreichendes Schmiedefeuer. Er war ein vielseitiger Handwerker.<\/p>\n\n\n\n<p>Selkirk war mit seiner Selbstversorgung zeitlich gut ausgelastet, doch belastete ihn die Einsamkeit. Um nicht depressiv zu werden las er oft in der Bibel. Diese erz\u00e4hlt ja nicht nur von einem eifers\u00fcchtigen Rachegott, der jede Verfehlung streng bestraft, sondern enth\u00e4lt \u2013 vor allem im Neuen Testament \u2013 auch Worte der Hoffnung, die in Notlagen innere Kraft schenken k\u00f6nnen.<\/p>\n\n\n\n<p>Als 1707 ein spanisches Schiff anlandete, musste Selkirk ins Innere der Insel fliehen und sich verstecken. Die Spanier, die keine Ausl\u00e4nder in ihrem Revier duldeten, h\u00e4tten ihn als Freibeuter behandelt und einen kurzen, aber brutalen Prozess gemacht.<\/p>\n\n\n\n<p>Die Rettung brachte dann am 2. Februar 1709 das britische Kaperschiff Duke, das vor der Insel ankerte und Selkirk aufnahm. Er schloss sich der Besatzung an, deren Schiff, gesch\u00fctzt durch einen Kaperbrief[3], im Namen der Krone Englands Feinde bek\u00e4mpfte und ausraubte.<\/p>\n\n\n\n<p>Der einstige Insulaner kehrte dann 1711 mit einigem Verm\u00f6gen als Ber\u00fchmtheit f\u00fcr einige Zeit nach England zur\u00fcck.<br>Danach zog es ihn wieder zur See, wo er als Leutnant an Bord eines britischen Kriegsschiffs verstarb.<\/p>\n\n\n\n<p>Weithin bekannt gemacht wurde sein Insel-Abenteuer erstmals 1712 in dem Buch \u201eCruising Voyage\u201c von Woods Rogers. In neuester Zeit suchten Arch\u00e4ologen nach den Spuren seines Aufenthalts auf seiner Insel, die inzwischen, um ihn zu ehren, in \u201eAlejandro Selkirk\u201c umbenannt wurde.<\/p>\n\n\n\n<p><strong>Endnoten:<br><\/strong>[1] Der Segelmeister (engl. Sailing master) war ein erfahrener Seemann, der f\u00fcr die Navigation zust\u00e4ndig war. Etwa wie heute der Steuermann.<br>[2] Die Schiffsbohrmuschel (Schiffsbohrwurm, <em>Teredo navalis<\/em>) lebt in warmen bis gem\u00e4\u00dfigten Zonen im Salzwasser. Sie kann \u00fcberall Schaden anrichten, wo geeignete Holzbauten im Wasser stehen. Durch Holzschiffe wurde sie weltweit verschleppt. Zum Gl\u00fcck gibt es den Schiffsbohrwurm nicht in der nicht sehr salzhaltigen, k\u00fchlen Ostsee. Sonst k\u00f6nnten wir die barocke Wasa von 1628 nicht in ihrem Museum in Stockholm bewundern.<br>Erst vom Ende des 18. Jahrhunderts an wurden Schiffe regelm\u00e4\u00dfig mit Kupferplatten beschlagen, die gegen den Bohrwurm sch\u00fctzten, aber nicht immer lange genug hielten.<br>[3] Solche Kaperschiffe waren Seer\u00e4ubern recht \u00e4hnlich, nur dass sie sich bei ihren Kaperungen auf die Schiffe feindlicher L\u00e4nder beschr\u00e4nken mussten.<\/p>\n\n\n\n<p><strong>Literatur:<br><\/strong>(1) Wikipedia \u201eAlexander Selkirk\u201c.<br>(2) \u201eGestrandet im Paradie\u201c, Der Spiegel vom 2. 2. 2009, zum 300. Jahrestag der Rettung von Alexander Selkirk.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zu der Zeit als ich zur Schule ging, kannte fast jedes Kind den \u201eRobinson Crusoe\u201c von Daniel Defoe (ca. 1660-1731). Das Buch gab es in etlichen Ausgaben, darunter auch vereinfachte Fassungen f\u00fcr Kinder, und \u201eRobinson\u201c wurde zum Synonym f\u00fcr einen Einsiedler auf einsamer Insel.Der Bestseller fand Nachahmer, und die \u201eRobinsonaden\u201c \u2013 Abenteuergeschichten um Segelschiffe, Schiffbr\u00fcchige [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-8440","post","type-post","status-publish","format-standard","hentry","category-merkwuerdige-geschichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der echte Robinson &#8211; SiegfriedHagl.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siegfriedhagl.com\/ru\/\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0435-\u0438\u0441\u0442\u043e\u0440\u0438\u0438\/\u043d\u0430\u0441\u0442\u043e\u044f\u0449\u0438\u0439-\u0440\u043e\u0431\u0438\u043d\u0437\u043e\u043d\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der echte Robinson &#8211; SiegfriedHagl.com\" \/>\n<meta property=\"og:description\" content=\"Zu der Zeit als ich zur Schule ging, kannte fast jedes Kind den \u201eRobinson Crusoe\u201c von Daniel Defoe (ca. 1660-1731). Das Buch gab es in etlichen Ausgaben, darunter auch vereinfachte Fassungen f\u00fcr Kinder, und \u201eRobinson\u201c wurde zum Synonym f\u00fcr einen Einsiedler auf einsamer Insel.Der Bestseller fand Nachahmer, und die \u201eRobinsonaden\u201c \u2013 Abenteuergeschichten um Segelschiffe, Schiffbr\u00fcchige [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siegfriedhagl.com\/ru\/\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0435-\u0438\u0441\u0442\u043e\u0440\u0438\u0438\/\u043d\u0430\u0441\u0442\u043e\u044f\u0449\u0438\u0439-\u0440\u043e\u0431\u0438\u043d\u0437\u043e\u043d\/\" \/>\n<meta property=\"og:site_name\" content=\"SiegfriedHagl.com\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-27T11:05:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-14T09:45:34+00:00\" \/>\n<meta name=\"author\" content=\"siegfriedhagl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c\" \/>\n\t<meta name=\"twitter:data1\" content=\"siegfriedhagl\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/der-echte-robinson\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/der-echte-robinson\\\/\"},\"author\":{\"name\":\"siegfriedhagl\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"headline\":\"Der echte Robinson\",\"datePublished\":\"2021-12-27T11:05:40+00:00\",\"dateModified\":\"2022-05-14T09:45:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/der-echte-robinson\\\/\"},\"wordCount\":979,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"articleSection\":[\"Merkw\u00fcrdige Geschichten\"],\"inLanguage\":\"ru-RU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/der-echte-robinson\\\/\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/der-echte-robinson\\\/\",\"name\":\"Der echte Robinson &#8211; SiegfriedHagl.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\"},\"datePublished\":\"2021-12-27T11:05:40+00:00\",\"dateModified\":\"2022-05-14T09:45:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/der-echte-robinson\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/der-echte-robinson\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/merkwuerdige-geschichten\\\/der-echte-robinson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der echte Robinson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\",\"name\":\"SiegfriedHagl.com\",\"description\":\"Artikel und Blog von Siegfried Hagl\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\",\"name\":\"siegfriedhagl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"caption\":\"siegfriedhagl\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.hagl.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041d\u0430\u0441\u0442\u043e\u044f\u0449\u0438\u0439 \u0420\u043e\u0431\u0438\u043d\u0437\u043e\u043d - SiegfriedHagl.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siegfriedhagl.com\/ru\/\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0435-\u0438\u0441\u0442\u043e\u0440\u0438\u0438\/\u043d\u0430\u0441\u0442\u043e\u044f\u0449\u0438\u0439-\u0440\u043e\u0431\u0438\u043d\u0437\u043e\u043d\/","og_locale":"ru_RU","og_type":"article","og_title":"Der echte Robinson &#8211; SiegfriedHagl.com","og_description":"Zu der Zeit als ich zur Schule ging, kannte fast jedes Kind den \u201eRobinson Crusoe\u201c von Daniel Defoe (ca. 1660-1731). Das Buch gab es in etlichen Ausgaben, darunter auch vereinfachte Fassungen f\u00fcr Kinder, und \u201eRobinson\u201c wurde zum Synonym f\u00fcr einen Einsiedler auf einsamer Insel.Der Bestseller fand Nachahmer, und die \u201eRobinsonaden\u201c \u2013 Abenteuergeschichten um Segelschiffe, Schiffbr\u00fcchige [&hellip;]","og_url":"https:\/\/www.siegfriedhagl.com\/ru\/\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0435-\u0438\u0441\u0442\u043e\u0440\u0438\u0438\/\u043d\u0430\u0441\u0442\u043e\u044f\u0449\u0438\u0439-\u0440\u043e\u0431\u0438\u043d\u0437\u043e\u043d\/","og_site_name":"SiegfriedHagl.com","article_published_time":"2021-12-27T11:05:40+00:00","article_modified_time":"2022-05-14T09:45:34+00:00","author":"siegfriedhagl","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c":"siegfriedhagl","\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"6 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/der-echte-robinson\/#article","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/der-echte-robinson\/"},"author":{"name":"siegfriedhagl","@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"headline":"Der echte Robinson","datePublished":"2021-12-27T11:05:40+00:00","dateModified":"2022-05-14T09:45:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/der-echte-robinson\/"},"wordCount":979,"publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"articleSection":["Merkw\u00fcrdige Geschichten"],"inLanguage":"ru-RU"},{"@type":"WebPage","@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/der-echte-robinson\/","url":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/der-echte-robinson\/","name":"\u041d\u0430\u0441\u0442\u043e\u044f\u0449\u0438\u0439 \u0420\u043e\u0431\u0438\u043d\u0437\u043e\u043d - SiegfriedHagl.com","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/#website"},"datePublished":"2021-12-27T11:05:40+00:00","dateModified":"2022-05-14T09:45:34+00:00","breadcrumb":{"@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/der-echte-robinson\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/der-echte-robinson\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/der-echte-robinson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.siegfriedhagl.com\/"},{"@type":"ListItem","position":2,"name":"Der echte Robinson"}]},{"@type":"WebSite","@id":"https:\/\/www.siegfriedhagl.com\/#website","url":"https:\/\/www.siegfriedhagl.com\/","name":"SiegfriedHagl.com","description":"\u0421\u0442\u0430\u0442\u044c\u044f \u0438 \u0431\u043b\u043e\u0433 \u0417\u0438\u0433\u0444\u0440\u0438\u0434\u0430 \u0425\u0430\u0433\u043b\u044f","publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siegfriedhagl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":["Person","Organization"],"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f","name":"\u0437\u0438\u0433\u0444\u0440\u0438\u0434\u0445\u0430\u0433\u043b\u044c","image":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","caption":"siegfriedhagl"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.hagl.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/8440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/comments?post=8440"}],"version-history":[{"count":4,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/8440\/revisions"}],"predecessor-version":[{"id":9135,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/8440\/revisions\/9135"}],"wp:attachment":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/media?parent=8440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/categories?post=8440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/tags?post=8440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}