{"id":2402,"date":"2015-07-29T10:56:14","date_gmt":"2015-07-29T09:56:14","guid":{"rendered":"https:\/\/www.siegfriedhagl.com\/?page_id=2402"},"modified":"2025-09-23T12:37:35","modified_gmt":"2025-09-23T11:37:35","slug":"500-jahre-reformation","status":"publish","type":"post","link":"https:\/\/www.siegfriedhagl.com\/ru\/%d0%bf%d0%b0%d0%bc%d1%8f%d1%82%d0%bd%d1%8b%d0%b5-%d0%b4%d0%bd%d0%b8\/500-%d0%bb%d0%b5%d1%82-%d1%80%d0%b5%d1%84%d0%be%d1%80%d0%bc%d0%b0%d1%86%d0%b8%d0%b8\/","title":{"rendered":"500 \u043b\u0435\u0442 \u0420\u0435\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438"},"content":{"rendered":"<h5>Zum 31. Oktober 2017<\/h5>\n<p>Zum f\u00fcnfhundertsten Jahrestag der Reformation kommt eine Flut von Veranstaltungen und Publikationen \u00fcber Martin Luther, seinen Streit mit dem Papst, die evangelischen<a href=\"#_edn1\" name=\"_ednref1\">[1]<\/a> Theologien und die Geschichte der protestantischen<a href=\"#_edn2\" name=\"_ednref2\">[2]<\/a> Kirchen.<\/p>\n<p>Wir wollen an dieser Stelle nicht die Pers\u00f6nlichkeit Luthers w\u00fcrdigen oder seine Weltanschauung betrachten; das haben viele andere bereits ausf\u00fchrlich getan. Wir versuchen vielmehr, den durch Luther begr\u00fcndeten Protestantismus in einem erweiterten, geschichtlichen Zusammenhang zu sehen.<\/p>\n<h5>Das Abendland im Umbruch<\/h5>\n<p>Im 15. und 16. Jahrhundert gab es eine Reihe einschneidender Ereignisse, die die Situation Europas nachhaltig ver\u00e4nderten.<\/p>\n<p>Die herausragendsten dieser Geschehen seinen kurz genannt:<\/p>\n<p><em><strong>Die Renaissance (15. &#8211; 17. Jahrhundert)<br \/>\n<\/strong><\/em>Das Lebensgef\u00fchl der Abendl\u00e4nder wurde am ausgehenden Mittelalter zwar noch vom Christentum dominiert, doch erweitert durch die R\u00fcckbesinnung auf die Antike (Renaissance = Wiedergeburt) mit ihrer vorchristlichen Philosophie und ihren technischen und organisatorischen Leistungen. Diese beiden gro\u00dfen Gedankenstr\u00f6me \u2013 christlicher Glaube und antikes Wissen \u2013 prallten aufeinander.<\/p>\n<p>Die \u00e4u\u00dferen Erscheinungsformen des Christentums hatten sich weit von den Lehren seines Gr\u00fcnders entfernt und mussten jedem denkenden Zeitgenossen h\u00f6chst unbefriedigend anmuten: Die Kirche war verweltlicht, die P\u00e4pste waren Machtpolitiker, Priester, M\u00f6nche und Nonnen waren h\u00e4ufig verlottert, die Abgaben an den Klerus waren dr\u00fcckend.<\/p>\n<p>Am sch\u00e4rfsten zeigten sich diese Missst\u00e4nde im Deutschen Reich, das in \u00fcber Tausend St\u00e4dte, Grafschaften, Bist\u00fcmer, Abteien, Herzogt\u00fcmer und F\u00fcrstenschaften zerfallen war. In diesem Flickenteppich eines Staatsgebildes rumorten Fehden zwischen St\u00e4dten und Grafen und die Gewalttaten der Ritter. Der Kaiser des \u201eHeiligen R\u00f6mischen Reiches Deutscher Nation\u201c herrschte fast nur noch formal und musste diesem elenden Treiben weitgehend machtlos zusehen.<\/p>\n<p><strong><em>Der Buchdruck (um 1450)<br \/>\n<\/em><\/strong>Johannes Gutenberg (1397-1468) erfand den Buchdruck mit beweglichen Lettern aus Metall<a href=\"#_edn3\" name=\"_ednref3\">[3]<\/a>. Nach jahrelangen Bem\u00fchungen konnte er die ber\u00fchmte, 42-zeilige lateinische Bibel drucken (Auflage ca. 180 Exemplare). Diese epochale Erfindung war nicht geheim zu halten und fand bald weite Verbreitung. Nun konnten Pamphlete, Flugschriften, B\u00fccher in gr\u00f6\u00dferer Auflage und schneller als je zuvor verbreitet werden. Ohne diese Erfindung, die den Beginn eines \u201efr\u00fchen Informationszeitalters\u201c markiert, ist die Reformation kaum vorstellbar.<\/p>\n<p><em><strong>Die T\u00fcrken erobern Konstantinopel (29. 5. 1453)<br \/>\n<\/strong><\/em>\u00dcber zwei Jahrtausende lang spielten sich die wesentlichen Beitr\u00e4ge zur europ\u00e4ischen Kulturgeschichte, die wichtigsten Entwicklungen des Abendlandes, vorwiegend rund um das Mittelmeer ab. Durch die Eroberung Konstantinopels wurde das Abendland vom nahen Osten abgeschnitten. Griechenland und gro\u00dfe Teile des Balkans wurden osmanisches Herrschaftsgebiet. Der nahe Osten und Nordafrika, einst christliche Kernl\u00e4nder,\u00a0 waren schon seit dem 7. Jahrhundert in islamischer Hand.<\/p>\n<p>Das \u201eHeilige R\u00f6mische Reich Deutscher Nation\u201c stand in einem harten Abwehrkampf gegen das Osmanische Reich, dessen Truppen 1529 zum ersten Mal vor Wien standen. Dem Deutschen Reich fehlte dadurch die milit\u00e4rische Kraft, entschieden gegen den Protestantismus vorzugehen, so dass behauptet werden kann, ohne die T\u00fcrken h\u00e4tte es keine Reformation gegeben.<\/p>\n<p>Der lukrative Orienthandel brach ein, durch den z. B. Venedig reich und m\u00e4chtig geworden war. T\u00fcrkische und arabische Piraten bedrohen den Handel und die Mittelmeerk\u00fcsten der Europ\u00e4er (vgl. \u201eSklavenraub im Mittelmeer\u201c, in &#8222;Kurz, knapp, kurios&#8220; Seite 285). Orientalische H\u00e4ndler erh\u00f6hten laufend die Preise. Der Mittelmeerraum verlor an Bedeutung, wenn auch so langsam, dass die Bl\u00fcte der italienischen Kunst bis ins 16. Jahrhundert anhalten konnte.<\/p>\n<p>Die Blicke mussten sich nun nach Westen richten, hinaus auf den lange vernachl\u00e4ssigten Atlantik. Bei der Erkundung der Seewege \u00fcber den Atlantischen Ozean gingen Portugal und Spanien den anderen seefahrenden Nationen voran.<\/p>\n<p><em><strong>Die Entdeckung Amerikas (12. 10. 1492)<br \/>\n<\/strong><\/em>Auf der Suche nach einem westlichen Seeweg nach Indien entdeckte Kolumbus die \u201eWestindischen Inseln\u201c (Karibik), die er f\u00fcr Ausl\u00e4ufer Asiens hielt. (Vgl. \u201eKolumbus und die flache Erde\u201d, in &#8222;Kurz, knapp, kurios&#8220; Seite 63).<br \/>\nDas Kolonialzeitalter bricht an.<\/p>\n<p><em><strong>Vasco da Gama landet in Calicut (20. 5. 1498)<br \/>\n<\/strong><\/em>Nach vielen Entdeckungsfahrten der Portugiesen, entlang der westafrikanischen K\u00fcste bis zum Kap der guten Hoffnung, ist endlich die ersehnte Seeroute nach Indien gefunden. Der Orienthandel kann nun \u00fcber zwei Ozeane (Atlantik und Indik) hinweg direkte Verbindungen zu den Erzeugerl\u00e4ndern im fernen \u201eOstindien\u201c aufnehmen und lange, teure Landwege sowie Zwischenh\u00e4ndler umgehen.<\/p>\n<p><strong><em>Luthers 95 Thesen (31. Oktober 1517<\/em>)<br \/>\n<\/strong>In dieser durch Entdeckungen, neue Ideen, Kritik an der Kirche und soziale Schieflagen aufgeheizten Atmosph\u00e4re ver\u00f6ffentlichte Martin Luther (1483-1546) seine ber\u00fchmten 95 Thesen. Ob er sie, wie man oft h\u00f6rt, an der Schlosskirche zu Wittenberg angeschlagen hat, ist umstritten.<br \/>\nDiese Thesen und weitere grundlegende Schriften Luthers brachten eine Bewegung von ungeheurem Ausma\u00df in Gang: den Durchbruch der Reformation, gekennzeichnet durch drei weitere bedeutsame Schriften Luthers:<br \/>\n* <em>August 1520<\/em>: Eine <em>politische <\/em>Programmschrift<em>:<\/em> \u201eAn den christlichen Adel deutscher Nation\u201c.<br \/>\n* <em>Oktober 1520<\/em>: Eine <em>dogmatische <\/em>Programmschrift<em>:<\/em> \u201eVon der babylonischen Gefangenschaft der Kirche\u201c.<br \/>\n* <em>November 1520<\/em>: Eine <em>ethische <\/em>Programmschrift<em>: <\/em>\u201eVon der Freiheit des Christenmenschen\u201c.<br \/>\nDer Buchdruck und die zunehmende Alphabetisierung der Menschen machten eine schnelle Verbreitung der neuen Ideen m\u00f6glich.<br \/>\nDie Publikationen des aufm\u00fcpfigen Augustiner-M\u00f6nches stellten die Autorit\u00e4t des Papstes in Frage. Der Papst war emp\u00f6rt und antwortete mit der Drohung mit dem Kirchenbann. Luther verbrannte \u00f6ffentlich die entsprechende p\u00e4pstliche Bulle; eine direkte Provokation des Heiligen Stuhles!<br \/>\nAus der Sicht Luthers war das ein Streit f\u00fcr einen reineren Glauben, aus p\u00e4pstlicher Sicht ein Machtkampf.<\/p>\n<p><em><strong>Maghellan umsegelt die Welt (20. 9. 1519 \u2013 6. 9. 1522)\u00a0<\/strong><br \/>\n<\/em>Die erste Weltumsegelung durch Ferdinand Magellan (1480-1521), die er nicht \u00fcberlebte, lieferte ein neues, gr\u00f6\u00dferes Bild der Erde. Amerika war nun eindeutig als vierter Kontinent erkannt<a href=\"#_edn4\" name=\"_ednref4\">[4]<\/a>. Zum ersten Mal wurde der riesige Pazifik von einem europ\u00e4ischen Schiff durchquert. Damit war auch die tats\u00e4chliche Gr\u00f6\u00dfe der Erde durch praktische Erfahrungen belegt. (Vgl. &#8222;<a href=\"https:\/\/www.siegfriedhagl.com\/gedenktage\/die-erste-umsegelung-der-erde-vor-500-jahren\/\">Die erste Umsegelung der Erde<\/a>&#8222;)<\/p>\n<p><em><strong>Die kopernikanische Wende (1543)<\/strong><br \/>\n<\/em>Nikolaus Kopernikus (1473-1543) ver\u00f6ffentliche in seinem Todesjahr seine \u201eSechs B\u00fccher \u00fcber die Uml\u00e4ufe der Himmelsk\u00f6rper\u201c. Er griff auf eine sehr alte Idee zur\u00fcck, die schon Aristarch von Samos (ca. 310-230 v. Chr.) vorgeschlagen hatte: Nicht die Erde, sondern die Sonne steht im Mittelpunkt der Welt. Die Planeten, einschlie\u00dflich der Erde, kreisen um die Sonne.<br \/>\nAus moderner Sicht ist das lediglich eine \u201eKoordinaten-Transformation\u201c: Man w\u00e4hlt einen Fixpunkt (in diesem Fall die Sonne anstatt der Erde) zweckm\u00e4\u00dfigerweise so, dass man die einfachsten Gleichungen bekommt!<br \/>\nDoch zu Luthers Zeiten sah man das anders. Luther selbst nannte Kopernikus einen Narren, weil in der Bibel klar und deutlich steht:<br \/>\n<em> \u201eDamals, als der Herr die Amoriter den Israeliten preisgab, redete Josua mit dem Herrn; dann sagte er in Gegenwart der Israeliten: Sonne, bleib stehen \u00fcber Gibeon und du Mond, \u00fcber dem Tal von Ajalon! Und die Sonne blieb stehen, und der Mond stand still, bis das Volk an seinen Feinden Rache genommen hatte.\u201c<\/em> (Jos. 10, 12).<\/p>\n<p>Das heliozentrische Weltsystem des Kopernikus revidierte nicht nur die astronomische Stellung der Weltkugel, sondern degradierte auch die religi\u00f6se und philosophische Bedeutung des Menschen, der nun nicht mehr als \u201eKrone der Sch\u00f6pfung\u201c auf einem besonderen Ort im \u201eMittelpunkt der Welt\u201c lebte. Vor allem widersprach es der Bibel, der wichtigsten Wahrheitsquelle und Grundlage der christlichen Religionen. Da konnte es nur eine Frage der Zeit sein, bis auch weitere Dogmen der Kirchen angezweifelt wurden.<\/p>\n<h5>Kirchenspaltungen<\/h5>\n<p>Das erste, das \u201eGro\u00dfe Schisma\u201c war im 11. Jahrhundert die Teilung der christlichen Kirchen in Ost- und Westrom. Auch Russland \u00fcbernahm den ostr\u00f6mischen (griechisch-orthodoxen) Glauben. Europa wurde religi\u00f6s gespalten; mit weitreichenden gesellschaftlichen und politischen Folgen bis in die Gegenwart. (Vgl. &#8222;Kurz, knapp, Kurios&#8220; Seite 290 \u201eHeiter, trinkfreudig und prachtvoll\u201c).<\/p>\n<p>Im 16. Jahrhundert wirkten die Thesen Luthers wie eine Initialz\u00fcndung. Die r\u00f6mische Kirche war zu selbstgerecht und sich ihrer Macht zu sicher geworden. Viele Gl\u00e4ubige waren von ihrer Kirche zutiefst entt\u00e4uscht und wendeten sich den zahlreichen neuen, kirchenkritischen Gedanken zu. Reformatorische Ideen erreichten alle Volksschichten und breiteten sich aus wie ein Fl\u00e4chenbrand, der nicht mehr zu l\u00f6schen war. Vor allem in Mittel- und Nordeuropa gr\u00fcndeten sich reformierte Kirchen.<\/p>\n<p>Diese zweite Glaubensspaltung Europas f\u00fchrte in manchen L\u00e4ndern zur Aufl\u00f6sung der nationalen und staatlichen Einheit. Eine einheitliche Religion f\u00fcr ganz West- und Mitteleuropa lie\u00df sich weder durch die Gegenreformation noch durch Religionskriege wieder herstellen.<\/p>\n<p>Protestanten lehnten den aus ihrer Sicht \u00fcbertriebenen Pomp der katholischen und der orthodoxen Kirchen ab; sie zogen einfachere Rituale in schlichteren Kirchen vor. Kl\u00f6ster wurden s\u00e4kularisiert.<br \/>\nDer Ablassverkauf, die Heiligenverehrung, Prozessionen, die Reliquienverehrung, Wallfahrten, der Wunderglaube, und viele kirchliche Feiertage wurden abgeschafft. Dementsprechend gab es mehr Arbeitstage: Das war der Start der sp\u00e4ter viel zitierten \u201eprotestantischen Arbeitsethik\u201c.<\/p>\n<h5>Bauernkriege und Religionskriege<\/h5>\n<p>Die katholische Kirche wollte den mit der Abspaltung der Protestanten verbundenen Machtverlust nicht hinnehmen. Sie fand Unterst\u00fctzung bei katholischen F\u00fcrsten, darunter dem Kaiser Karl V., die die religi\u00f6se Einheit des Reiches bewahren wollten \u2013 wenn n\u00f6tig auch mit Gewalt. So kam es unausweichlich zu kriegerischen Auseinandersetzungen.<\/p>\n<p><em><strong>Die Bauernkriege (1523-1526)<\/strong><br \/>\n<\/em>Der erste sozial-religi\u00f6se Aufbruch der Reformationszeit in Deutschland waren die Bauernkriege. \u00dcber die berechtigten Anliegen der kleinen Leute und die brutale Niederschlagung der Revolten haben wir bereits berichtet. (\u201e<a href=\"https:\/\/www.siegfriedhagl.com\/merkwuerdige-geschichten\/wenn-die-obrigkeit-sagt-zwei-und-funf-sind-gleich-acht-so-musst-dus-glauben\/\">Wenn die Obrigkeit sagt, zwei und f\u00fcnf sind gleich acht, so musst du\u2019s glauben<\/a>\u201c, unter &#8222;Merkw\u00fcrdige Geschichten&#8220;).<\/p>\n<blockquote><p><strong>Religionskriege:<br \/>\n<\/strong>Religions- und Glaubenskriege im engeren Sinne sind erst eine Erscheinung der Neuzeit. Sie bezeichneten stets innerchristliche Gro\u00dfkonflikte im fr\u00fchneuzeitlichen Europa. Die Auseinandersetzungen mit den \u201eUngl\u00e4ubigen\u201c des Osmanischen Reiches bezeichnete niemand als Religionskrieg. (5, S. 4).<\/p><\/blockquote>\n<p><em><strong>Der Schmalkaldische Krieg (1546-1547)<\/strong><br \/>\n<\/em>Kaiser Karl V. wollte die religi\u00f6se Einheit des Reiches erzwingen. So kam es zum Krieg katholischer Teile des Reiches gegen den protestantischen <em>Schmalkaldischen Bund. <\/em>Dieser Krieg, ohne gr\u00f6\u00dfere Schlachten, ging f\u00fcr die protestantische Bewegung ungl\u00fccklich aus. Doch der Sieg der kaiserlichen Truppen reichte nicht aus, den Protestantismus zu eliminieren und die Einheit der Kirche wieder herzustellen. Die Religionsspaltungen und die Unzufriedenheit im Deutschen Reich gingen weiter, Macht und Ansehen des Kaisers litten.<\/p>\n<p><em><strong>Der Augsburger Religionsfriede (1555)<\/strong><br \/>\n<\/em>Die religi\u00f6s begr\u00fcndeten Unruhen im Deutschen Reich lie\u00dfen sich erst durch den Augsburger Religionsfrieden eind\u00e4mmen; ein erster, zaghafter Schritt zu religi\u00f6ser Toleranz. (<a href=\"https:\/\/www.siegfriedhagl.com\/gedenktage\/die-neuzeit-beginnt-immer-noch\/\">\u201eDie Neuzeit beginnt immer noch\u201c<\/a>, unter &#8222;Gedenktage&#8220;). Er war ein Kompromiss, der immerhin mehr als sechzig Jahre lang hielt, bis es zum verheerendsten aller Religionskriege kam.<\/p>\n<p><strong><em>Die Gegenreformation (etwa zwischen 1555 und 1750)<br \/>\n<\/em><\/strong>Die Erfolge der protestantischen Bewegung erzwangen auch innerhalb der katholischen Kirche Erneuerungsbewegungen, die nicht nur die Kirche ver\u00e4ndern, sondern vor allem auch den Protestantismus zur\u00fcckdr\u00e4ngen wollten. Die Hauptkampffelder der Gegenreformation waren Deutschland und die Niederlande.<br \/>\nZum Inbegriff der Gegenreformation wurde der von Ignatius von Loyola (1491-1556) im Jahre 1534 gegr\u00fcndete Jesuitenorden. Dieser Orden betrieb eine kluge Politik, war den Wissenschaften gegen\u00fcber aufgeschlossen und entwickelte in der Schulausbildung und der Mission neue Wege. Seine Einflussnahme auf die Politik brachte ihn in Konflikte mit katholischen Herrschern. So entstand eine Gegenbewegung, die im 18. Jahrhundert in vielen Staaten zum Verbot des Jesuitenordens f\u00fchrte.<\/p>\n<p><strong><em>Der Drei\u00dfigj\u00e4hrige Krieg (1618-1648)<br \/>\n<\/em><\/strong>Dieser grauenhafte Krieg begann mit dem Versuch der Habsburger in Wien, den Protestantismus in ihren Erblanden auszurotten. Dazu versicherten sie sich der Unterst\u00fctzung der spanischen Vettern.<\/p>\n<p>Die kriegerischen Konflikte begannen in B\u00f6hmen mit der Schlacht am Wei\u00dfen Berg (8. November 1620). Die Protestanten wurden geschlagen und weit nach Norden zur\u00fcckgedr\u00e4ngt. Die protestantische Sache schien f\u00fcr Deutschland verloren.<br \/>\nDann landete im Jahre 1630 der protestantische K\u00f6nig von Schweden, Gustav II. Adolf (1594-1632), an der pommerschen K\u00fcste. Seine Siege gegen die kaiserlichen Truppen retteten den Protestantismus in Deutschland. Auch nach Gustav Adolfs Tod in der Schlacht von L\u00fctzen bei Leipzig spielten die gef\u00fcrchteten Schweden noch eine wichtige Rolle als europ\u00e4ische Macht.<br \/>\nSchlie\u00dflich waren neben \u00f6sterreichischen und spanischen Habsburgern, deutschen Katholiken, deutschen Protestanten und Schweden, auch Franzosen und Engl\u00e4nder in die blutigen Auseinandersetzungen auf deutschem Boden verwickelt. Aus dem Religionskrieg entwickelte sich ein Kampf um die Vormacht in Europa zwischen Frankreich, Spanien und Schweden, der zum Niedergang Spaniens f\u00fchrte. (Vgl. &#8222;Kurz, knapp, Kurios&#8220; Seite 346 \u201eWie religi\u00f6ser Fanatismus L\u00e4nder und Reiche ruinierte\u201c).<\/p>\n<p>Die leitende Pers\u00f6nlichkeit der franz\u00f6sischen Regierung, der katholische Kardinal Richelieu (1585-1642), f\u00fchrte Krieg gegen die Habsburger, die den katholischen Glauben in abgefallenen L\u00e4ndern wieder herstellen wollten! Das ist Machtdenken der Neuzeit, unbelastet von religi\u00f6sen Bindungen!<\/p>\n<p>Zuletzt waren alle Parteien ersch\u00f6pft, Deutschland zum gro\u00dfen Teil verw\u00fcstet. Der Krieg endete im Westf\u00e4lischen Frieden, der dem in drei\u00dfig Kriegsjahren aufgestauten Hass eine Absage erteilte und gegenseitiges Verzeihen verlangte.<\/p>\n<p>Die Zeche bezahlte Deutschland. Die angeblichen Sieger \u2013 Frankreich und Schweden \u2013 annektierten Teile des Reiches; das katholische Bayern, das auch schwer gelitten hatte, bekam die Kurw\u00fcrde<a href=\"#_edn5\" name=\"_ednref5\">[5]<\/a>; die Schweiz und Holland wurden selbst\u00e4ndig.<\/p>\n<h5><strong>Das geistige Zentrum verlagert sich nach Norden <\/strong><\/h5>\n<p>Gegen Endes des Mittelalters boten die italienischen Stadt-Staaten mit ihrer florierenden Wirtschaft die gl\u00e4nzendsten Beispiele der abendl\u00e4ndischen Kunst und Kultur. Allerdings waren sie untereinander zerstritten, lebten in einem labilen politischen Gleichgewicht, das schlie\u00dflich kippte und Italien zum Spielball fremder M\u00e4chte machte. (Vgl. &#8222;Kurz, knapp, kurios&#8220; Seite 323 \u201eEin Renaissance-Prophet im Wankelmut der Massen\u201c).<\/p>\n<p>Vor allem die L\u00e4nder im Norden Europas sagten sich von der katholischen Kirche los: Der gr\u00f6\u00dfte Teil Deutschlands, England, Teile Frankreichs, die Niederlande, die Schweiz, Skandinavien. Staatskirchen wurden gegr\u00fcndet und in vielen L\u00e4ndern traten Reformatoren oder auch Mystiker auf, die sich von der katholischen Kirche abwandten. Die bekanntesten \u2013 nach Luther \u2013 sind Ulrich Zwingli (1484-1531) in der deutschsprachigen Schweiz, Jean (oder Johannes) Calvin (1509-1564) in der franz\u00f6sischsprachigen Schweiz und in Frankreich, John Knox (1505-1572) in England. Leider waren die Reformatoren und ihre Gemeinden auch untereinander zerstritten. So konnten sich z. B. Luther und Zwingli nicht \u00fcber die spirituelle Bedeutung und die Form des Abendmahls einigen. Dieses hochkomplizierte theologische Thema sollte die verschiedenen protestantischen Gemeinden noch lange besch\u00e4ftigen<a href=\"#_edn6\" name=\"_ednref6\">[6]<\/a>.<\/p>\n<p>Europa wurde gespalten, in einen vorwiegend protestantischen Norden und den katholischen S\u00fcden. Dieser Riss ging mitten durch Deutschland.<\/p>\n<p>Mit der Reformation verschoben sich die Schwerpunkte der wissenschaftlichen Forschung und der neuzeitlichen Philosophie. Denn bei aller dogmatischen Gebundenheit der Lutheraner an die Bibel, als einzige anerkannte religi\u00f6se \u00dcberlieferung, wurde das geistige Klima in den protestantischen L\u00e4ndern offener, die freie Meinungs\u00e4u\u00dferung eher m\u00f6glich als in streng katholischen L\u00e4ndern wie Italien, \u00d6sterreich, Portugal, Spanien. Hier f\u00fcrchteten Priester und F\u00fcrsten um ihre Macht und unterdr\u00fcckten mit Gegenreformation, Inquisition und Ketzerprozessen alle verd\u00e4chtigen, oppositionellen Gedanken.<\/p>\n<p>Aus dem Kampf um die Vormacht des Katholizismus wurde ein Kampf gegen die Moderne. In Rom wurde Giordano Bruno (1548-1600), der vision\u00e4re Propagandist der Kopernikanischen Wende, als Ketzer verbrannt, und Galileo Galilei (1564-1642) musste dem kopernikanischen Weltbild abschw\u00f6ren. Abschreckende Exempel f\u00fcr andere, fortschrittliche Denker?<br \/>\nSo war es kein Zufall, dass der Aufbruch der Naturwissenschaften nicht vom Mittelmeerraum ausging, der \u00fcber viele Jahrhunderte f\u00fchrenden Region. Einen ersten, wichtigen Schritt zur \u201eNeuen Wissenschaft\u201c (der Naturwissenschaft) verdanken wir noch dem Italiener Galileo Galilei (1564-1642), doch blieb dieser f\u00fcr lange Zeit der letzte, ganz gro\u00dfe Wissenschaftler des S\u00fcdens. (Vgl. &#8222;Kurz, knapp, kurios Seite 218 \u201eDer Vater der Neuen Wissenschaft\u201c).<br \/>\nDie protestantischen Niederlande wurden, nicht zuletzt durch Simon Stevin (1548-1620), mitten im Freiheitskampf gegen Spanien zu einem Vorl\u00e4ufer der industriellen Revolution. (Vgl. &#8222;Kurz, knapp, kurios&#8220;\u00a0 Seite 178 \u201eDie goldene Zeit der Niederlande&#8220;). Dann gr\u00fcndeten englische Wissenschaftler 1660 die Royal Society, die sich den Naturwissenschaften und der Mathematik widmete. Philosophen wie Francis Bacon (1561-1626) und Naturwissenschaftler wie Isaak Newton (1642-1726) konnten ihre Thesen ohne Angst vor Verfolgung publizieren.<br \/>\nWichtige Grundlagen f\u00fcr die im 18. Jahrhundert beginnende industrielle Revolution wurden gelegt.<br \/>\nKatholische L\u00e4nder fielen gegen\u00fcber den dem Fortschritt aufgeschlosseneren, vorwiegend protestantischen L\u00e4ndern zur\u00fcck. Einige Regionen haben diesen R\u00fcckstand bis heute nicht aufgeholt. Die Problemf\u00e4lle der EURO-Krise (besonders Griechenland, Italien, Portugal, Spanien, aber mit Einschr\u00e4nkungen auch Frankreich), die genau genommen eine Schuldenkrise von Staaten mit schlechten Regierungen ist, sind katholische bzw. griechisch-orthodoxe L\u00e4nder!<\/p>\n<h5>Die protestantische Arbeitsethik<\/h5>\n<p>Die in mancher Hinsicht offeneren, freier denkenden Protestanten waren in anderer Beziehung besonders streng. Manche Gruppen forderten ein asketisches, arbeitsames, christliches Leben. Viele Vergn\u00fcgungen \u2013 z. B. Fastnachtsbr\u00e4uche, Kirchweihfeste, Lustspiele und vieles mehr \u2013 waren bei strengen Protestanten verp\u00f6nt.<\/p>\n<p><em><strong>Calvinisten<\/strong><br \/>\n<\/em>Ein rigoroses religi\u00f6ses System errichtete Jean Calvin (1509-1564) in Genf. Hier wurden Ehrlichkeit, Flei\u00df, Sparsamkeit, Disziplin, Verzicht auf Vergn\u00fcgungen und Luxus in extremer Weise gefordert. Gegen Andersdenkende waren Calvinisten unduldsam.<br \/>\nDie Calvinisten predigten eine neue Einstellung zur Arbeit und zum Beruf:<br \/>\n<em>\u201eNicht Mu\u00dfe und Genuss, sondern nur Handeln dient nach dem unzweideutig geoffenbarten Willen Gottes zur Mehrung seines Ruhmes. Zeitvergeudung ist also die erste und prinzipiell schwerste aller S\u00fcnden<\/em><a href=\"#_edn7\" name=\"_ednref7\">[7]<\/a>. <em>Die Zeitspanne des Lebens ist unendlich kurz und kostbar&#8230;Zeitverlust durch Geselligkeit, faules Gerede, Luxus, selbst durch mehr als der Gesundheit n\u00f6tign Schlaf&#8230; ist sittlich absolut verwerflich.\u201c<\/em><br \/>\nDie Arbeit wird zum Selbstzweck des Lebens. Der paulinische Satz <em>\u201eWer nicht arbeitet, soll nicht essen\u201c <\/em>(2. Thess. 3,10), gilt bedingungslos und f\u00fcr jedermann. Die Arbeitsunlust ist Symptom fehlenden Gnadenstandes. (8, S. 183 f.).<br \/>\nWer in der Arbeit Selbstzweck und Lebensaufgabe sieht, wird in der Regel sein Eigentum mehren. Daher fordert der Puritanismus die Verantwortung f\u00fcr seinen Besitz, den man zu Gottes Ruhm ungeschm\u00e4lert erhalten und durch rastlose Arbeit mehren soll. (8, S. 193).<\/p>\n<p>Folgt man Max Weber (8), dann haben der Calvinismus und seine Ethik des asketischen Protestantismus die wirtschaftliche Entwicklung ma\u00dfgeblich beeinflusst und den Durchbruch des Kapitalismus gef\u00f6rdert: In England, Holland, der Schweiz und den USA; in Deutschland besonders in den seit 1613 von den reformierten Hohenzollern regierten Staaten (10). Den Kapitalismus hat es seit der Antike in vielerlei Formen gegeben (vgl. &#8222;<a href=\"https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/karthago-der-erste-kapitalistisch-staat\/\">Karthago, der erste kapitalistische Staat?&#8220;<\/a>), doch blieb es der Neuzeit \u00fcberlassen, diesen zu einem globalen Prinzip zu erheben. (Vgl. <a href=\"https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/wirtschaftskrise-und-weltverschworung\/\">&#8222;Wirtschaftskrise und Weltverschw\u00f6rung&#8220;,<\/a> unter &#8222;Wirtschaft und Soziales&#8220;).<\/p>\n<p>Inzwischen haben Chinesen die einst &#8222;protestantisch&#8220; genannte Arbeitsethik verinnerlicht und f\u00fchlen sich als das flei\u00dfigste Volk. Mit einer\u00a0 Wochen-Arbeitszeit von 6 Tagen a. 12 Stunden.<br \/>\nSo musste sich im Oktober 2011 eine europ\u00e4ische Delegation von Jin Liqun, dem Aufsichtsratsvorsitzenden der staatlichen China Investment Corporation ermahnen lassen:<em><br \/>\n&#8222;Die Wurzeln des \u00dcbels sind der \u00fcberlastete Wohlfahrtsstaat, der nach dem Zweiten Weltkrieg in Europa errichtet wurde, und die zur Faulheit und Tr\u00e4gheit verleitenden Arbeitsmarktregelungen. Die Menschen sollten ein wenig h\u00e4rter und l\u00e4nger arbeiten, und sie sollten innovativer sein. Wir Chinesen arbeiten wie verr\u00fcckt.&#8220;<\/em> (2).<\/p>\n<p>Neben Luther war Calvin der bedeutendste Reformator, dessen Gedanken weit \u00fcber seinen pers\u00f6nlichen Wirkungskreis hinaus ausstrahlten und viele der zahlreichen protestantischen Gemeinden mehr oder weniger beeinflussten.<\/p>\n<p><em><strong>Puritaner<\/strong><br \/>\n<\/em>In England und Teilen Schottlands errang der aus dem Calvinismus hervorgegangene Puritanismus zeitweise gr\u00f6\u00dfte Bedeutung. Die von Oliver Cromwell (1599-1658) angef\u00fchrte Elite-Truppe der Puritaner (die \u201eironsides\u201c) siegte im B\u00fcrgerkrieg zwischen Krone und Parlament. Die Monarchie wurde abgeschafft, K\u00f6nig Karl I. 1649 hingerichtet.<\/p>\n<p>Die puritanische Einstellung zur Arbeit und zum Eigentum wurde von England aus in die Kolonien getragen.<\/p>\n<p><em><strong>Nordamerika<\/strong><br \/>\n<\/em>In den englischen Kolonien Nordamerikas hatten Puritaner gro\u00dfen Einfluss auf die Entwicklung des Landes. Noch heute wollen manche Kommentatoren einen, vom \u201eOstk\u00fcsten-Establishment\u201c (den WASPs = White Anglo-Saxon Protestants) ausgehenden, puritanischen Einfluss auf die Politik der USA sehen. Beispielsweise in einem Sendungsbewusstsein, das die in \u201eGottes eigenem Land\u201c geschaffenen wirtschaftlichen und politischen Verh\u00e4ltnisse auf den Rest der Welt \u00fcbertragen will.<\/p>\n<p><em><strong>Deutschland\u00a0\u00a0<\/strong><br \/>\n<\/em>Deutschland war nach dem Drei\u00dfigj\u00e4hrigen Krieg gespalten in einen vorwiegend protestantischen Norden und den katholischen S\u00fcden, den Norddeutsche lange als zur\u00fcckgebliebene Agrarregion sahen.<\/p>\n<p>Die industrielle Revolution erreichte den n\u00f6rdlicheren, vorwiegend protestantischen Teil Deutschlands zuerst. Das mehr nach Italien hin orientierte, katholische Bayern wurde eigentlich erst nach den Verwerfungen durch zwei Weltkriege ein Industrieland.<\/p>\n<p><em><strong>Preu\u00dfen<\/strong><br \/>\n<\/em>War Preu\u00dfen das typisch protestantische Land?<br \/>\nEigentlich nicht. Denn in Preu\u00dfen war man nicht fanatisch religi\u00f6s \u2013 anders als viele protestantische Gemeinden. Hugenotten<a href=\"#_edn8\" name=\"_ednref8\">[8]<\/a> aus Frankreich, Protestanten aus dem Salzburger Land, Niederl\u00e4nder, \u00d6sterreicher, Russen sogar wurden aufgenommen. Polnische und schlesische Katholiken konnten ihrer Religion treu bleiben, und der vom Papst abgeschaffte Jesuitenorden wurde in Preu\u00dfen nicht verboten.<br \/>\nDie Migranten brachten meist wenig Hab und Gut mit, aber oft handwerkliche und wissenschaftliche Kenntnisse, die dringend ben\u00f6tigt wurden. Ganz abgesehen davon, dass die preu\u00dfischen Lande nur d\u00fcnn besiedelt waren und Zuwanderer aufnehmen konnten.<br \/>\nZum heute verp\u00f6nten, typisch Preu\u00dfischen geh\u00f6rten \u00dcberbewertung des Milit\u00e4rischen, Disziplin, hohes Ehrgef\u00fchl, gut funktionierende Verwaltung, Einfachheit, Gewerbeflei\u00df, Rechtssicherheit, religi\u00f6se Toleranz und ein autorit\u00e4rer, aber keineswegs kriegsl\u00fcsterner Staat. Zu Preu\u00dfens Glanzzeiten unter dem aufgekl\u00e4rten Friedrich II. (K\u00f6nig 1740-1786) spielten Religionen keine tragende Rolle.<br \/>\nAls 1871 der K\u00f6nig von Preu\u00dfen Deutscher Kaiser wurde, und Preu\u00dfen im Deutschen Reich auf- (oder unter-) ging, verschwanden nach und nach die typisch preu\u00dfischen Tugenden. An ihre Stelle trat die Gro\u00dfmannssucht des Kaiserreiches.<\/p>\n<h5>Die Folgen der Reformation<\/h5>\n<p>Luther wollte eine bescheidene Reform der katholischen Kirche. Ausgel\u00f6st hat er einen Fl\u00e4chenbrand, der \u00fcber Jahrhunderte hinweg Europa und die Welt nachhaltig ver\u00e4ndert hat.<\/p>\n<p><em><strong>Zersplitterung des Christentums<\/strong><br \/>\n<\/em>Die einheitliche, das Abendland spirituell beherrschende katholische Kirche war zerbrochen. Zwei traditionelle christliche Kirchen (katholisch und orthodox), zahlreiche reformierte (protestantische) Kirchen und Gemeinden, rangen eifers\u00fcchtig um ihren Einfluss auf die Seelen der Menschen und das Handeln der Regierenden. Was war von den verschiedenen \u201echristlichen\u201c Lehren zu halten, die sich nicht selten widersprachen?<br \/>\nKirchliche Hierarchien, aber auch weltliche Herrscher \u201evon Gottes Gnaden\u201c gerieten ins Zwielicht.<\/p>\n<p><em><strong>Die religi\u00f6se Basis bricht weg<\/strong><br \/>\nM<\/em>artin Luther hatte die Autorit\u00e4t des Papstes in Frage gestellt und einen verinnerlichten, streng auf der \u201eHeiligen Schrift\u201c aufgebauten Glauben gefordert. Nachbiblische Offenbarungen, Schriften der Kirchenv\u00e4ter, Konzilsbeschl\u00fcsse, p\u00e4pstliche Enzykliken usw. lie\u00df Luther als Glaubensgrundlagen nicht gelten.<br \/>\nDurch die \u201eKopernikanische Wende\u201c litt die Glaubw\u00fcrdigkeit der Bibel, der \u00fcber viele Jahrhunderte unangefochtenen Basis des Christentums. Dann wagten Linguisten und Historiker kritische Untersuchungen der christlichen \u00dcberlieferungen.<br \/>\nWem durfte man noch glauben, welche Ethik war g\u00fcltig, wo konnte man den Willen Gottes erkennen, wenn die Bibel nicht mehr die \u201eHeilige Schrift\u201c, das \u201eWort Gottes\u201c war, sondern nur noch eine alte, vielleicht ehrw\u00fcrdige, Sammlung von j\u00fcdischen Sagen und unsicheren christlichen \u00dcberlieferungen?<br \/>\nWodurch waren die Religionen als solche legitimiert?<\/p>\n<blockquote><p><strong><em>Luthers bleibende Wirkung:<\/em><br \/>\n<\/strong><em>&#8222;Auch heute noch l\u00e4sst sich \u00fcber Luthers religi\u00f6se Ansichten geteilter Meinung sein. Seine gr\u00f6\u00dfte Leistung bestand wohl darin, die Macht der Kirche gebrochen zu haben. Allerdings machte er den Glauben erst recht zum Mittelpunkt des Lebens. Luther ging davon aus, dass der Mensch nicht einmal einen freien Willen habe, weil alles von Gott bestimmt sei. Luther brachte den Menschen keine gr\u00f6\u00dfere Selbstbestimmung; er bek\u00e4mpfte alles, was gegen seine Ideen sprach. Schlie\u00dflich warf man ihm vor, der &#8218;Papst Wittenbergs&#8216; zu sein.<br \/>\n<\/em><em>Trotzdem hat Luther mit seinem neuen Glaubensweg eine neue Zeit eingeleitet, vielleicht eine bessere. Denn mit Luther begannen die Menschen, die Religion und ihre Aus\u00fcbung massiv zu hinterfragen. Das f\u00f6rderte die Rationalit\u00e4t, das Vernunftdenken. Die Menschen gewannen an pers\u00f6nlicher Freiheit. Diese Entwicklung f\u00fchrte schlie\u00dflich zu einer Trennung von Kirche und Staat und erlaubte alle m\u00f6glichen Formen von Religion, auch den Atheismus.<br \/>\n<\/em><em>So ist heute der tiefe Glaube an Gott, der das ganze Leben bestimmt, verschwunden, zumindest in weiten Teilen der westlichen Welt. Am Anfang dieser Entwicklung stand Martin Luther, der mit seiner Reformation die Menschen zum \u201erichtigen\u201c Glauben f\u00fchren wollte.&#8220;<br \/>\n<\/em>Andreas Venzke (7, S. 99).<\/p><\/blockquote>\n<h5>Rationalit\u00e4t statt Spiritualit\u00e4t<\/h5>\n<p>Das einfache Volk blieb noch Jahrhunderte lang gl\u00e4ubig. Es folgte seinem Pfarrer oder Pastor und war weder bestrebt noch in der Lage, die Grundpfeiler seiner Religion zu verstehen, geschweige denn in Frage zu stellen. Anders die f\u00fchrenden Kreise: K\u00fcnstler, Mathematiker, Naturwissenschaftler, Philosophen. In deren Augen hatten die Religionen abgewirtschaftet. Am besten sollte man sie abschaffen. Aus politischer Sicht konnten Religionen allenfalls noch als Regulativ f\u00fcr einfache Menschen dienen, die aus Gewohnheit und Tradition an ihrer Religion mit deren Festen und Riten hingen.<\/p>\n<p>Der Rationalismus, das logische Denken, verdr\u00e4ngte bei den Intellektuellen Religiosit\u00e4t und Spiritualit\u00e4t. Die Philosophie der Aufkl\u00e4rung, die naturwissenschaftliche Revolution, ein in gebildeten Kreisen verbreiteter Skeptizismus, oft gepaart mit Kirchenfeindlichkeit, bestimmten das geistige Klima der Neuzeit.<\/p>\n<h5>Gewissensfreiheit<\/h5>\n<p>Martin Luther hat eine Idee in die Welt gebracht, die in den H\u00e4nden von Demagogen zu einem Kampfinstrument wurde<em>: <\/em><\/p>\n<p><em><strong>Der Gedanke der Freiheit<\/strong><\/em><strong>.<br \/>\n<\/strong><em>\u201eDie Freiheit, welche Luther meinte, war die eines religi\u00f6s tief verpflichteten und an Gott gebundenen Gewissens. Diese Freiheit macht den Menschen zum Ma\u00df aller Dinge, sie beugt sich nur vor der Autorit\u00e4t Gottes.\u201c<\/em> (9, S. 230).<br \/>\nLuthers Freiheitsbegriff sollte dem Menschen erm\u00f6glichen, sich f\u00fcr die \u201erichtige\u201c, die evangelische Religion zu entscheiden. Keinesfalls sollte die staatliche Autorit\u00e4t untergraben werden.<br \/>\n<em>\u201eDer zum Ma\u00dfstab erhobene Mensch zerbricht in der Folge der Geschichte zuerst die Fesseln von Dogma und Hierarchie, dann die der feudalen und monarchischen Gewalten, schlie\u00dflich wirft er auch die lastende Autorit\u00e4t der traditionellen und lebenden Leitbilder, der bisher g\u00fcltigen Wertskalen und jeglicher F\u00fchrerschaft ab&#8230;.<br \/>\n<\/em>I<em>m Namen der Freiheit pl\u00fcndern und sch\u00e4nden die Cromwellschen Heere in Irland, die Calvinisten in Genf, die Puritaner in den Neuenglandstaaten; in der franz\u00f6sischen Revolution werden der P\u00f6belfreiheit die Blutopfer der Septembermorde und sp\u00e4ter die des \u201a<\/em><em style=\"font-size: revert; color: initial;\">terreur blanche\u2019 <a href=\"#_edn9\" name=\"_ednref9\">[9]<\/a> gebracht, man tanzt um die Guillotine wie um die Freiheitsb\u00e4ume, man metzelt St\u00e4nde und Klassen nieder, die sich einer gewissen Form von Freiheit als hinderlich erweisen. Alle Revolutionen schreiben \u201aFreiheit\u2019 auf ihre Banner und verbreiten sie mit Kanonen, Salven und Bajonetten, indem sie anderen menschlichen Wesen ihre Freiheit nehmen.\u201c<\/em><span style=\"font-size: revert; color: initial;\"> (9, S. 230).<br \/>\n<\/span>Heute gibt es kaum einen Begriff, der von Demagogen, Politpropagandisten, Revolution\u00e4ren, Volksverhetzern mehr missbraucht wird, als die \u201eFreiheit\u201c.<\/p>\n<h5>Alles ger\u00e4t ins Wanken<\/h5>\n<p>Der Mensch des Mittelalters durfte sich geborgen f\u00fchlen in einem vom Willen Gottes gelenkten Kosmos.<br \/>\nIm Schutze der Himmelsglocke befand sich die Erde im Mittelpunkt der Welt. Um die Erde kreisten die sieben Wandelgestirne (Mond, Merkur, Venus, Sonne, Mars, Jupiter, Saturn). In den Sternen am Firmament konnte man Fenster des Himmels sehen, in dem Gott thronte. ER wusste alles, sah alles und lenkte alles. Im Erdinneren war dann die Unterwelt, die H\u00f6lle zu vermuten.<\/p>\n<p>Der Wille Gottes war offenbart in der Heiligen Schrift, auf der auch die irdische Ordnung in Kirche und Staat aufgebaut war. Der s\u00fcndige Mensch hatte sich dem\u00fctig dem Willen Gottes zu f\u00fcgen und den Autorit\u00e4ten in Kirche und Staat treu zu gehorchen.<\/p>\n<p>In der Neuzeit brachen die Fixpunkte dieses mittelalterlichen Weltverst\u00e4ndnisses weg:<br \/>\n* Die \u201eallein selig machende Kirche\u201c musste sich in Frage stellen lassen und bekam Konkurrenz.<br \/>\n* Die Erde verlor ihre besondere Stellung im Mittelpunkt der Welt.<br \/>\n<strong>* <\/strong>Giordano Bruno sah in den Fixsternen Sonnen gleich unserer Sonne; umgeben von Planeten, auf denen erl\u00f6sungsbed\u00fcrftige Menschen leben gleich uns. Wie war vor diesem Hintergrund die Einmaligkeit der Sendung Jesu zu verstehen?<br \/>\n<strong>* <\/strong>Die Bibel musste sich hinterfragen lassen. War sie \u201eGottes Wort\u201c oder nur eine von irrenden Menschen tradierte \u00dcberlieferung?<br \/>\n* Zuletzt stellte der Rationalismus alles in Frage: Heilige Schriften, Religionen, Traditionen, Herrschaftssysteme. Die christliche Ethik verlor ihre einigende Kraft, die einst alle gesellschaftlichen Gruppen des Abendlandes verbunden hatte. Der Einzelmensch und sein Wohlergehen stehen von nun an im Vordergrund. Die gemeinsame Religion, eine von allen anerkannte Weltanschauung als Grundlagen f\u00fcr Staat und Gesellschaft, ging verloren.<\/p>\n<p>Heute wird in einer von der \u00d6konomie beherrschten, globalisierten Welt, zersplittert in viele Staaten, Regierungsformen, Traditionen und Religionen, die verbindende, gro\u00dfe Idee gesucht, die den schrankenlosen Egoismus von Einzelnen, von Gruppen, Parteien, Religionen und Staaten \u00fcberwindet und eine mehr dem Gemeinwohl und dem Naturschutz verpflichtete Gesellschaft entstehen l\u00e4sst.<br \/>\nKann es die \u201efreiheitliche Demokratie\u201c sein? Die ohne eine allgemein akzeptierte Weltanschauung, ohne ein \u00fcbergeordnetes Prinzip, ohne Gott und dessen ewige Gesetze auskommen will?<\/p>\n<p><strong>Literatur:<br \/>\n<\/strong>(1) Darwin John, Der imperiale Traum, Campus, Frankfurt, 2010.<br \/>\n(2) Der Spiegel, 45\/2011, Seite 134.<br \/>\n(3) Ertl Thomas, Alle Wege f\u00fchrten nach Rom, Jan Thorbecke, Ostfildern, 2010.<br \/>\n(4) Lutz Heinrich, Reformation und Gegenreformation, Oldenbourg, M\u00fcnchen, 2002.<br \/>\n(5) Praxis Geschichte 6\/2009, Westermann, Braunschweig.<br \/>\n(6) Sethe Paul, Schicksalsstunden der Weltgeschichte, Heinrich Scheffler, Frankfurt, 1952.<br \/>\n(7) Venzke Andreas, Luther und die Macht des Wortes, Arena, W\u00fcrzburg, 2007.<br \/>\n(8) Weber Max, Die protestantische Ethik und der Geist des Kapitalismus, C. H. Beck, M\u00fcnchen, 2006.<br \/>\n(9) Zierer Otto, Ideen bewegen die Welt, Prima, G\u00fctersloh, 1978.<br \/>\n(10) <a href=\"http:\/\/de.wikipedia.org\/wiki\/Calvinismus\">http:\/\/de.wikipedia.org\/wiki\/Calvinismus.\u00a0<\/a><\/p>\n<p><strong>Endnoten:<br \/>\n<\/strong><a href=\"#_ednref1\" name=\"_edn1\">[1]<\/a> Reformierte Kirchen w\u00e4hlten den Begriff \u201eevangelisch\u201c um klarzustellen, dass sie ausschlie\u00dflich die Bibel als Quelle akzeptieren.<br \/>\n<a href=\"#_ednref2\" name=\"_edn2\">[2]<\/a> Als Protestanten werden nach der Reformation entstandene, christliche Konfessionen bezeichnet, die den Papst nicht anerkennen.<br \/>\n<a href=\"#_ednref3\" name=\"_edn3\">[3]<\/a> Die ersten Schriften mit beweglichen Metalllettern wurden im 12. Jahrhundert in Korea gedruckt.<br \/>\n<a href=\"#_ednref4\" name=\"_edn4\">[4]<\/a> Der Florentiner Amerigo Vespucci, der dem vierten Kontinent seinen Namen gab, hatte schon nach einer Reise in die Neue Welt in den Jahren 1501\/02 die Vermutung ausgesprochen, es handele sich um einen Kontinent.<br \/>\n<a href=\"#_ednref5\" name=\"_edn5\">[5]<\/a> Die sieben Kurf\u00fcrsten w\u00e4hlten den Deutschen K\u00f6nig.<br \/>\n<a href=\"#_ednref6\" name=\"_edn6\">[6]<\/a> Die Jesusworte bei seinem Abschiedsmahl (Matth. 26, 26-28 bzw. Mark. 14, 22-24) wurden schon von seinen J\u00fcngern missverstanden. Die Kl\u00e4rung brachte Abd-ru-shin in seinem Vortrag \u201eDas ist mein Fleisch! Das ist mein Blut\u201c. (&#8222;Im Lichte der Wahrheit&#8220;, Band 2, Vortrag 47).<br \/>\n<a href=\"#_ednref7\" name=\"_edn7\">[7]<\/a> Der amerikanische Wahlspruch \u201etime is money\u201c (Zeit ist Geld) war damals noch nicht erfunden, trifft aber genau diese Denkungsart.<br \/>\n<a href=\"#_ednref8\" name=\"_edn8\">[8]<\/a> Hugenotten = Eidgenossen. Calvinistisch Reformierte in Frankreich.<br \/>\n<a href=\"#_ednref9\" name=\"_edn9\">[9]<\/a> Terreur blanche = der wei\u00dfe Schrecken zwischen 1815 und 1820. Die blutigen Vergeltungsaktionen der zur\u00fcckkehrenden Emigranten gegen Anh\u00e4nger der Revolution und Napoleons.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zum 31. Oktober 2017 Zum f\u00fcnfhundertsten Jahrestag der Reformation kommt eine Flut von Veranstaltungen und Publikationen \u00fcber Martin Luther, seinen Streit mit dem Papst, die evangelischen[1] Theologien und die Geschichte der protestantischen[2] Kirchen. Wir wollen an dieser Stelle nicht die Pers\u00f6nlichkeit Luthers w\u00fcrdigen oder seine Weltanschauung betrachten; das haben viele andere bereits ausf\u00fchrlich getan. Wir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2402","post","type-post","status-publish","format-standard","hentry","category-gedenktage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>500 Jahre Reformation &#8211; SiegfriedHagl.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siegfriedhagl.com\/ru\/\u043f\u0430\u043c\u044f\u0442\u043d\u044b\u0435-\u0434\u043d\u0438\/500-\u043b\u0435\u0442-\u0440\u0435\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"500 Jahre Reformation &#8211; SiegfriedHagl.com\" \/>\n<meta property=\"og:description\" content=\"Zum 31. Oktober 2017 Zum f\u00fcnfhundertsten Jahrestag der Reformation kommt eine Flut von Veranstaltungen und Publikationen \u00fcber Martin Luther, seinen Streit mit dem Papst, die evangelischen[1] Theologien und die Geschichte der protestantischen[2] Kirchen. Wir wollen an dieser Stelle nicht die Pers\u00f6nlichkeit Luthers w\u00fcrdigen oder seine Weltanschauung betrachten; das haben viele andere bereits ausf\u00fchrlich getan. Wir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siegfriedhagl.com\/ru\/\u043f\u0430\u043c\u044f\u0442\u043d\u044b\u0435-\u0434\u043d\u0438\/500-\u043b\u0435\u0442-\u0440\u0435\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438\/\" \/>\n<meta property=\"og:site_name\" content=\"SiegfriedHagl.com\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-29T09:56:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-23T11:37:35+00:00\" \/>\n<meta name=\"author\" content=\"siegfriedhagl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c\" \/>\n\t<meta name=\"twitter:data1\" content=\"siegfriedhagl\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/gedenktage\\\/500-jahre-reformation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/gedenktage\\\/500-jahre-reformation\\\/\"},\"author\":{\"name\":\"siegfriedhagl\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"headline\":\"500 Jahre Reformation\",\"datePublished\":\"2015-07-29T09:56:14+00:00\",\"dateModified\":\"2025-09-23T11:37:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/gedenktage\\\/500-jahre-reformation\\\/\"},\"wordCount\":4797,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"articleSection\":[\"Gedenktage\"],\"inLanguage\":\"ru-RU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/gedenktage\\\/500-jahre-reformation\\\/\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/gedenktage\\\/500-jahre-reformation\\\/\",\"name\":\"500 Jahre Reformation &#8211; SiegfriedHagl.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\"},\"datePublished\":\"2015-07-29T09:56:14+00:00\",\"dateModified\":\"2025-09-23T11:37:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/gedenktage\\\/500-jahre-reformation\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siegfriedhagl.com\\\/gedenktage\\\/500-jahre-reformation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/gedenktage\\\/500-jahre-reformation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"500 Jahre Reformation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\",\"name\":\"SiegfriedHagl.com\",\"description\":\"Artikel und Blog von Siegfried Hagl\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\",\"name\":\"siegfriedhagl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"caption\":\"siegfriedhagl\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.hagl.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"500 \u043b\u0435\u0442 \u0420\u0435\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438 - SiegfriedHagl.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siegfriedhagl.com\/ru\/\u043f\u0430\u043c\u044f\u0442\u043d\u044b\u0435-\u0434\u043d\u0438\/500-\u043b\u0435\u0442-\u0440\u0435\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438\/","og_locale":"ru_RU","og_type":"article","og_title":"500 Jahre Reformation &#8211; SiegfriedHagl.com","og_description":"Zum 31. Oktober 2017 Zum f\u00fcnfhundertsten Jahrestag der Reformation kommt eine Flut von Veranstaltungen und Publikationen \u00fcber Martin Luther, seinen Streit mit dem Papst, die evangelischen[1] Theologien und die Geschichte der protestantischen[2] Kirchen. Wir wollen an dieser Stelle nicht die Pers\u00f6nlichkeit Luthers w\u00fcrdigen oder seine Weltanschauung betrachten; das haben viele andere bereits ausf\u00fchrlich getan. Wir [&hellip;]","og_url":"https:\/\/www.siegfriedhagl.com\/ru\/\u043f\u0430\u043c\u044f\u0442\u043d\u044b\u0435-\u0434\u043d\u0438\/500-\u043b\u0435\u0442-\u0440\u0435\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438\/","og_site_name":"SiegfriedHagl.com","article_published_time":"2015-07-29T09:56:14+00:00","article_modified_time":"2025-09-23T11:37:35+00:00","author":"siegfriedhagl","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c":"siegfriedhagl","\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"26 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siegfriedhagl.com\/gedenktage\/500-jahre-reformation\/#article","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/gedenktage\/500-jahre-reformation\/"},"author":{"name":"siegfriedhagl","@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"headline":"500 Jahre Reformation","datePublished":"2015-07-29T09:56:14+00:00","dateModified":"2025-09-23T11:37:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siegfriedhagl.com\/gedenktage\/500-jahre-reformation\/"},"wordCount":4797,"publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"articleSection":["Gedenktage"],"inLanguage":"ru-RU"},{"@type":"WebPage","@id":"https:\/\/www.siegfriedhagl.com\/gedenktage\/500-jahre-reformation\/","url":"https:\/\/www.siegfriedhagl.com\/gedenktage\/500-jahre-reformation\/","name":"500 \u043b\u0435\u0442 \u0420\u0435\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438 - SiegfriedHagl.com","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/#website"},"datePublished":"2015-07-29T09:56:14+00:00","dateModified":"2025-09-23T11:37:35+00:00","breadcrumb":{"@id":"https:\/\/www.siegfriedhagl.com\/gedenktage\/500-jahre-reformation\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siegfriedhagl.com\/gedenktage\/500-jahre-reformation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siegfriedhagl.com\/gedenktage\/500-jahre-reformation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.siegfriedhagl.com\/"},{"@type":"ListItem","position":2,"name":"500 Jahre Reformation"}]},{"@type":"WebSite","@id":"https:\/\/www.siegfriedhagl.com\/#website","url":"https:\/\/www.siegfriedhagl.com\/","name":"SiegfriedHagl.com","description":"\u0421\u0442\u0430\u0442\u044c\u044f \u0438 \u0431\u043b\u043e\u0433 \u0417\u0438\u0433\u0444\u0440\u0438\u0434\u0430 \u0425\u0430\u0433\u043b\u044f","publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siegfriedhagl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":["Person","Organization"],"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f","name":"\u0437\u0438\u0433\u0444\u0440\u0438\u0434\u0445\u0430\u0433\u043b\u044c","image":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","caption":"siegfriedhagl"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.hagl.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/2402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/comments?post=2402"}],"version-history":[{"count":64,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/2402\/revisions"}],"predecessor-version":[{"id":11890,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/2402\/revisions\/11890"}],"wp:attachment":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/media?parent=2402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/categories?post=2402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/tags?post=2402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}