{"id":2109,"date":"2014-03-19T11:20:20","date_gmt":"2014-03-19T10:20:20","guid":{"rendered":"https:\/\/www.siegfriedhagl.com\/?page_id=2109"},"modified":"2023-08-04T10:51:02","modified_gmt":"2023-08-04T09:51:02","slug":"karthago-der-erste-kapitalistisch-staat","status":"publish","type":"post","link":"https:\/\/www.siegfriedhagl.com\/ru\/%d1%8d%d0%ba%d0%be%d0%bd%d0%be%d0%bc%d0%b8%d1%87%d0%b5%d1%81%d0%ba%d0%b8%d0%b9-%d0%b8-%d1%81%d0%be%d1%86%d0%b8%d0%b0%d0%bb%d1%8c%d0%bd%d1%8b%d0%b9\/%d0%ba%d0%b0%d1%80%d1%84%d0%b0%d0%b3%d0%b5%d0%bd-%d0%bf%d0%b5%d1%80%d0%b2%d0%be%d0%b5-%d0%ba%d0%b0%d0%bf%d0%b8%d1%82%d0%b0%d0%bb%d0%b8%d1%81%d1%82%d0%b8%d1%87%d0%b5%d1%81%d0%ba%d0%be%d0%b5-%d0%b3\/","title":{"rendered":"\u041a\u0430\u0440\u0444\u0430\u0433\u0435\u043d - \u043f\u0435\u0440\u0432\u043e\u0435 \u043a\u0430\u043f\u0438\u0442\u0430\u043b\u0438\u0441\u0442\u0438\u0447\u0435\u0441\u043a\u043e\u0435 \u0433\u043e\u0441\u0443\u0434\u0430\u0440\u0441\u0442\u0432\u043e?"},"content":{"rendered":"<blockquote><p><span style=\"font-size: 13px;\">(Ver\u00f6ffentlicht April 2014)<\/span><\/p><\/blockquote>\n<p><strong><i>Lange vor dem Industriezeitalter bot bereits eine antike Stadt ein Exempel kapitalistischen Wirtschaftens. Die fortschrittliche \u00d6konomie Karthagos sicherte der Handelsmacht zwar gro\u00dfe Erfolge, ging aber auf Kosten vieler Menschenleben. Nach ihrer Zerst\u00f6rung durch die R\u00f6mer \u00fcbernahmen diese das erfolgstr\u00e4chtige Modell, gingen nun aber unaufhaltsam ihrem Zerfall entgegen \u2026<\/i><\/strong><\/p>\n<p><b>Das New York der Antike<br \/>\n<\/b>In der Antike war Nordafrika \u2013 wo es damals noch reichlich W\u00e4lder gab \u2013 ein landwirtschaftlich sehr produktives Gebiet, das bis ins f\u00fcnfte nachchristliche Jahrhundert die Kornkammer Roms blieb.<br \/>\nDie Karthager, von den R\u00f6mern \u201ePunier\u201c genannt, hatten in Bereichen des heutigen Algerien, Libyen, Marokko und Tunesien eine gut organisierte Landwirtschaft entwickelt. Neben Getreide wurden Olivenb\u00e4ume, Weinreben, Feigenb\u00e4ume und Dattelpalmen angebaut (8). Mit intensiver Bewirtschaftung und k\u00fcnstlicher Bew\u00e4sserung wurden hervorragende Ernten erzielt. Diese karthagischen Gro\u00dfg\u00fcter waren weit produktiver als die Parzellen der r\u00f6mischen Kleinbauern. F\u00fcr die R\u00f6mer waren die Nordafrikaner im Fernhandel unangenehme Konkurrenten.<\/p>\n<p>Im dritten vorchristlichen Jahrhundert hatte sich Karthago, das \u201eNew York der Antike\u201c, dank seiner geographisch g\u00fcnstigen Lage zum gr\u00f6\u00dften Handelsimperium seiner Zeit entwickelt. Karthago war die verm\u00f6gendste und prunkvollste Stadt des Mittelmeerraumes; noch weit reicher als es Athen zu seiner Bl\u00fctezeit gewesen war.<br \/>\nDer Herrschaftsbereich des Stadtstaates Karthago umfasste K\u00fcstenstreifen in Nordafrika und Spanien, St\u00e4dte am Mittelmeer und etliche Inseln. Karthagos Handelshafen bot den gr\u00f6\u00dften Umschlagplatz f\u00fcr den Mittelmeerhandel, und das Innere seines sagenumwobenen, streng abgeschirmten Kriegshafens war eines der bestgeh\u00fcteten Geheimnisse. Wie alle ph\u00f6nizischen[i] St\u00e4dte war auch das kosmopolitische Karthago f\u00fcr seine maritimen Leistungen und vor allem seine geschickten H\u00e4ndler ber\u00fchmt, die so gut wie alle Tricks kannten. Die Kriegsgaleeren der Ph\u00f6nizier beherrschten das Mittelmeer, und ihre Lastschiffe dominierten den Seehandel zwischen den Azoren und den griechischen K\u00fcsten.<br \/>\nIn Karthago, als der bedeutendsten der ph\u00f6nizischen St\u00e4dte, hatten reiche Handelsherren das Sagen. Der Stadtstaat f\u00f6rderte den Handel und erzwang sich Handelsmonopole.<br \/>\nBeispielsweise wurde auf den Balearen (Mallorca, Menorca usw.) den Bauern der Getreideanbau verboten. Dort durfte nur Wein und \u00d6l erzeugt werden. Im Gegenzug war der Anbau von Oliven und Reben auf Sardinien bei Todesstrafe untersagt. So waren diese Inseln auf die Lieferungen der fehlenden Produkte durch die Karthager angewiesen, die ihr Monopol zu nutzen wussten (7, S. 48).<br \/>\nDie Idee, ganze Staaten mit kriegerischer Gewalt in wirtschaftliche Abh\u00e4ngigkeit zu zwingen und daraus seinen Profit zu ziehen, stammt also keineswegs erst aus der Zeit des neuzeitlichen Kolonialismus, der seit dem 15. Jahrhundert von Europa ausging.<\/p>\n<p><b>Krieg mit Rom<br \/>\n<\/b>In der Mitte des dritten vorchristlichen Jahrhunderts trat das m\u00e4chtiger werdende R\u00f6mische Reich den Karthagern entgegen, die sich die Insel Sizilien ganz aneignen wollten, um die von dort ausgehende Piraterie zu stoppen. Sizilien geh\u00f6rte damals noch nicht zu Rom.<br \/>\nDie dadurch ausgel\u00f6sten kriegerischen Auseinandersetzungen f\u00fchrten zu harten Entscheidungsk\u00e4mpfen um die F\u00fchrungsrolle im Mittelmeerraum, deren Ergebnis die Geschichte der n\u00e4chsten Jahrhunderte nachhaltig beeinflusste.<br \/>\nKarthago verlor im Ersten Punischen Krieg (264\u2013241 v. Chr.) seinen Einfluss auf Sizilien, das nun r\u00f6misch wurde.<br \/>\nVierzig Jahre sp\u00e4ter, nach dem Zweiten Punischen Krieg, dem \u201eHannibalischen Krieg\u201c (218\u2013201 v. Chr.), musste Karthago nach einer entscheidenden Niederlage auf alle seine au\u00dferafrikanischen Besitzungen verzichten. Damit war die politische Bedeutung der einstigen Gro\u00dfmacht stark geschrumpft. F\u00fcr Rom war Karthago keine milit\u00e4rische Bedrohung mehr.<br \/>\nDoch \u00f6konomisch entwickelte sich der besiegte Stadtstaat bald wieder so gut, dass er mit den R\u00f6mern erfolgreich konkurrieren konnte und deren Neid erweckte.<\/p>\n<p><b>Die erste Theorie des Kapitalismus?<br \/>\n<\/b>Einige Zeit nach dem Ende des Zweiten Punischen Krieges reiste eine r\u00f6mische Gesandtschaft zu politischen Gespr\u00e4chen nach Karthago. Einer der Senatoren, die diese Delegation anf\u00fchrten, war Marcus Porcius Cato der \u00c4ltere (234\u2013149 v. Chr.). Als Staatsbeamter war er um die Erhaltung altr\u00f6mischer Tugenden bem\u00fcht. Privat besa\u00df er ein gro\u00dfes Landgut und blieb sein Leben lang am Landbau interessiert. Nun fand er Gelegenheit, die sehr produktiven punischen Bewirtschaftungsmethoden an Ort und Stelle zu studieren.<br \/>\nIn der Bibliothek von Karthago (die sp\u00e4ter von den R\u00f6mern total zerst\u00f6rt wurde) lie\u00df sich Cato mit Hilfe eines Dolmetschers ein ber\u00fchmtes Werk zeigen, von dem in Rom schon Ger\u00fcchte umgingen. Der punische Schriftsteller Mago verfasste im zweiten Jahrhundert vor Christus eine umfassende Agrar-Enzyklop\u00e4die, die nicht erhalten ist. Ihr Inhalt ist uns nur aus Zitaten anderer Autoren bekannt, die ihn als den \u201eVater der Landwirtschaft\u201c lobten.<br \/>\nIn seinem Werk beginnt Mago <em>\u201emit dem Gutskauf. Er verr\u00e4t gleich zu Anfang des ersten Buches, dass er ganz kapitalistisch eingestellt ist. Ihm sind Erde, Regen und Sonnenschein nur Kr\u00e4fte, mit denen man bei einigem Geschick verk\u00e4ufliche Waren erzeugen kann. Land ist f\u00fcr Mago nicht Heimat, und Pflanze, Tier und Wetter sind ihm nicht ein St\u00fcck Natur, in deren Kreislauf das Schicksal des Menschen eingespannt ist; der Bauer ist f\u00fcr den Karthager nicht der erdverwurzelte Mensch, der mit dem Herzen seinem Hof verbunden ist: er kennt nur menschliche und tierische Arbeitskraft zur Bewirtschaftung der \u00c4cker und G\u00e4rten. Seine Untersuchungen richten sich auf die zweckm\u00e4\u00dfigste Verwendung der Arbeit: er versucht, die wissenschaftliche Grundlage einer rein kapitalistischen Bodenbewirtschaftung zu schaffen, deren h\u00f6chstes Ziel eine m\u00f6glichst hohe Verzinsung des aufgewendeten Kapitals ist.\u201c<\/em> (7, S. 47).<\/p>\n<p><b>Produktionsmittel Mensch<br \/>\n<\/b>Dann fand Cato Gelegenheit, selbst zu sehen, wie die Theorien des Mago in der Praxis funktionierten:<br \/>\nAn einem schier endlosen Acker <em>\u201ewogt das braugoldene Korn auf kr\u00e4ftigen, kurzen Halmen [\u2026] Eine Linie von mehreren hundert Sklaven aller Rassen bewegt sich langsam gegen das stehende Korn. Jeder dieser M\u00e4nner und Frauen ist mit einem scharfen Sichelmesser und einem Sack ausger\u00fcstet. Im Takt, den einige Aufseher angeben, schneiden sie die \u00c4hren vom Halm und stecken sie in die S\u00e4cke. Hinter der ersten Reihe der M\u00e4nner und Frauen geht eine zweite Kette, die das Stroh dicht am Boden schneidet, und dahinter t\u00e4nzeln einige Fl\u00f6tenbl\u00e4ser, nach deren Musik die Arbeit vor sich zu gehen hat.<br \/>\n<\/em><em>Manchmal klatschen die langen Nilpferdpeitschen der Aufseher auf die nackten, braunen, schwarzen und rotgebrannten R\u00fccken. Fl\u00fcche und Schreie gellen dann \u00fcber die gl\u00fchenden, staubigen Felder der \u201aGetreidefabrik\u2018.<br \/>\n<\/em><em>Und diese langen Linien der Sklaven sind mit Lederriemen aneinander gefesselt. Sie haben nur so viel Bewegungsfreiheit, dass sie ihre Arbeit tun k\u00f6nnen [\u2026] All diese Hunderte von Menschen auf den meilenweiten \u00c4ckern der Plantage bilden zusammen nur eine einzige gro\u00dfe Erntemaschine \u2026\u201c<\/em> (7, S. 49).<\/p>\n<p>Karthago konnte nach dem Zweiten Punischen Krieg keine Kriege mehr f\u00fchren, um Sklaven zu gewinnen. Der von seiner Art der Bewirtschaftung ben\u00f6tigte laufende Nachschub an \u201eMenschenmaterial\u201c geriet ins Stocken. Dadurch hatte die h\u00f6chst produktive karthagische Landwirtschaft ein Problem. Denn der Verschlei\u00df des \u201eProduktionsmittels Mensch\u201c war gro\u00df.<br \/>\nIm Gutsbetrieb konnte ein Sklave, bei einer Lebenserwartung von kaum zwanzig Jahren, seine volle Arbeitskraft h\u00f6chstes \u00fcber ein Dutzend Jahre erbringen. In den Werkst\u00e4tten war die Lebensdauer geringer. Die M\u00fchlensklaven waren meist nur f\u00fcr vier Jahre zu gebrauchen und im Bergwerk und auf den Galeeren verschlissen sich die Arbeitskr\u00e4fte noch schneller (7, S. 49)[2].\u00a0Aufm\u00fcpfige Sklaven wurden grausam bestraft.<\/p>\n<blockquote><p><b>Catos einziger Erfolg und Roms Bu\u00dfe<br \/>\n<\/b><em>\u201eDer alte Censor <\/em>[5]<em>\u00a0hatte eine tiefe Wirkung auf die r\u00f6mische Geschichte. Noch jahrhundertelang blickte man auf ihn als den typischen R\u00f6mer der Republik zur\u00fcck: Cicero<\/em>\u00a0[Anm.: r\u00f6mischer Schriftsteller und Redner 106\u201343 v. Chr.] <em>idealisierte ihn in seinem De senectute; sein Urenkel[6] reinkarnierte seine Philosophie ohne seinen Humor; Marc Aurel <\/em>[Anm.: R\u00f6mischer Kaiser 161\u2013180 n. Chr.]<em> nahm ihn sich zum Vorbild; Fronto <\/em>[7]<em> rief die lateinischen Literaten auf, zu der Einfachheit und Geradlinigkeit seines Stiles zur\u00fcckzukehren. Und doch war die Zerst\u00f6rung Karthagos sein einziger wirklicher Erfolg. Sein Feldzug gegen den Hellenismus scheitere v\u00f6llig; Literatur, Philosophie, Redekunst, Wissenschaft, Kunst, Religion, Sitten, Gebr\u00e4uche und Kleidung unterlagen in jeder Hinsicht dem griechischen Einfluss. Cato hasste die griechischen Philosophen; sein ber\u00fchmter Nachfahre <\/em>[Anm.: Cato der J\u00fcngere, vgl. Fu\u00dfnote 6]<em> umgab sich mit ihnen. Der religi\u00f6se Glaube, den er verloren hatte, lie\u00df sich von ihm nicht wieder beleben und ging weiter dem Untergang entgegen. Vor allem aber wuchs und vertiefte sich die politische Korruption, die er in seiner Jugend so sehr bek\u00e4mpft hatte, je eintr\u00e4glicher die \u00c4mter mit der Ausbreitung des Reiches wurden; jede neue Eroberung machte Rom reicher, verderbter, gnadenloser. Rom hatte jeden Krieg gewonnen \u2013 nur nicht den sozialen Krieg im Inneren, und mit der Zerst\u00f6rung Karthagos kam das letzte Hindernis, das dem Klassenkampf noch im Wege stand, zum Fortfall. Nun sollte Rom in hundert bitteren Revolutionsjahren Bu\u00dfe leisten f\u00fcr die Eroberung der Welt.\u201c<br \/>\n<\/em>Will Durant (2, S. 197 f.).<span style=\"font-size: 13px;\">\u00a0<\/span><\/p><\/blockquote>\n<p><b>Das j\u00e4he Ende Karthagos \u2026<br \/>\n<\/b>F\u00fcr den R\u00f6mer Cato war die Sklaverei kein Thema. Alle Staaten der Antike beruhten mehr oder weniger auf der billigen Sklavenarbeit, die auch in Rom die Regel war. Und so lange erfolgreiche Kriege gen\u00fcgend Gefangene einbrachten, war an Sklaven kein Mangel.<br \/>\nNeu waren f\u00fcr den R\u00f6mer das konsequente kapitalistische Denken der Karthager und ihre bestens durchorganisierte Bodenbewirtschaftung. Als erfahrener \u00d6konom erkannte er schnell, warum die Punier den R\u00f6mern so erfolgreich Konkurrenz machen konnten. Die Zukunft lag in den gro\u00dfen, mit Sklaven bewirtschafteten G\u00fctern. Die Kleinbauern auf der italienischen Halbinsel mit ihren Mischkulturen waren vielleicht krisensicherer, aber nicht wettbewerbsf\u00e4hig!<br \/>\nZur\u00fcck in Rom, schrieb Cato \u00fcber das in Karthago Erlebte ein Buch, das er <em>\u201eVon der Landwirtschaft\u201c<\/em> (1) nannte. Eine Abschrift dieses Werkes war bald in vielen r\u00f6mischen Gutsh\u00f6fen zu finden. Die Schl\u00fcsse, die Cato aus seinen Beobachtungen zog, klingen allen Gymnasiasten in den Ohren. Jede der Reden Catos vor dem Senat endete von nun an mit dem bekannten Satz:<br \/>\n<em>\u201eCeterum censeo Carthaginem esse delendam\u201c<\/em> (\u00dcbrigens bin ich der Meinung, dass Karthago zerst\u00f6rt werden muss).<\/p>\n<p>Bislang hatten die vorwiegend aus der b\u00e4uerlichen Bev\u00f6lkerung bestehenden r\u00f6mischen Milizen in der Hauptsache Verteidigungskriege gef\u00fchrt. Jetzt folgten sie der hetzenden Stimme Catos.<\/p>\n<p>Der Dritte Punische Krieg (149\u2013146 v. Chr.) war der erste von vielen noch folgenden r\u00f6mischen Raubz\u00fcgen, die ausschlie\u00dflich den imperialistischen Wirtschafts- und Machtinteressen Roms dienten.<\/p>\n<p>Marcus Porcius Cato erlebte die von ihm betriebene Vernichtung Karthagos im Dritten Punischen Krieg nicht mehr. Doch ist es seinem Einfluss zu verdanken, dass Magos Lehrbuch, als das einzige Werk der ganzen punischen Literatur, nach der vollst\u00e4ndigen Zerst\u00f6rung Karthagos, von den R\u00f6mern \u00fcbersetzt wurde. R\u00f6mische Autoren haben es dann viel zitiert.<\/p>\n<p><b>\u2026und das schleichende Ende Roms<br \/>\n<\/b>Karthago \u2013 der vermutlich erste \u201emoderne\u201c kapitalistische Staat \u2013 wurde 146 v. Chr. aus Konkurrenzneid auf verr\u00e4terische, grausame Weise erobert und vollst\u00e4ndig vernichtet. Danach \u00fcbernahm die r\u00f6mische Siegermacht dessen brutale Ausbeutungsmethoden und verlor ihre einstigen Tugenden.<br \/>\nDurch den st\u00e4ndigen \u201eVerbrauch an Sklaven\u201c geriet auch die r\u00f6mische Wirtschaft unter Druck. Immer neue Kriege wurden n\u00f6tig, um Sklaven einzufangen oder Zugang zu den orientalischen Sklavenm\u00e4rkten zu erhalten.<br \/>\nNach der Vernichtung Karthagos kamen Hunderttausende als Sklaven nach Italien. Die Landg\u00fcter der Karthager \u00fcbernahmen r\u00f6mische Verwalter. Und noch im Jahr der Vernichtung Karthagos (146 v. Chr.) \u00fcberfiel ein r\u00f6misches Heer auch die reiche griechische Stadt Korinth, pl\u00fcnderte sie aus, brannte sie nieder und f\u00fchrte 100.000 Sklaven davon.<br \/>\nDer antike Kapitalismus war auf permanenten Nachschub an \u201emenschlichen Produktionsmitteln\u201c angewiesen, den Raubkriege liefern mussten!<\/p>\n<p>F\u00fcr den r\u00f6mischen Bauernstand hatten die Punischen Kriege dramatische Folgen. Die Legion\u00e4re, die Karthago in drei Kriegen niedergek\u00e4mpft hatten, waren in der Mehrzahl Bauern. Ihr Blutzoll war hoch.<br \/>\nIm Zweiten Punischen Krieg hatte Hannibal gro\u00dfe Teile Italiens verw\u00fcstet. Viele der freien Bauern gerieten in \u00f6konomische Bedr\u00e4ngnis und mussten sich verschulden. Immer mehr Ackerland wurde Gro\u00dfgrundbesitz in den H\u00e4nden nur weniger Familien. Die neuen Eigent\u00fcmer folgten den Lehren des Karthagers Mago und produzierten durch Sklavenarbeit konkurrenzlos billig. Das war das Ende des altr\u00f6mischen Agrarstaates.<br \/>\nEin gro\u00dfer Teil der Bauern, die einst Rom gegr\u00fcndet und dann in harten K\u00e4mpfen gro\u00df gemacht hatten, war durch die Kriege verarmt. Ihnen blieb oft nur die Landflucht. Das daraus entstehende Stadtproletariat wuchs und wuchs.<\/p>\n<p>Bei den Herrschenden wurden Machtmissbrauch und Korruption zur Regel. Rom war auf dem Weg zu dem oft angeprangerten \u201esp\u00e4tr\u00f6mischen Sittenverfall\u201c, der einen ersten H\u00f6hepunkt unter Nero (37\u201368 n. Chr.) erreichte.<\/p>\n<p>Ausgerechnet Cato, einst \u00fcberzeugter H\u00fcter altr\u00f6mischer Tugenden, trug entscheidend zu dem Untergang der traditionellen b\u00e4uerlichen Lebensweise und dem Verfall der alten Sitten bei!<\/p>\n<p>Die Erinnerung an das romantische Landleben aus einer Zeit, als ein angeblich tugendhaftes, nach Gerechtigkeit strebendes Rom sich anschickte, die Welt zu erobern, war bald nur noch ein Thema dichterischer Verkl\u00e4rung. So schrieb der gro\u00dfe Dichter Vergil (70-19 v. Chr.) zur Zeit des Kaisers Augustus:<br \/>\n<i>\u201e\u00dcbergl\u00fccklich die Bauern, \/ Wenn sie ihrer eigensten G\u00fcter inne w\u00fcrden! \/ Denn ihnen l\u00e4sst fern vom L\u00e4rme der Waffen \/ Leben in F\u00fclle gedeihn die Allgerechte, die Erde!\u201c\u00a0<\/i><\/p>\n<p>Im r\u00f6mischen Senat dominierten die Oligarchen[3], die reichen\u00a0 Handelsherren und Gro\u00dfgrundbesitzer, die \u00fcber die Interessen der kleinen Leute rigoros hinweggingen. Zwar kam es zu Protesten und sogar Erhebungen der Plebejer[4], doch die Herrschenden konnten sich mit Tricks und Gewalt durchsetzen.<br \/>\nRom verspielte jegliche moralische Legitimation f\u00fcr seine Eroberungen und wurde \u2013 trotz seiner technischen und organisatorischen Leistungen \u2013 zum Feindbild f\u00fcr den Rest der Welt.<br \/>\nSieht Jemand eine Parallele zu heute?<\/p>\n<p><b>Blockierte die Sklavenarbeit den Fortschritt?<br \/>\n<\/b>Eine viel diskutierte Frage ist, ob die billige Sklavenarbeit die technische Entwicklung der Alten R\u00f6mer bremste. Eigentlich hatten diese schon viele der Kenntnisse, die mehr als ein Jahrtausend sp\u00e4ter zum wissenschaftlich-technischen Durchbruch in der Renaissance und besonders im Barockzeitalter f\u00fchrten.<\/p>\n<p>Warum haben die R\u00f6mer nicht schon das Schie\u00dfpulver und die Dampfmaschine erfunden? H\u00e4tten sie mit Kanonen ihr Weltreich retten k\u00f6nnen? War es bequemer und billiger, Sklaven schuften zu lassen, als teure Maschinen zu entwickeln?<\/p>\n<p>Vermutlich lassen sich solche m\u00fc\u00dfigen Fragen nie schl\u00fcssig kl\u00e4ren. Doch unstrittig scheint, dass die exzessive Sklavenwirtschaft den Keim f\u00fcr den Untergang Roms gelegt und zum Siegeszug des Christentums beigetragen hat.<span style=\"font-size: 13px;\">\u00a0<\/span><\/p>\n<p><b>Endnoten:<br \/>\n<\/b>[1] Ph\u00f6nizien, das \u201eLand des roten Purpurs\u201c, war im Altertum der Name eines K\u00fcstenstreifens an der syrischen Mittelmeerk\u00fcste. Von den St\u00e4dten Tyrus, Sidon, Berytos und Biblos ausgehend gr\u00fcndeten ph\u00f6nizische Kaufleute seit etwa 1200 v. Chr. Handelskolonien im Mittelmeerraum und dar\u00fcber hinaus, von denen Karthago die bedeutendste wurde.<br \/>\n[2] Aus lateinischen Grabsteinen mit Altersangaben wurde eine durchschnittliche Lebensdauer f\u00fcr Sklaven von 19 Jahren und f\u00fcr freie R\u00f6mer von 32 Jahren errechnet. Dabei sind Totgeburten und verstorbene Kleinkinder nicht ber\u00fccksichtigt, so dass die tats\u00e4chliche durchschnittliche Lebenserwartung noch geringer war. (4, S. 6).<br \/>\n[3] Oligarchie = Regierungsform, in der die Staatsgewalt in den H\u00e4nden einer kleinen Clique liegt, die durch Herkunft und Verm\u00f6gen, nicht durch Leistung zur Macht gelangte.<br \/>\n[4] Plebejer = im r\u00f6mischen Staat die mittlere und untere Klasse, die nicht zu den Nobiles (dem Adel) geh\u00f6rte.<br \/>\n[5] Censor = hoher Beamter der r\u00f6mischen Republik. Er war unter anderem f\u00fcr die Steuersch\u00e4tzung zust\u00e4ndig.<br \/>\n[6] Marcus Porcius Cato der J\u00fcngere (95\u201346 v. Chr.), ein Gegner Caesars.<br \/>\n[7] Marcus Cornelius Fronto (100\u2013170 n. Chr.), Grammatiker, Rhetoriker und Anwalt.<\/p>\n<p><b>Literatur:<br \/>\n<\/b>(1) Cato, Marcus Porcius, \u00dcber den Ackerbau, Franz Steiner, Wiesbaden 2005.<br \/>\n(2) Durant, Will, Kulturgeschichte der Menschheit, Band 7, Editions Rencontre, Lausanne o. J.<br \/>\n(3) Huss, Werner, Karthago, C. H. Beck, M\u00fcnchen 1990.<br \/>\n(4) Krenkel, Werner A., Technik in der Antike, Vandenhoeck &amp; Ruprecht, G\u00f6ttingen 1994.<br \/>\n(5) Schumacher, Leonhard, Sklaverei in der Antike, C. H. Beck, M\u00fcnchen 2001.<br \/>\n(6) Vergil, Landleben, Artemis, M\u00fcnchen, 1987.<br \/>\n(7) Zierer, Otto, Aus Knechtschaft zur Freiheit, Das Bergland Buch, Salzburg 1979.<br \/>\n(8) http:\/\/de.wikipedia.org\/wiki\/Karthago.<br \/>\n(9) http:\/\/de.wikipedia.org\/wiki\/Geschichte_Karthagos.<br \/>\n(10) http:\/\/de.wikipedia.org\/wiki\/Marcus_Portius_Cato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Ver\u00f6ffentlicht April 2014) Lange vor dem Industriezeitalter bot bereits eine antike Stadt ein Exempel kapitalistischen Wirtschaftens. Die fortschrittliche \u00d6konomie Karthagos sicherte der Handelsmacht zwar gro\u00dfe Erfolge, ging aber auf Kosten vieler Menschenleben. Nach ihrer Zerst\u00f6rung durch die R\u00f6mer \u00fcbernahmen diese das erfolgstr\u00e4chtige Modell, gingen nun aber unaufhaltsam ihrem Zerfall entgegen \u2026 Das New York der [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2109","post","type-post","status-publish","format-standard","hentry","category-wirtschaft-und-soziales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Karthago - der erste kapitalistische Staat ? &#8211; SiegfriedHagl.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siegfriedhagl.com\/ru\/\u044d\u043a\u043e\u043d\u043e\u043c\u0438\u0447\u0435\u0441\u043a\u0438\u0439-\u0438-\u0441\u043e\u0446\u0438\u0430\u043b\u044c\u043d\u044b\u0439\/\u043a\u0430\u0440\u0444\u0430\u0433\u0435\u043d-\u043f\u0435\u0440\u0432\u043e\u0435-\u043a\u0430\u043f\u0438\u0442\u0430\u043b\u0438\u0441\u0442\u0438\u0447\u0435\u0441\u043a\u043e\u0435-\u0433\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karthago - der erste kapitalistische Staat ? &#8211; SiegfriedHagl.com\" \/>\n<meta property=\"og:description\" content=\"(Ver\u00f6ffentlicht April 2014) Lange vor dem Industriezeitalter bot bereits eine antike Stadt ein Exempel kapitalistischen Wirtschaftens. Die fortschrittliche \u00d6konomie Karthagos sicherte der Handelsmacht zwar gro\u00dfe Erfolge, ging aber auf Kosten vieler Menschenleben. Nach ihrer Zerst\u00f6rung durch die R\u00f6mer \u00fcbernahmen diese das erfolgstr\u00e4chtige Modell, gingen nun aber unaufhaltsam ihrem Zerfall entgegen \u2026 Das New York der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siegfriedhagl.com\/ru\/\u044d\u043a\u043e\u043d\u043e\u043c\u0438\u0447\u0435\u0441\u043a\u0438\u0439-\u0438-\u0441\u043e\u0446\u0438\u0430\u043b\u044c\u043d\u044b\u0439\/\u043a\u0430\u0440\u0444\u0430\u0433\u0435\u043d-\u043f\u0435\u0440\u0432\u043e\u0435-\u043a\u0430\u043f\u0438\u0442\u0430\u043b\u0438\u0441\u0442\u0438\u0447\u0435\u0441\u043a\u043e\u0435-\u0433\/\" \/>\n<meta property=\"og:site_name\" content=\"SiegfriedHagl.com\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-19T10:20:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-04T09:51:02+00:00\" \/>\n<meta name=\"author\" content=\"siegfriedhagl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c\" \/>\n\t<meta name=\"twitter:data1\" content=\"siegfriedhagl\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wirtschaft-und-soziales\\\/karthago-der-erste-kapitalistisch-staat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wirtschaft-und-soziales\\\/karthago-der-erste-kapitalistisch-staat\\\/\"},\"author\":{\"name\":\"siegfriedhagl\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"headline\":\"Karthago &#8211; der erste kapitalistische Staat ?\",\"datePublished\":\"2014-03-19T10:20:20+00:00\",\"dateModified\":\"2023-08-04T09:51:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wirtschaft-und-soziales\\\/karthago-der-erste-kapitalistisch-staat\\\/\"},\"wordCount\":2616,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"articleSection\":[\"Wirtschaft und Soziales\"],\"inLanguage\":\"ru-RU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wirtschaft-und-soziales\\\/karthago-der-erste-kapitalistisch-staat\\\/\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wirtschaft-und-soziales\\\/karthago-der-erste-kapitalistisch-staat\\\/\",\"name\":\"Karthago - der erste kapitalistische Staat ? &#8211; SiegfriedHagl.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\"},\"datePublished\":\"2014-03-19T10:20:20+00:00\",\"dateModified\":\"2023-08-04T09:51:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wirtschaft-und-soziales\\\/karthago-der-erste-kapitalistisch-staat\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siegfriedhagl.com\\\/wirtschaft-und-soziales\\\/karthago-der-erste-kapitalistisch-staat\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wirtschaft-und-soziales\\\/karthago-der-erste-kapitalistisch-staat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karthago &#8211; der erste kapitalistische Staat ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\",\"name\":\"SiegfriedHagl.com\",\"description\":\"Artikel und Blog von Siegfried Hagl\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\",\"name\":\"siegfriedhagl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"caption\":\"siegfriedhagl\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.hagl.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041a\u0430\u0440\u0444\u0430\u0433\u0435\u043d - \u043f\u0435\u0440\u0432\u043e\u0435 \u043a\u0430\u043f\u0438\u0442\u0430\u043b\u0438\u0441\u0442\u0438\u0447\u0435\u0441\u043a\u043e\u0435 \u0433\u043e\u0441\u0443\u0434\u0430\u0440\u0441\u0442\u0432\u043e? - SiegfriedHagl.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siegfriedhagl.com\/ru\/\u044d\u043a\u043e\u043d\u043e\u043c\u0438\u0447\u0435\u0441\u043a\u0438\u0439-\u0438-\u0441\u043e\u0446\u0438\u0430\u043b\u044c\u043d\u044b\u0439\/\u043a\u0430\u0440\u0444\u0430\u0433\u0435\u043d-\u043f\u0435\u0440\u0432\u043e\u0435-\u043a\u0430\u043f\u0438\u0442\u0430\u043b\u0438\u0441\u0442\u0438\u0447\u0435\u0441\u043a\u043e\u0435-\u0433\/","og_locale":"ru_RU","og_type":"article","og_title":"Karthago - der erste kapitalistische Staat ? &#8211; SiegfriedHagl.com","og_description":"(Ver\u00f6ffentlicht April 2014) Lange vor dem Industriezeitalter bot bereits eine antike Stadt ein Exempel kapitalistischen Wirtschaftens. Die fortschrittliche \u00d6konomie Karthagos sicherte der Handelsmacht zwar gro\u00dfe Erfolge, ging aber auf Kosten vieler Menschenleben. Nach ihrer Zerst\u00f6rung durch die R\u00f6mer \u00fcbernahmen diese das erfolgstr\u00e4chtige Modell, gingen nun aber unaufhaltsam ihrem Zerfall entgegen \u2026 Das New York der [&hellip;]","og_url":"https:\/\/www.siegfriedhagl.com\/ru\/\u044d\u043a\u043e\u043d\u043e\u043c\u0438\u0447\u0435\u0441\u043a\u0438\u0439-\u0438-\u0441\u043e\u0446\u0438\u0430\u043b\u044c\u043d\u044b\u0439\/\u043a\u0430\u0440\u0444\u0430\u0433\u0435\u043d-\u043f\u0435\u0440\u0432\u043e\u0435-\u043a\u0430\u043f\u0438\u0442\u0430\u043b\u0438\u0441\u0442\u0438\u0447\u0435\u0441\u043a\u043e\u0435-\u0433\/","og_site_name":"SiegfriedHagl.com","article_published_time":"2014-03-19T10:20:20+00:00","article_modified_time":"2023-08-04T09:51:02+00:00","author":"siegfriedhagl","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c":"siegfriedhagl","\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"14 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/karthago-der-erste-kapitalistisch-staat\/#article","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/karthago-der-erste-kapitalistisch-staat\/"},"author":{"name":"siegfriedhagl","@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"headline":"Karthago &#8211; der erste kapitalistische Staat ?","datePublished":"2014-03-19T10:20:20+00:00","dateModified":"2023-08-04T09:51:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/karthago-der-erste-kapitalistisch-staat\/"},"wordCount":2616,"publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"articleSection":["Wirtschaft und Soziales"],"inLanguage":"ru-RU"},{"@type":"WebPage","@id":"https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/karthago-der-erste-kapitalistisch-staat\/","url":"https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/karthago-der-erste-kapitalistisch-staat\/","name":"\u041a\u0430\u0440\u0444\u0430\u0433\u0435\u043d - \u043f\u0435\u0440\u0432\u043e\u0435 \u043a\u0430\u043f\u0438\u0442\u0430\u043b\u0438\u0441\u0442\u0438\u0447\u0435\u0441\u043a\u043e\u0435 \u0433\u043e\u0441\u0443\u0434\u0430\u0440\u0441\u0442\u0432\u043e? - SiegfriedHagl.com","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/#website"},"datePublished":"2014-03-19T10:20:20+00:00","dateModified":"2023-08-04T09:51:02+00:00","breadcrumb":{"@id":"https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/karthago-der-erste-kapitalistisch-staat\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/karthago-der-erste-kapitalistisch-staat\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siegfriedhagl.com\/wirtschaft-und-soziales\/karthago-der-erste-kapitalistisch-staat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.siegfriedhagl.com\/"},{"@type":"ListItem","position":2,"name":"Karthago &#8211; der erste kapitalistische Staat ?"}]},{"@type":"WebSite","@id":"https:\/\/www.siegfriedhagl.com\/#website","url":"https:\/\/www.siegfriedhagl.com\/","name":"SiegfriedHagl.com","description":"\u0421\u0442\u0430\u0442\u044c\u044f \u0438 \u0431\u043b\u043e\u0433 \u0417\u0438\u0433\u0444\u0440\u0438\u0434\u0430 \u0425\u0430\u0433\u043b\u044f","publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siegfriedhagl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":["Person","Organization"],"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f","name":"\u0437\u0438\u0433\u0444\u0440\u0438\u0434\u0445\u0430\u0433\u043b\u044c","image":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","caption":"siegfriedhagl"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.hagl.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/2109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/comments?post=2109"}],"version-history":[{"count":18,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/2109\/revisions"}],"predecessor-version":[{"id":10221,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/2109\/revisions\/10221"}],"wp:attachment":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/media?parent=2109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/categories?post=2109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/tags?post=2109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}