{"id":1979,"date":"2013-05-06T10:07:37","date_gmt":"2013-05-06T09:07:37","guid":{"rendered":"https:\/\/www.siegfriedhagl.com\/?page_id=1979"},"modified":"2021-12-23T13:38:39","modified_gmt":"2021-12-23T12:38:39","slug":"das-ende-der-normalitat","status":"publish","type":"post","link":"https:\/\/www.siegfriedhagl.com\/ru\/%d1%80%d0%b5%d1%86%d0%b5%d0%bd%d0%b7%d0%b8%d0%b8-%d0%bd%d0%b0-%d0%ba%d0%bd%d0%b8%d0%b3%d0%b8-%d0%b8-%d1%84%d0%b8%d0%bb%d1%8c%d0%bc%d1%8b\/%d0%ba%d0%be%d0%bd%d0%b5%d1%86-%d0%bd%d0%be%d1%80%d0%bc%d0%b0%d0%bb%d1%8c%d0%bd%d0%be%d1%81%d1%82%d0%b8\/","title":{"rendered":"\u041a\u043e\u043d\u0435\u0446 \u043d\u043e\u0440\u043c\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0438"},"content":{"rendered":"<h4>Nachruf auf unser Leben, wie es bisher war<\/h4>\n<blockquote><p>(Ver\u00f6ffentlicht in Gralswelt 76\/2013)<\/p><\/blockquote>\n<p>Von Gabor Steingart,<br \/>\nPiper, M\u00fcnchen 2012, ISBN 978-3-492-27489-0, 182 Seiten.<\/p>\n<h6><span style=\"font-size: 13px; line-height: 19px;\">Haben sich die Politik, die Wirtschaft, die Umwelt, das Leben, die Welt schon jemals schneller ver\u00e4ndert als in den letzten Jahrzehnten?<\/span><\/h6>\n<p>Heute erst wird uns so recht bewusst, dass die Jahre des sogenannten Kalten Krieges eine stabile, geradezu \u201efriedliche\u201c Zeit waren, zumindest f\u00fcr Europa. Zwar standen sich zwei feindliche Lager drohend gegen\u00fcber, doch Kernwaffen erzwangen ein milit\u00e4risches Patt. Als sich aber die Feindbilder aufl\u00f6sten, und der Weltfriede greifbarer schien als je zuvor, wurde die Welt keineswegs friedlicher, sondern sie wurde komplizierter und un\u00fcbersichtlicher. Pl\u00f6tzlich scheint alles im Wandel, alles wird anders, als es war. Hier einige Stichw\u00f6rter dazu:<\/p>\n<p>Arbeitswelt (Outsourcing und Teilzeitarbeit), Demokratieverst\u00e4ndnis, Familienbild (Alleinerziehende und Patchwork-Familie), Hochfinanz, Medien, Moralvorstellungen, Religi\u00f6se Ethik, Soziale Sicherheit, Staatsvertrauen, Verteidigung (\u201eDeutschland wird auch am Hindukusch verteidigt\u201c<a title=\"\" href=\"file:\/\/\/H:\/Gralswelt%2013\/Das%20Ende%20derNormalit%C3%A4t.doc#_edn1\">[i]<\/a>), Weltmarkt, Wirtschaftsweise, zwischenmenschliche Beziehungen. Man hat es schwer, sich an das uns geradezu \u00fcberschwemmende Neue zu gew\u00f6hnen, mit dem schnellen Paradigmenwechsel mitzuhalten, und neue ethische Ma\u00dfst\u00e4be zu finden, nachdem die alten verloren gingen&#8230;<\/p>\n<p>Gabor Steingart skizziert diese moderne \u201eUmwertung aller Werte\u201c (Nietzsche), den Verlust des Gewohnten, den Untergang von Selbstverst\u00e4ndlichkeiten, in seinem gut lesbaren Buch in einer Reihe von pfiffigen Essays, die den Kern der verwirrenden Vorg\u00e4nge f\u00fcr jedermann in verst\u00e4ndlicher Form herausarbeiten. Wer am Zeitgeschehen interessiert, manchmal davon vielleicht auch verunsichert oder verwirrt ist, sollte dieses fesselnde Buch unbedingt lesen.<\/p>\n<p>Wohin uns der Strom der Geschichte treibt, kann auch Steingart nicht sagen, doch findet er im Abschluss seiner Schrift einen hoffnungsvollen Ausblick:<br \/>\n<em>\u201eWenn keine Macht in uns wirkt, sind wir leer. Das Abschalten aller bisherigen Kraftquellen beschert dem Menschen zwar ein freieres, aber noch kein besseres Leben&#8230;.<br \/>\n<\/em><em>An das Individuum stellt die neue Zeit damit hohe und h\u00f6chste, wom\u00f6glich sogar heroische Anforderungen. Selbstbefragung tritt an die Stelle von Selbstbefriedigung und Selbstbedienung. Selbstbeherrschung ist von allen Herrschaftsformen die schwierigste. Das Ende der Normalit\u00e4t bedeutet eben nicht das Ende der Geschichte, sondern den Beginn einen neuen Zeit. Es wird keine leichte Zeit sein. Aber es k\u00f6nnte unsere gl\u00fccklichste werden.\u201c<\/em><\/p>\n<div>\n<p><strong>Endnote:\u00a0\u00a0<\/strong><br \/>\n<a title=\"\" href=\"file:\/\/\/H:\/Gralswelt%2013\/Das%20Ende%20derNormalit%C3%A4t.doc#_ednref1\">[i]<\/a> Verteidigungsminister Peter Struck im Mai 2003: <em>\u201eDie Sicherheit der Bundesrepublik Deutschland wird auch am Hindukusch verteidigt\u201c.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nachruf auf unser Leben, wie es bisher war (Ver\u00f6ffentlicht in Gralswelt 76\/2013) Von Gabor Steingart, Piper, M\u00fcnchen 2012, ISBN 978-3-492-27489-0, 182 Seiten. Haben sich die Politik, die Wirtschaft, die Umwelt, das Leben, die Welt schon jemals schneller ver\u00e4ndert als in den letzten Jahrzehnten? Heute erst wird uns so recht bewusst, dass die Jahre des sogenannten [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1979","post","type-post","status-publish","format-standard","hentry","category-buch-und-filmbesprechungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das Ende der Normalit\u00e4t &#8211; SiegfriedHagl.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siegfriedhagl.com\/ru\/\u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438-\u043d\u0430-\u043a\u043d\u0438\u0433\u0438-\u0438-\u0444\u0438\u043b\u044c\u043c\u044b\/\u043a\u043e\u043d\u0435\u0446-\u043d\u043e\u0440\u043c\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0438\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das Ende der Normalit\u00e4t &#8211; SiegfriedHagl.com\" \/>\n<meta property=\"og:description\" content=\"Nachruf auf unser Leben, wie es bisher war (Ver\u00f6ffentlicht in Gralswelt 76\/2013) Von Gabor Steingart, Piper, M\u00fcnchen 2012, ISBN 978-3-492-27489-0, 182 Seiten. Haben sich die Politik, die Wirtschaft, die Umwelt, das Leben, die Welt schon jemals schneller ver\u00e4ndert als in den letzten Jahrzehnten? Heute erst wird uns so recht bewusst, dass die Jahre des sogenannten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siegfriedhagl.com\/ru\/\u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438-\u043d\u0430-\u043a\u043d\u0438\u0433\u0438-\u0438-\u0444\u0438\u043b\u044c\u043c\u044b\/\u043a\u043e\u043d\u0435\u0446-\u043d\u043e\u0440\u043c\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0438\/\" \/>\n<meta property=\"og:site_name\" content=\"SiegfriedHagl.com\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-06T09:07:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-23T12:38:39+00:00\" \/>\n<meta name=\"author\" content=\"siegfriedhagl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c\" \/>\n\t<meta name=\"twitter:data1\" content=\"siegfriedhagl\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/buch-und-filmbesprechungen\\\/das-ende-der-normalitat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/buch-und-filmbesprechungen\\\/das-ende-der-normalitat\\\/\"},\"author\":{\"name\":\"siegfriedhagl\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"headline\":\"Das Ende der Normalit\u00e4t\",\"datePublished\":\"2013-05-06T09:07:37+00:00\",\"dateModified\":\"2021-12-23T12:38:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/buch-und-filmbesprechungen\\\/das-ende-der-normalitat\\\/\"},\"wordCount\":389,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"articleSection\":[\"Buch- und Filmbesprechungen\"],\"inLanguage\":\"ru-RU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/buch-und-filmbesprechungen\\\/das-ende-der-normalitat\\\/\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/buch-und-filmbesprechungen\\\/das-ende-der-normalitat\\\/\",\"name\":\"Das Ende der Normalit\u00e4t &#8211; SiegfriedHagl.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\"},\"datePublished\":\"2013-05-06T09:07:37+00:00\",\"dateModified\":\"2021-12-23T12:38:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/buch-und-filmbesprechungen\\\/das-ende-der-normalitat\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siegfriedhagl.com\\\/buch-und-filmbesprechungen\\\/das-ende-der-normalitat\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/buch-und-filmbesprechungen\\\/das-ende-der-normalitat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das Ende der Normalit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\",\"name\":\"SiegfriedHagl.com\",\"description\":\"Artikel und Blog von Siegfried Hagl\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\",\"name\":\"siegfriedhagl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"caption\":\"siegfriedhagl\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.hagl.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041a\u043e\u043d\u0435\u0446 \u043d\u043e\u0440\u043c\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0438 - SiegfriedHagl.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siegfriedhagl.com\/ru\/\u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438-\u043d\u0430-\u043a\u043d\u0438\u0433\u0438-\u0438-\u0444\u0438\u043b\u044c\u043c\u044b\/\u043a\u043e\u043d\u0435\u0446-\u043d\u043e\u0440\u043c\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0438\/","og_locale":"ru_RU","og_type":"article","og_title":"Das Ende der Normalit\u00e4t &#8211; SiegfriedHagl.com","og_description":"Nachruf auf unser Leben, wie es bisher war (Ver\u00f6ffentlicht in Gralswelt 76\/2013) Von Gabor Steingart, Piper, M\u00fcnchen 2012, ISBN 978-3-492-27489-0, 182 Seiten. Haben sich die Politik, die Wirtschaft, die Umwelt, das Leben, die Welt schon jemals schneller ver\u00e4ndert als in den letzten Jahrzehnten? Heute erst wird uns so recht bewusst, dass die Jahre des sogenannten [&hellip;]","og_url":"https:\/\/www.siegfriedhagl.com\/ru\/\u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438-\u043d\u0430-\u043a\u043d\u0438\u0433\u0438-\u0438-\u0444\u0438\u043b\u044c\u043c\u044b\/\u043a\u043e\u043d\u0435\u0446-\u043d\u043e\u0440\u043c\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0438\/","og_site_name":"SiegfriedHagl.com","article_published_time":"2013-05-06T09:07:37+00:00","article_modified_time":"2021-12-23T12:38:39+00:00","author":"siegfriedhagl","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c":"siegfriedhagl","\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"3 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siegfriedhagl.com\/buch-und-filmbesprechungen\/das-ende-der-normalitat\/#article","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/buch-und-filmbesprechungen\/das-ende-der-normalitat\/"},"author":{"name":"siegfriedhagl","@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"headline":"Das Ende der Normalit\u00e4t","datePublished":"2013-05-06T09:07:37+00:00","dateModified":"2021-12-23T12:38:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siegfriedhagl.com\/buch-und-filmbesprechungen\/das-ende-der-normalitat\/"},"wordCount":389,"publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"articleSection":["Buch- und Filmbesprechungen"],"inLanguage":"ru-RU"},{"@type":"WebPage","@id":"https:\/\/www.siegfriedhagl.com\/buch-und-filmbesprechungen\/das-ende-der-normalitat\/","url":"https:\/\/www.siegfriedhagl.com\/buch-und-filmbesprechungen\/das-ende-der-normalitat\/","name":"\u041a\u043e\u043d\u0435\u0446 \u043d\u043e\u0440\u043c\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0438 - SiegfriedHagl.com","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/#website"},"datePublished":"2013-05-06T09:07:37+00:00","dateModified":"2021-12-23T12:38:39+00:00","breadcrumb":{"@id":"https:\/\/www.siegfriedhagl.com\/buch-und-filmbesprechungen\/das-ende-der-normalitat\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siegfriedhagl.com\/buch-und-filmbesprechungen\/das-ende-der-normalitat\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siegfriedhagl.com\/buch-und-filmbesprechungen\/das-ende-der-normalitat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.siegfriedhagl.com\/"},{"@type":"ListItem","position":2,"name":"Das Ende der Normalit\u00e4t"}]},{"@type":"WebSite","@id":"https:\/\/www.siegfriedhagl.com\/#website","url":"https:\/\/www.siegfriedhagl.com\/","name":"SiegfriedHagl.com","description":"\u0421\u0442\u0430\u0442\u044c\u044f \u0438 \u0431\u043b\u043e\u0433 \u0417\u0438\u0433\u0444\u0440\u0438\u0434\u0430 \u0425\u0430\u0433\u043b\u044f","publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siegfriedhagl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":["Person","Organization"],"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f","name":"\u0437\u0438\u0433\u0444\u0440\u0438\u0434\u0445\u0430\u0433\u043b\u044c","image":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","caption":"siegfriedhagl"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.hagl.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/1979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/comments?post=1979"}],"version-history":[{"count":8,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/1979\/revisions"}],"predecessor-version":[{"id":8366,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/posts\/1979\/revisions\/8366"}],"wp:attachment":[{"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/media?parent=1979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/categories?post=1979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/ru\/wp-json\/wp\/v2\/tags?post=1979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}