{"id":4370,"date":"2000-05-10T11:22:00","date_gmt":"2000-05-10T10:22:00","guid":{"rendered":"https:\/\/www.siegfriedhagl.com\/?page_id=4370"},"modified":"2026-01-25T12:26:19","modified_gmt":"2026-01-25T11:26:19","slug":"energie-entropie-und-zeit","status":"publish","type":"post","link":"https:\/\/www.siegfriedhagl.com\/it\/scienza\/energia-entropia-e-tempo\/","title":{"rendered":"energia, entropia e tempo"},"content":{"rendered":"<blockquote>\n<p style=\"text-align: left;\">(Ver\u00f6ffentlicht in GralsWelt Themenheft 5\/2000)<\/p>\n<\/blockquote>\n<p style=\"text-align: left;\"><strong>Mit dem Begriff \u201eEnergie\u201c verkn\u00fcpft sich auch die Frage nach dem Schicksal des Universums. Unserem heutigen physikalischen Weltbild zufolge ist das Ende des Alls unausweichlich: Entweder es \u201estirbt\u201c den sogenannten \u201eentropischen W\u00e4rmetod\u201c oder es beginnt sich irgendwann wieder zusammenzuziehen, wobei sich auch der &#8222;Zeitpfeil&#8220; umkehren, die Zeit also r\u00fcckw\u00e4rts laufen k\u00f6nnte.<a href=\"#_edn1\" name=\"_ednref1\">[i]<\/a>\u00a0<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Wie kam es zu den derzeit g\u00e4ngigen weltanschaulichen Vorstellungen und ist unser All wirklich ein \u201eabgeschlossenes System\u201c? Religi\u00f6se Offenbarungen und auch die Kunde vom \u201eGral\u201c lassen vermuten, dass physikalisch nicht fassbare Energien wesentlichen Anteil am Weltgeschehen haben.\u00a0<\/strong><\/p>\n<p>Seit Menschen \u00fcber sich und die Welt nachdenken, besch\u00e4ftigt sie auch der Begriff der Zeit.<\/p>\n<p>In der Antike beobachtete man den Lauf der Gestirne, den Wechsel von Tag und Nacht und den Zyklus der Jahreszeiten. Daraus entstand die Vorstellung von der fortlaufenden Wiederkehr des Gleichen. Hineingestellt in diesen immerw\u00e4hrenden Wechsel war der Mensch, dessen Leben sehr kurz scheint.<\/p>\n<p>Diese L\u00fccke schloss die Lehre von der Reinkarnation, die nicht nur seit mindestens 500 v. Chr. in Indien, sondern auch von <em>Platon<\/em> (427-347 v.Chr.) und <em>Aristoteles<\/em> (384-322 v.Chr.) in Griechenland vertreten wurde. Diese konnte den Menschen mit seinem zeitlich begrenzten irdischen Leben vers\u00f6hnen, indem sie weitere Existenzen auf Erden und im Jenseits postulierte.<\/p>\n<p>Einen anderen Ansatz lieferte die Bibel. In der Genesis (dem erst en Buch Mose) beginnt alles mit einem Sch\u00f6pferakt, hat also einen Anfang. Und wo es einen Anfang gibt, da ist nach aller menschlichen Erfahrung auch ein Ende zu erwarten. Dies ist ein Thema, das alttestamentliche Propheten besch\u00e4ftigt, in den Evangelien breiten Raum einnimmt und seinen eindeutigen Ausdruck im letzten Buch des Neuen Testamentes, der Apokalypse des Johannes, findet.<\/p>\n<p><strong>Vom Ende der Zeit<\/strong><\/p>\n<p>Die Betrachtungen zum \u201eEnde der Zeit\u201c blieben Vermutungen, ergaben religi\u00f6se Lehren oder philosophische Spekulationen. Beobachtbare Tatsache blieb indes der st\u00e4ndige Wechsel oder der Kreislauf:<\/p>\n<p><em>\u201eSolange die Erde steht, soll nicht aufh\u00f6ren Saat und Ernte, Frost und Hitze, Sommer und Winter, Tag und Nacht.\u201c <\/em>(1. Mose, 8, 22<em>). <\/em><\/p>\n<p>Auch die Wissenschaft der Neuzeit wusste zun\u00e4chst wenig zum R\u00e4tsel der Zeit beizutragen, die sich ja allein aus der <em>Verschiedenheit <\/em>der aufeinanderfolgenden Augenblicke ergibt und daraus ermitteln l\u00e4sst.<\/p>\n<p><em>Isaak Newton <\/em>(1643-1727) arbeitete mit einem abstrakten Zeitbegriff, mit dem die Physiker bis ins 20. Jahrhundert zurechtkamen:<\/p>\n<p><em>\u201eDie absolute, wahre und mathematische Zeit verflie\u00dft an sich und verm\u00f6ge ihrer Natur gleichf\u00f6rmig und ohne Beziehung auf irgendeinen \u00e4u\u00dferen Gegenstand.\u201c<\/em><\/p>\n<p>Doch warum die Zeit nur in einer Richtung l\u00e4uft, warum die Vergangenheit mit keinem Mittel wiederherzustellen ist, konnte auch der gro\u00dfe <em>Newton <\/em>nicht sagen.<\/p>\n<p><strong>Thermodynamik und \u201eEnergieerhaltung\u201c<\/strong><\/p>\n<p>Im Zeitalter der Romantik kam ab 1865 von unerwarteter Seite \u00fcberraschend ein ganz neuer Beitrag zum Verst\u00e4ndnis der Zeit: Das Neue kam von der Thermodynamik, die sich mit der W\u00e4rme als Energieform befasst, und zun\u00e4chst dem Anschein nach wenig mit dem philosophischen Zeitverst\u00e4ndnis zu tun hat.<\/p>\n<p>In dieser W\u00e4rmelehre gibt es zwei grundlegende Aussagen, die man den ersten und zweiten \u201eHauptsatz der Thermodynamik\u201c nennt.<\/p>\n<p>Der \u201eErste Hauptsatz der Thermodynamik\u201c lautet: <em>\u201eW\u00e4rme ist eine Energieform. Sie kann aus mechanischer Arbeit erzeugt und in mechanische Arbeit umgewandelt werden.\u201c <\/em><\/p>\n<p>Daraus folgt, dass die W\u00e4rmeenergie weder unmittelbar aus dem \u201eNichts\u201c entstehen, noch ins \u201eNichts\u201c verschwinden kann, sondern als Energie erkannt wurde. Zum Beispiel geht ein Teil der Sonnenmaterie in Energie \u00fcber, wenn die Sonne bei ihrer Kernfusion ihre unvorstellbaren Energien ins All abstrahlt.<\/p>\n<p>Die Energieerzeugung aus dem Nichts \u2013 meist Perpetuum mobile genannt \u2013 erscheint dagegen unm\u00f6glich. Allenfalls w\u00e4re die Entdeckung bisher unbekannter Energiequellen denkbar. \u2013<\/p>\n<p>Der \u201eZweite Hauptsatz der Thermodynamik\u201c lautet: <em>\u201eW\u00e4rme kann nur von einem K\u00f6rper h\u00f6herer Temperatur auf einen K\u00f6rper niedrigerer Temperatur \u00fcbergehen, jedoch nicht umgekehrt.\u201c<\/em><\/p>\n<p>Mit diesem zweiten Hauptsatz erhalten wir eine Rangordnung der Energien. Man kann ihm ja entnehmen, dass eine W\u00e4rmemenge bei h\u00f6herer Temperatur gr\u00f6\u00dferen Wert hat als dieselbe W\u00e4rmemenge bei niedrigerer Temperatur.\u00a0 Ebenso bekommen verschiedene Energiearten unterschiedliche Wertigkeit, da man die \u201eh\u00f6here\u201c Energieform verlustfrei in eine niedrigere Energieform umwandeln kann, der umgekehrte Weg jedoch versperrt ist.<\/p>\n<p>So wird mechanische Energie durch Reibung zu W\u00e4rme. Diese Reibungsw\u00e4rme l\u00e4sst sich aber nicht mehr verlustfrei in mechanische Energie zur\u00fcck verwandeln, denn aus der \u201egeordneten Bewegung\u201c der mechanischen Energie ist W\u00e4rme, ein \u201eungeordnetes Molek\u00fclgewackel\u201c geworden, das sich nicht einfach wieder ordnen l\u00e4sst. Ein praktisches Beispiel liefert jedes Auto: Beim Bremsen wird die mechanische Energie der Bewegung in W\u00e4rme umgesetzt (die Bremsen werden hei\u00df!). Diese W\u00e4rme l\u00e4sst sich anschlie\u00dfend nicht wieder zum Beschleunigen des Fahrzeuges einsetzen.<\/p>\n<p>Die beiden Haupts\u00e4tze der Thermodynamik sind \u00fcbrigens Erfahrungss\u00e4tze, die nur f\u00fcr \u201eabgeschlossene Systeme\u201c gelten und sich nicht beweisen lassen. Es gibt daher immer wieder Zweifel an ihrer universellen G\u00fcltigkeit, und bis heute werden Erfindungen vorgetragen, die gegen diese Haupts\u00e4tze versto\u00dfen und daher auch nicht als patenf\u00e4hig gelten.<\/p>\n<p>Da sich Wissenschaftler nicht mit solchen Ideen besch\u00e4ftigen, werden sie in der Regel auch nicht genauer durchgepr\u00fcft, was Erfinder gelegentlich zur Verzweiflung treiben kann.<\/p>\n<p><strong>Entropie und \u201eW\u00e4rmetod\u201c<\/strong><\/p>\n<p>Um nun einen Namen und ein Ma\u00df f\u00fcr diese bei jeder Energieumwandlung auftretenden Verluste zu finden \u2013 f\u00fcr diese \u201cUnordnung\u201c, die nach physikalischer Auffassung laufend zunehmen muss \u2013, wurde der Begriff \u201cEntropie\u201c eingef\u00fchrt. Es handelt sich um eine nur mathematisch zu beschreibende Gr\u00f6\u00dfe, die nicht direkt gemessen werden kann und die auch dem Verst\u00e4ndnis nicht sofort zug\u00e4nglich ist.<\/p>\n<p>Eine humoristische Erkl\u00e4rung f\u00fcr diesen Begriff wird <em>Werner\u00a0Heisenberg<\/em>\u00a0(1901-1976) zugeschrieben, der gesagt haben soll, dass man das Wesen der Entropie daran erkennen k\u00f6nne, dass auf seinem Schreibtisch immer \u201evon selbst\u201c Unordnung entst\u00fcnde.<\/p>\n<p>Mit der Entropie ist praktischerweise ein Unterschied zwischen Vergangenheit und Zukunft physikalisch definierbar: Gestern war die Entropie niedriger als heute, und morgen wird sie gr\u00f6\u00dfer als heute sein. Die Vergangenheit \u2013 der vorherige Zustand \u2013 l\u00e4sst sich mit keinem Mittel der Physik wieder herstellen.<\/p>\n<p>Wendet man die Vorstellung der unaufhaltsam zunehmenden Unordnung, deren Ma\u00df die Entropie ist, auf das Weltall an, so ergibt sich folgender Gedanke: Energien sind \u2013 zum Beispiel in Form von W\u00e4rme \u2013 im All ungleichm\u00e4\u00dfig verteilt. Man denke nur an die hei\u00dfe Sonne und die Eisesk\u00e4lte zwischen den Sternen.<\/p>\n<p>Alles organische Leben beruht auf physikalischen, chemischen, biologischen Prozessen, die sich in einer Hinsicht alle gleichen: Sie ben\u00f6tigen Energie, die sie nur dadurch erhalten k\u00f6nnen, dass Energie von einem h\u00f6heren Niveau zu einem niedrigeren flie\u00dft (\u201eZweiter Hauptsatz\u201c). Ob ein Dachziegel zu Boden f\u00e4llt, ob das Sonnenlicht den Erdball erw\u00e4rmt oder ob ein Fluss ein Wasserrad treibt, immer wandelt sich Energie von \u201eh\u00f6herem Niveau\u201c in Energie \u201eniedrigeren Niveaus\u201c.<\/p>\n<p>Alle diese Energieumsetzungen sind nur m\u00f6glich, weil es Niveau-Unterschiede gibt, welche die Tendenz haben, sich auszugleichen. Wasser flie\u00dft den Berg nur hinunter, W\u00e4rme flutet nur vom hei\u00dfen Ofen zur k\u00e4lteren Umgebung, und kein K\u00f6rper erhitzt sich dadurch, dass er seiner k\u00fchleren Umgebung W\u00e4rme entzieht.<\/p>\n<p>Wo es jedoch keine Unterschiede im Energieniveau mehr gibt, h\u00f6rt jeder Energiefluss und damit alles organische Leben auf!<\/p>\n<p>Weil nun \u00fcberall die Tendenz besteht, dass sich Unterschiede im Energieniveau ausgleichen wollen, so kann es nur eine Frage der Zeit sein, bis sich alle Energie im ganzen Weltall gleichm\u00e4\u00dfig verteilt hat.<\/p>\n<p>Die Sonnen werden dann ausgebrannt sein, jeder Himmelsk\u00f6rper kann nur so lange W\u00e4rme abstrahlen, bis er die gleiche Temperatur wie seine Umgebung erreicht hat, bis alles \u201egleich warm\u201c ist, also das selbe Energieniveau erreicht hat. Dann ist alles Leben zu Ende, alle chemischen Reaktionen h\u00f6ren auf.<\/p>\n<p>Was bleibt, sind nur mechanische Bewegungen der Planeten um ihre erkalteten Sonnen, bis schlie\u00dflich \u2013 abgebremst durch auch im Weltraum nicht v\u00f6llig fehlende Reibungswiderst\u00e4nde \u2013 die letzten Planeten auf ihr Zentralgestirn st\u00fcrzen.<\/p>\n<p>Der \u201eW\u00e4rmetod\u201c \u2013 die gleichf\u00f6rmige Verteilung aller Energie im All \u2013 w\u00e4re demnach das unausweichlich vorprogrammierte Ende des Universums, dem es entgegeneilt.<\/p>\n<p>Was immer wir tun, ob wir arbeiten oder schlafen, wir vermehren die \u201eUnordnung\u201c, also die Entropie des Weltalls, und jedes Ereignis, von der Atmung des Menschen bis zum Absturz eines Himmelsk\u00f6rpers oder der Explosion einer Sonne, l\u00e4sst die Entropie anwachsen, die ihrem Maximum zustrebt, dem \u201eW\u00e4rmetod\u201c des Universums.<\/p>\n<p><strong>Sind Lebewesen \u201eanentropisch\u201c?<\/strong><\/p>\n<p>Lebewesen bestehen aus hoch komplizierten, also im Sinn der Thermodynamik h\u00f6chst \u201eunwahrscheinlichen\u201c Strukturen, die dem Entropieprinzip scheinbar widersprechen. Zum Beispiel ist das kleinste Bakterium, das vielleicht nur Minuten leben wird, komplizierter als jedes Werk menschlicher Technik.<\/p>\n<p>Doch der zweite Hauptsatz widerspricht keineswegs dem Aufbau hochentwickelter Lebewesen, m\u00f6gen diese, thermodynamisch gesehen, noch so unwahrscheinlich sein. Dieses Prinzip sagt nur, dass in einem <em>abgeschlossenen<\/em> System die Entropie stets zunehmen muss.<\/p>\n<p>Unsere Erde zum Beispiel ist gar kein abgeschlossenes System. Sie ist ein <em>offenes<\/em> System, eingebunden in den Energiefluss Sonne \u2013 Erde \u2013 Weltraum, der Leben auf unserem Planeten m\u00f6glich macht. Mag auch die Entropie durch die Entwicklung von Pflanzen und Tieren auf Erden \u00f6rtlich abnehmen, gleichzeitig nimmt die Entropie der Sonne zu. Die Existenz von organischem Leben, das h\u00f6here Strukturen aus einfachen erzeugt, widerspricht nicht dem Entropiesatz im Ganzen.<\/p>\n<p><strong>Vom Lauf der Zeit<\/strong><\/p>\n<p>Unser menschlies Bewusstsein ist von dem \u201ethermodynamischen Zeitpfeil\u201c gepr\u00e4gt: Gestern war fr\u00fcher als heute, und vom Morgen wissen wir nichts. Die Forderung des Entropiesatzes, dass Zeit nur in einer Richtung l\u00e4uft, erscheint selbstverst\u00e4ndlich, denn noch nie hat jemand eine \u201er\u00fcckl\u00e4ufige Zeit\u201c beobachten k\u00f6nnen.<\/p>\n<p>Wissenschaftlich belegen l\u00e4sst sich diese Selbstverst\u00e4ndlichkeit nicht, und die moderne Physik kann nicht ausschlie\u00dfen, dass sich der Zeitpfeil auch umdrehen k\u00f6nnte.<\/p>\n<p>Der Physiker <em>Stephen W. Hawking <\/em>(1942-2018) hat aus diesem Dilemma einen Ausweg gefunden, indem er den Zeitpfeil mit der Expansion des Alls in Verbindung brachte. Unser Universum dehnt sich ja aus, und w\u00e4hrend dieser Expansion muss der Zeitpfeil in die bekannte Richtung laufen.<\/p>\n<p>Sollte dereinst diese Expansion zum Stillstand kommen, und dann das All erst langsam, dann immer schneller in sich zusammenst\u00fcrzen, dann k\u00f6nnte sich der Zeitpfeil umkehren und die Zeit w\u00fcrde r\u00fcckw\u00e4rts laufen. Unter diesen Bedingungen w\u00e4re allerdings pflanzliches, tierisches, menschliches Leben l\u00e4ngst nicht mehr m\u00f6glich. Alle Spekulationen, wie die Physik in r\u00fcckl\u00e4ufiger Zeit aussehen mag, er\u00fcbrigen sich, denn erleben wird diese Epoche niemand.<\/p>\n<p>Das Ende des Universums und damit allen physischen Lebens erscheint also unausweichlich, egal, ob es sich durch den entropischen W\u00e4rmetod ereignet oder durch die Umkehrung des Zeitpfeiles in der Kontraktionsphase des Alls.<\/p>\n<p>Neuerdings geht man davon aus, dass sich die Ausdehnung des Universums aufgrund einer r\u00e4tselhafte &#8222;dunklen Energie&#8220; laufend beschleunigt. Der W\u00e4rmetod w\u00e4re ihm dann sicher!<\/p>\n<p><strong>Ist unsere Welt ein abgeschlossenes System?<\/strong><\/p>\n<p>In zur\u00fcckliegenden Jahrtausenden galten \u201eEingriffe von oben\u201c als Tatsache. G\u00f6tter der Alten Griechen griffen aktiv in Kriege ein, Propheten warnten vor der \u201eStrafe Gotte\u201c, und selbst in unserer Zeit wird das \u201eWirken Gottes in der Geschichte\u201c gesucht. (Vor kurzem h\u00f6rte ich von einem Professor der Theologie, dass die Wiedervereinigung Deutschlands nur als Folge eines g\u00f6ttlichen Eingriffs m\u00f6glich war).<\/p>\n<p>In der historischen Forschung ist sp\u00e4testens seit <em>David Friedrich Strau\u00df <\/em>(1808-1874) sein damals h\u00f6chst umstrittenes Werk \u201eDas Leben Jesu\u201c (1835) publizierte, der Gedanke an direkte g\u00f6ttliche Eingriffe ausgeklammert.<\/p>\n<p>Doch das menschliche Gem\u00fct str\u00e4ubt sich gegen die Behauptung, dass unsere Welt unausweichlich im Chaos und im W\u00e4rmetod enden muss. Unbewusst weigert man sich, das Universum als \u201eabgeschlossenes System\u201c zu akzeptieren, das, den physikalischen Naturgesetzen \u00fcberlassen, auf keinerlei Hilfe hoffen darf.<\/p>\n<p>Keine Religion kann sich mit dieser \u201evon Gott verlassenen Welt\u201c abfinden; jeder religi\u00f6se Mensch sucht Kontakt nach oben, erfleht weiterf\u00fchrende Einsichten, die ihm das Weltbild der Physik nicht bieten kann.<\/p>\n<p>Hoffnung verhei\u00dft eine alte \u00dcberlieferung: die sagenhafte Kunde vom Gral.<\/p>\n<p>In vielf\u00e4ltiger Form wird von der Wunderkraft dieses Gef\u00e4\u00dfes berichtet. Dieses gilt als ein \u201eKraftvermittler\u201c zwischen dem Sch\u00f6pfer und seiner Sch\u00f6pfung. Gott hat seine Gesch\u00f6pfe nicht im Stich gelassen. Er hat nicht nur vollkommene Gesetze in seinem Werk verankert, sondern f\u00fchrt ihm auch erhaltende Kr\u00e4fte zu. Diese heilige Kraft erh\u00e4lt und f\u00f6rdert alle Welten, und niemand muss sich von Gott verlassen f\u00fchlen. \u2013<\/p>\n<p>Wer will, kann noch weitere Folgerungen daraus ziehen. Die Kraft (ein Physiker w\u00fcrde von \u201eEnergie\u201c sprechen) aus dem Heiligen Gral wirkt dann auch \u201eanentropisch\u201c, sie reduziert die \u201eUnordnung\u201c in der Sch\u00f6pfung. Unsere Welt ist demnach auch gar kein \u201eabgeschlossenes System\u201c, denn es flie\u00dft ihr st\u00e4ndig von au\u00dfen geistige Energie zu, die dann letztlich auch irdisch wirksam wird. Damit muss \u201edie Welt\u201c nicht unausweichlich, der vollen H\u00e4rte des Entropiesatzes ausgeliefert, dem Chaos entgegeneilen.<\/p>\n<p>Der Sch\u00f6pfer selbst, der ununterbrochen Kraft abgeben kann, steht weit \u00fcber den Prinzipien, die die Thermodynamik formuliert hat. Es ist kaum ein Zufall, dass die beiden Haupts\u00e4tze durch Beobachtung auf Erden gefunden, aber nie bewiesen wurden: Vermutlich gelten sie nur im irdischen Raum und in der irdischen Zeit und verlieren an Einfluss in h\u00f6heren, in geistigen oder gar in g\u00f6ttliche Ebenen.<\/p>\n<p>Auch der Mensch als ein unsterbliches Geistwesen darf hoffen, sich aus dem Kreislauf des Irdischen, aus Werden und Vergehen, aus Geburt und Wiedergeburt heraus zu entwickeln zu der von allen Religionen verhei\u00dfen Daseinsform auf lichteren H\u00f6hen, wo andere Zeitbegriffe herrschen \u2013 und folglich auch der Entropiesatz nicht gelten muss.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Ver\u00f6ffentlicht in GralsWelt Themenheft 5\/2000) Mit dem Begriff \u201eEnergie\u201c verkn\u00fcpft sich auch die Frage nach dem Schicksal des Universums. Unserem heutigen physikalischen Weltbild zufolge ist das Ende des Alls unausweichlich: Entweder es \u201estirbt\u201c den sogenannten \u201eentropischen W\u00e4rmetod\u201c oder es beginnt sich irgendwann wieder zusammenzuziehen, wobei sich auch der &#8222;Zeitpfeil&#8220; umkehren, die Zeit also r\u00fcckw\u00e4rts laufen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-4370","post","type-post","status-publish","format-standard","hentry","category-wissenschaft"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energie, Entropie und Zeit &#8211; SiegfriedHagl.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siegfriedhagl.com\/it\/scienza\/energia-entropia-e-tempo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energie, Entropie und Zeit &#8211; SiegfriedHagl.com\" \/>\n<meta property=\"og:description\" content=\"(Ver\u00f6ffentlicht in GralsWelt Themenheft 5\/2000) Mit dem Begriff \u201eEnergie\u201c verkn\u00fcpft sich auch die Frage nach dem Schicksal des Universums. Unserem heutigen physikalischen Weltbild zufolge ist das Ende des Alls unausweichlich: Entweder es \u201estirbt\u201c den sogenannten \u201eentropischen W\u00e4rmetod\u201c oder es beginnt sich irgendwann wieder zusammenzuziehen, wobei sich auch der &#8222;Zeitpfeil&#8220; umkehren, die Zeit also r\u00fcckw\u00e4rts laufen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siegfriedhagl.com\/it\/scienza\/energia-entropia-e-tempo\/\" \/>\n<meta property=\"og:site_name\" content=\"SiegfriedHagl.com\" \/>\n<meta property=\"article:published_time\" content=\"2000-05-10T10:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-25T11:26:19+00:00\" \/>\n<meta name=\"author\" content=\"siegfriedhagl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"siegfriedhagl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/energie-entropie-und-zeit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/energie-entropie-und-zeit\\\/\"},\"author\":{\"name\":\"siegfriedhagl\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"headline\":\"Energie, Entropie und Zeit\",\"datePublished\":\"2000-05-10T10:22:00+00:00\",\"dateModified\":\"2026-01-25T11:26:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/energie-entropie-und-zeit\\\/\"},\"wordCount\":2235,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"articleSection\":[\"Wissenschaft\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/energie-entropie-und-zeit\\\/\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/energie-entropie-und-zeit\\\/\",\"name\":\"Energie, Entropie und Zeit &#8211; SiegfriedHagl.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\"},\"datePublished\":\"2000-05-10T10:22:00+00:00\",\"dateModified\":\"2026-01-25T11:26:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/energie-entropie-und-zeit\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/energie-entropie-und-zeit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/energie-entropie-und-zeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energie, Entropie und Zeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\",\"name\":\"SiegfriedHagl.com\",\"description\":\"Artikel und Blog von Siegfried Hagl\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\",\"name\":\"siegfriedhagl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"caption\":\"siegfriedhagl\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.hagl.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energia, entropia e tempo - SiegfriedHagl.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siegfriedhagl.com\/it\/scienza\/energia-entropia-e-tempo\/","og_locale":"it_IT","og_type":"article","og_title":"Energie, Entropie und Zeit &#8211; SiegfriedHagl.com","og_description":"(Ver\u00f6ffentlicht in GralsWelt Themenheft 5\/2000) Mit dem Begriff \u201eEnergie\u201c verkn\u00fcpft sich auch die Frage nach dem Schicksal des Universums. Unserem heutigen physikalischen Weltbild zufolge ist das Ende des Alls unausweichlich: Entweder es \u201estirbt\u201c den sogenannten \u201eentropischen W\u00e4rmetod\u201c oder es beginnt sich irgendwann wieder zusammenzuziehen, wobei sich auch der &#8222;Zeitpfeil&#8220; umkehren, die Zeit also r\u00fcckw\u00e4rts laufen [&hellip;]","og_url":"https:\/\/www.siegfriedhagl.com\/it\/scienza\/energia-entropia-e-tempo\/","og_site_name":"SiegfriedHagl.com","article_published_time":"2000-05-10T10:22:00+00:00","article_modified_time":"2026-01-25T11:26:19+00:00","author":"siegfriedhagl","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"siegfriedhagl","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/energie-entropie-und-zeit\/#article","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/energie-entropie-und-zeit\/"},"author":{"name":"siegfriedhagl","@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"headline":"Energie, Entropie und Zeit","datePublished":"2000-05-10T10:22:00+00:00","dateModified":"2026-01-25T11:26:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/energie-entropie-und-zeit\/"},"wordCount":2235,"publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"articleSection":["Wissenschaft"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/energie-entropie-und-zeit\/","url":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/energie-entropie-und-zeit\/","name":"Energia, entropia e tempo - SiegfriedHagl.com","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/#website"},"datePublished":"2000-05-10T10:22:00+00:00","dateModified":"2026-01-25T11:26:19+00:00","breadcrumb":{"@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/energie-entropie-und-zeit\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siegfriedhagl.com\/wissenschaft\/energie-entropie-und-zeit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/energie-entropie-und-zeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.siegfriedhagl.com\/"},{"@type":"ListItem","position":2,"name":"Energie, Entropie und Zeit"}]},{"@type":"WebSite","@id":"https:\/\/www.siegfriedhagl.com\/#website","url":"https:\/\/www.siegfriedhagl.com\/","name":"SiegfriedHagl.com","description":"Articolo e blog di Siegfried Hagl","publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siegfriedhagl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f","name":"siegfriedhagl","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","caption":"siegfriedhagl"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.hagl.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts\/4370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/comments?post=4370"}],"version-history":[{"count":14,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts\/4370\/revisions"}],"predecessor-version":[{"id":12139,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts\/4370\/revisions\/12139"}],"wp:attachment":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/media?parent=4370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/categories?post=4370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/tags?post=4370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}