{"id":244,"date":"2009-03-25T17:49:45","date_gmt":"2009-03-25T16:49:45","guid":{"rendered":"https:\/\/www.siegfriedhagl.com\/?page_id=244"},"modified":"2024-04-24T10:00:23","modified_gmt":"2024-04-24T09:00:23","slug":"der-urknall-als-gottesbeweis","status":"publish","type":"post","link":"https:\/\/www.siegfriedhagl.com\/it\/scienza\/il-big-bang-come-prova-di-dio\/","title":{"rendered":"Il Big Bang come prova di Dio"},"content":{"rendered":"<blockquote><p>(Pubblicato su GralsWelt 32\/2004)<\/p><\/blockquote>\n<p>Il mondo \u00e8 pieno di meraviglie, grandi e piccole.<br \/>\nUno di questi miracoli - qualcosa che non possiamo spiegare - \u00e8 la raffinata interazione, il coordinamento esattamente equilibrato delle leggi della natura. Questi dovevano essere esattamente gli stessi, in nessun caso potevano essere leggermente diversi, in modo che soli, pianeti, piante, animali, persone potessero sorgere nel nostro universo.<\/p>\n<p>Se chiediamo il perch\u00e9 delle cose, ci sono diversi modi per cercare le risposte:<\/p>\n<blockquote><p><em>&quot;Lo spirito di Dio sono le leggi della natura&quot;.<\/em><br \/>\nStephen Hawking<\/p><\/blockquote>\n<p>il <strong>teologi<\/strong> \u00e8 facile: la tua domanda \u00e8 &quot;Perch\u00e9 c&#039;\u00e8 qualcosa?&quot;. E la risposta \u00e8: &quot;Perch\u00e9 Dio ha deciso che qualcosa dovrebbe essere!&quot;<br \/>\nIn questo modo i teologi evitano di rispondere alle domande perch\u00e9 sanno che non ci pu\u00f2 essere risposta a domande cos\u00ec fondamentali da un punto di vista umano, nella migliore delle ipotesi informazione attraverso la rivelazione.<\/p>\n<p><strong>naturalista<\/strong> renderlo pi\u00f9 difficile. Riconoscono che \u00e8 inutile chiedere &quot;perch\u00e9&quot;, ma invece chiedono &quot;quando&quot;, &quot;dove&quot;, &quot;come&quot; e cercano spiegazioni plausibili. \u00c8 stato dimostrato che, ad esempio, l&#039;astrofisica non pu\u00f2 n\u00e9 provare n\u00e9 confutare l&#039;esistenza del Creatore, ma che il concetto di Dio \u00e8 compatibile con le scoperte della fisica moderna.<\/p>\n<p><strong>Forze che governano il mondo<br \/>\n<\/strong>Quattro forze fondamentali (secondo le conoscenze attuali) tengono insieme il mondo materiale:<br \/>\n* La forte interazione lega insieme gli elementi costitutivi principali. Il loro raggio d&#039;azione \u00e8 molto breve, il loro potere enorme.<br \/>\n* La debole interazione con un range estremamente corto, che \u00e8 di particolare importanza per le particelle subatomiche (es. quark, neutrini, leptoni). \u00c8 difficile da dimostrare perch\u00e9 \u00e8 coperto dall&#039;interazione forte ed elettromagnetica.<br \/>\n* L&#039;interazione elettromagnetica, che \u00e8 importante per le particelle cariche. La loro portata \u00e8 teoricamente infinita, ma il loro effetto a lunga distanza viene presto schermato da altre particelle cariche.<br \/>\n* A prima vista, solo una debole gravitazione con portata (teoricamente) infinita, che tiene insieme i corpi celesti e li costringe sulle loro orbite.<\/p>\n<p>Un universo che deve produrre vita e coscienza dipende da una messa a punto inimmaginabilmente precisa di queste forze fondamentali. Se le forze della natura, o carica, o la massa dei mattoni nucleari fossero solo leggermente differenti, l&#039;universo come lo conosciamo non esisterebbe:<\/p>\n<p>Una gravitazione leggermente maggiore, ad esempio, avrebbe rallentato troppo l&#039;espansione dell&#039;universo e tutta la materia sarebbe sprofondata in un buco nero molto tempo fa. Tuttavia, una gravit\u00e0 leggermente inferiore avrebbe impedito la formazione di stelle con sistemi planetari, poich\u00e9 tutta la materia sarebbe fuggita nello spazio troppo rapidamente.<\/p>\n<p>Dall&#039;inizio dell&#039;universo, anche nel &quot;big bang&quot; (big bang), la coordinazione di forze, masse e cariche \u00e8 stata cos\u00ec fine che gli scienziati paragonano questo equilibrio a una matita in equilibrio sulla punta. Prendendo ad esempio la gravitazione, sarebbe bastato uno scostamento di un millesimo di miliardesimo (= un trilionesimo) dal valore reale e sarebbe emerso un cosmo completamente diverso (5).<\/p>\n<p>Ci sono innumerevoli altri &quot;miracoli&quot; sulla via dell&#039;origine della vita (6); es. la formazione degli atomi di carbonio fondamentali per tutta la vita all&#039;interno dei soli.<\/p>\n<p>Il ricercatore di questa fusione nucleare, Sir Fred Hoyle (1915-2001) disse:<\/p>\n<p><em>&quot;Niente ha scosso il mio ateismo come questa scoperta&quot;<\/em> (5).<\/p>\n<p>Visto in questo modo, il tanto citato \u201cbig bang\u201d non \u00e8 un termine felice; le leggi della natura, che erano gi\u00e0 finemente sintonizzate nel Big Bang, parlano pi\u00f9 di termini come &quot;accordo primordiale&quot; o &quot;armonia primordiale&quot;.<\/p>\n<p><strong>Il principio antropico<\/strong><br \/>\nDai primi secondi della formazione dell&#039;universo fino ad oggi ci sono stati e sono innumerevoli gli eventi che dovevano svolgersi in un modo molto specifico affinch\u00e9 potessero finalmente sorgere esseri che pensassero alla loro esistenza e al suo significato.<\/p>\n<p>Quindi la selezione estremamente precisa delle leggi della natura non \u00e8 un caso, ma un&#039;espressione della volont\u00e0 del creatore? Forse anche una &quot;prova di Dio&quot; fisica?<\/p>\n<p>Perch\u00e9 secondo le ultime scoperte scientifiche, l&#039;universo sembra quasi &quot;costruito&quot;, cio\u00e8 propositivo, seguendo un piano di creazione.<\/p>\n<p>Sarebbe l&#039;opposto del &quot;gioco d&#039;azzardo&quot; altrimenti dato per scontato nelle scienze naturali, che rifiuta tutte le influenze teleologiche (mirate) sullo sviluppo naturale.<\/p>\n<p>I fisici sono riluttanti ad assumere una visione antropocentrica (incentrata sull&#039;uomo) che suggerisce gli esseri umani &quot;come l&#039;obiettivo dell&#039;universo&quot;, ma discutono del principio antropico, che riconosce alcuni prerequisiti necessari affinch\u00e9 la vita, in particolare la vita intelligente, diventi possibile.<\/p>\n<p>Il <strong>principio antropico debole<\/strong> dice che il nostro universo \u00e8 tale che possono essere prodotti osservatori (esseri pensanti) (4). I sostenitori di questo principio sono dell&#039;opinione, ad esempio, che ci possa essere un numero qualsiasi di universi. Se le costanti naturali in un universo sono diverse da quelle dell&#039;unico a noi accessibile, allora non c&#039;\u00e8 vita l\u00ec, n\u00e9 persone, n\u00e9 nessuno che possa pensare a questo mondo. Nel nostro universo, le condizioni sono (per caso?) esattamente tali che potrebbero svilupparsi esseri pensanti e meditabondi.<\/p>\n<p>Alla domanda &quot;perch\u00e9 il nostro cosmo \u00e8 cos\u00ec e non diverso&quot; c&#039;\u00e8 una risposta semplice: &quot;perch\u00e9 altrimenti non esisteremmo&quot;, in cui si pu\u00f2 vedere anche un argomento circolare:<\/p>\n<p><em>&quot;Perch\u00e9 noi esistiamo, il cosmo deve essere cos\u00ec com&#039;\u00e8...&quot;<\/em><\/p>\n<p>Il <strong>forte principio antropico<\/strong> afferma che condizioni molto specifiche hanno permesso alla storia dell&#039;universo di svolgersi esattamente come la conosciamo, in modo che la vita superiore potesse (inevitabilmente) emergere (4).<\/p>\n<p>Di conseguenza, il cosmo sarebbe basato su un principio di costruzione. Perch\u00e9 anche la minima deviazione dell&#039;una o dell&#039;altra costante naturale avrebbe creato un universo fondamentalmente diverso che \u00e8 oltre la nostra immaginazione e in cui non potrebbe esserci vita autocosciente.<\/p>\n<p>Rimane aperta la questione di chi abbia coordinato tra loro le forze naturali e le costanti naturali in modo cos\u00ec preciso, perch\u00e9 questa \u00e8 una questione religiosa, non scientifica.<\/p>\n<blockquote><p><em>\u201cPossiamo concepire l&#039;universo come un messaggio codificato in un codice segreto, una specie di geroglifico cosmico che stiamo appena iniziando a decifrare. Chi ha scritto questo messaggio? Se l&#039;enigma di questo codice cosmico ci \u00e8 stato imposto dal suo creatore, i nostri sforzi per decifrarlo non sono forse una sorta di schema, qualcosa come uno specchio sempre pi\u00f9 chiaro, in cui l&#039;autore del messaggio rinnova la conoscenza che ha di se stesso?&quot;<\/em><br \/>\nJean Guitton, francese filosofo (cfr. 5)<\/p>\n<p><em>\u201cLee Smolin ha calcolato la probabilit\u00e0 che il nostro universo esistesse, supponendo che le costanti naturali possano essere scelte pi\u00f9 o meno liberamente, e ha ottenuto il valore follemente piccolo di 1:10 alla potenza di 229. Prima di immaginare questo numero ho suggerisco di iniziare immaginando il numero approssimativo di tutti i protoni nell&#039;universo osservabile: presumo che tu fallisca con questo misero 10 all&#039;80a potenza. Per inciso, la probabilit\u00e0 di vincere alla lotteria \u00e8 1:13.983.816, che \u00e8 significativamente migliore di 1:10 alla potenza di 8.<\/em><br \/>\ndopo il dott Manzel: &quot;Il Vangelo delle scienze naturali&quot; (cfr 5).<\/p><\/blockquote>\n<p><strong>La scienza incontra la volont\u00e0 di Dio?<\/strong><br \/>\nLe nostre scienze esatte hanno percorso un percorso interessante negli ultimi secoli: costretti all&#039;opposizione dall&#039;intransigenza dei teologi, molti scienziati si sono dedicati alla lotta contro la superstizione e, con essa, all&#039;esposizione di insegnamenti ecclesiastici insostenibili.<\/p>\n<p>Tra scienza e fede si \u00e8 aperto un abisso apparentemente incolmabile.<\/p>\n<p>Con l&#039;aumentare del livello di conoscenza, le ultime scoperte diventano sempre pi\u00f9 trascendenti, le osservazioni fisiche sempre pi\u00f9 irreali, la fisica e la metafisica iniziano a toccarsi.<\/p>\n<p>Questo non \u00e8 sorprendente. Perch\u00e9 non c&#039;\u00e8 confine tra il terreno e il trascendente, tra questo mondo e l&#039;aldil\u00e0. Sono le limitazioni imposte dai nostri sensi o le limitazioni delle capacit\u00e0 di misurazione fisica che fanno sembrare queste aree separate.<\/p>\n<p>Il principio antropico si colloca nel campo di transizione tra fisica e metafisica. Non \u00e8 una teoria strettamente scientifica in quanto non pu\u00f2 essere dimostrata o smentita; ma stimola la riflessione, forse la ricerca di Dio.<\/p>\n<p>Il fisico teorico Paul Davies:<\/p>\n<p><em>&quot;Pu\u00f2 sembrare strano, ma dal mio punto di vista la scienza offre un approccio pi\u00f9 sicuro a Dio rispetto alla religione&quot;.<\/em> (2, pag. 15).<\/p>\n<p>I ricercatori nell&#039;universo non troveranno il vecchio Dio Padre dei teologi del Medioevo.<\/p>\n<p>In cambio incontrano l&#039;opera di un creatore onnipotente che ha ancorato la sua volont\u00e0 nella forma di leggi viventi nell&#039;universo. Queste leggi della natura o della creazione parlano il suo linguaggio e danno un&#039;idea della sua volont\u00e0 creativa.<\/p>\n<p>Leggi anche l&#039;articolo sotto &quot;Storia religiosa&quot;. <a href=\"https:\/\/www.siegfriedhagl.com\/it\/storia-religiosa\/ce-dio\/\">&quot;C&#039;\u00e8 Dio?&quot;<\/a> e alla voce &quot;Scienza&quot; il contributo <a href=\"https:\/\/www.siegfriedhagl.com\/it\/scienza\/un-universo-costruito\/\">&quot;Un universo costruito?&quot;<\/a>.<\/p>\n<p><strong>LETTERATURA:<br \/>\n<\/strong>(1) Breuer, Reinhard: &quot;Il principio antropico&quot;, Meyster, Vienna 1981.<br \/>\n(2) Davis, Paul: &quot;Dio e la fisica moderna&quot;, Goldmann, Monaco, 1989.<br \/>\n(3) Guitton, Jean\/Bogdanov, Grichka e Igor: &quot;Dio e scienza&quot;, DTV, Monaco di Baviera 1993.<br \/>\n(4) http:\/\/www.cip.physik.uni-muenchen.de\/+zimmermann\/dl\/anthrprinz.html.<br \/>\n(5) http:\/\/www.klawi.de\/anthr.p.htm#Anker1anthr.p.<br \/>\n(6) http:\/\/members.taunusstein.net\/.<br \/>\n(7) http:\/\/members.aol.com\/denkbar\/Astronomie.html#Anthrop.<\/p>","protected":false},"excerpt":{"rendered":"<p>(Ver\u00f6ffentlicht in GralsWelt 32\/2004) Die Welt ist voller Wunder, im Gr\u00f6\u00dften wie im Kleinsten. Eines dieser Wunder &#8211; also etwas, das wir nicht erkl\u00e4ren k\u00f6nnen &#8211; ist das feine Zusammenspiel, die exakt ausgewogene Abstimmung der Naturgesetze. Diese mussten genau so, durften keinesfalls geringf\u00fcgig anders sein, damit Sonnen, Planeten, Pflanzen, Tiere, Menschen in unserem Universum entstehen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-244","post","type-post","status-publish","format-standard","hentry","category-wissenschaft"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Urknall als Gottesbeweis &#8211; SiegfriedHagl.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siegfriedhagl.com\/it\/scienza\/il-big-bang-come-prova-di-dio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Urknall als Gottesbeweis &#8211; SiegfriedHagl.com\" \/>\n<meta property=\"og:description\" content=\"(Ver\u00f6ffentlicht in GralsWelt 32\/2004) Die Welt ist voller Wunder, im Gr\u00f6\u00dften wie im Kleinsten. Eines dieser Wunder &#8211; also etwas, das wir nicht erkl\u00e4ren k\u00f6nnen &#8211; ist das feine Zusammenspiel, die exakt ausgewogene Abstimmung der Naturgesetze. Diese mussten genau so, durften keinesfalls geringf\u00fcgig anders sein, damit Sonnen, Planeten, Pflanzen, Tiere, Menschen in unserem Universum entstehen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siegfriedhagl.com\/it\/scienza\/il-big-bang-come-prova-di-dio\/\" \/>\n<meta property=\"og:site_name\" content=\"SiegfriedHagl.com\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-25T16:49:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T09:00:23+00:00\" \/>\n<meta name=\"author\" content=\"siegfriedhagl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"siegfriedhagl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/der-urknall-als-gottesbeweis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/der-urknall-als-gottesbeweis\\\/\"},\"author\":{\"name\":\"siegfriedhagl\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"headline\":\"Der Urknall als Gottesbeweis\",\"datePublished\":\"2009-03-25T16:49:45+00:00\",\"dateModified\":\"2024-04-24T09:00:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/der-urknall-als-gottesbeweis\\\/\"},\"wordCount\":1430,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"articleSection\":[\"Wissenschaft\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/der-urknall-als-gottesbeweis\\\/\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/der-urknall-als-gottesbeweis\\\/\",\"name\":\"Der Urknall als Gottesbeweis &#8211; SiegfriedHagl.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\"},\"datePublished\":\"2009-03-25T16:49:45+00:00\",\"dateModified\":\"2024-04-24T09:00:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/der-urknall-als-gottesbeweis\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/der-urknall-als-gottesbeweis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/wissenschaft\\\/der-urknall-als-gottesbeweis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Urknall als Gottesbeweis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\",\"name\":\"SiegfriedHagl.com\",\"description\":\"Artikel und Blog von Siegfried Hagl\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\",\"name\":\"siegfriedhagl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"caption\":\"siegfriedhagl\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.hagl.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Big Bang come prova di Dio - SiegfriedHagl.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siegfriedhagl.com\/it\/scienza\/il-big-bang-come-prova-di-dio\/","og_locale":"it_IT","og_type":"article","og_title":"Der Urknall als Gottesbeweis &#8211; SiegfriedHagl.com","og_description":"(Ver\u00f6ffentlicht in GralsWelt 32\/2004) Die Welt ist voller Wunder, im Gr\u00f6\u00dften wie im Kleinsten. Eines dieser Wunder &#8211; also etwas, das wir nicht erkl\u00e4ren k\u00f6nnen &#8211; ist das feine Zusammenspiel, die exakt ausgewogene Abstimmung der Naturgesetze. Diese mussten genau so, durften keinesfalls geringf\u00fcgig anders sein, damit Sonnen, Planeten, Pflanzen, Tiere, Menschen in unserem Universum entstehen [&hellip;]","og_url":"https:\/\/www.siegfriedhagl.com\/it\/scienza\/il-big-bang-come-prova-di-dio\/","og_site_name":"SiegfriedHagl.com","article_published_time":"2009-03-25T16:49:45+00:00","article_modified_time":"2024-04-24T09:00:23+00:00","author":"siegfriedhagl","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"siegfriedhagl","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/der-urknall-als-gottesbeweis\/#article","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/der-urknall-als-gottesbeweis\/"},"author":{"name":"siegfriedhagl","@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"headline":"Der Urknall als Gottesbeweis","datePublished":"2009-03-25T16:49:45+00:00","dateModified":"2024-04-24T09:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/der-urknall-als-gottesbeweis\/"},"wordCount":1430,"publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"articleSection":["Wissenschaft"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/der-urknall-als-gottesbeweis\/","url":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/der-urknall-als-gottesbeweis\/","name":"Il Big Bang come prova di Dio - SiegfriedHagl.com","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/#website"},"datePublished":"2009-03-25T16:49:45+00:00","dateModified":"2024-04-24T09:00:23+00:00","breadcrumb":{"@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/der-urknall-als-gottesbeweis\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siegfriedhagl.com\/wissenschaft\/der-urknall-als-gottesbeweis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siegfriedhagl.com\/wissenschaft\/der-urknall-als-gottesbeweis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.siegfriedhagl.com\/"},{"@type":"ListItem","position":2,"name":"Der Urknall als Gottesbeweis"}]},{"@type":"WebSite","@id":"https:\/\/www.siegfriedhagl.com\/#website","url":"https:\/\/www.siegfriedhagl.com\/","name":"SiegfriedHagl.com","description":"Articolo e blog di Siegfried Hagl","publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siegfriedhagl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f","name":"siegfriedhagl","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","caption":"siegfriedhagl"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.hagl.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts\/244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/comments?post=244"}],"version-history":[{"count":19,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts\/244\/revisions"}],"predecessor-version":[{"id":7970,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts\/244\/revisions\/7970"}],"wp:attachment":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/media?parent=244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/categories?post=244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/tags?post=244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}