{"id":235,"date":"2009-03-25T12:57:04","date_gmt":"2009-03-25T11:57:04","guid":{"rendered":"https:\/\/www.siegfriedhagl.com\/?page_id=235"},"modified":"2026-02-02T13:28:14","modified_gmt":"2026-02-02T12:28:14","slug":"der-tempel-zu-jerusalem","status":"publish","type":"post","link":"https:\/\/www.siegfriedhagl.com\/it\/storia-religiosa\/il-tempio-di-gerusalemme\/","title":{"rendered":"Il Tempio di Gerusalemme"},"content":{"rendered":"<blockquote><p>(Pubblicato su GralsWelt 26\/2002)<\/p><\/blockquote>\n<p><strong>TERRA SANTA <\/strong><\/p>\n<p>Una striscia di terra al passaggio dall'Africa all'Asia, l'unico ponte terrestre tra questi grandi continenti, \u00e8 stata per migliaia di anni un punto di passaggio e di collegamento tra popoli, paesi, nazioni, culture: <strong>Palestina<\/strong>.<\/p>\n<p>Il commercio e gli scambi culturali si arricchirono, le campagne di guerra devastarono il Paese, che come la maggior parte dei Paesi di transito, stretti tra imperi pi\u00f9 grandi, trov\u00f2 una pace solo temporanea. Oggi, gli interessi dei diversi gruppi si scontrano nuovamente. Non sono affatto solo gli israeliani e i palestinesi a non riuscire a trovare un accordo in un Paese che non ha abbastanza acqua per la sua popolazione, cresciuta notevolmente negli ultimi decenni. Sullo sfondo ci sono Stati pi\u00f9 grandi che perseguono i propri interessi e non agiscono affatto in modo altruistico come dicono.<\/p>\n<p>Inoltre, l'attuale sanguinoso conflitto tra le due parti non riguarda qualcosa di concreto come una terra coltivabile con acqua sufficiente. Le passioni religiose hanno un peso maggiore in questa regione che in quasi tutti gli altri luoghi della terra. Perch\u00e9 c'\u00e8 <strong>Gerusalemme<\/strong>, la citt\u00e0 santa delle tre religioni abramitiche (o monoteiste): Ebraismo, cristianesimo e islam. Per i musulmani \u00e8 il terzo luogo pi\u00f9 importante; per i cristiani \u00e8 la citt\u00e0 dove si sono svolti gli eventi pi\u00f9 importanti della predicazione cristiana; per gli ebrei il Tempio distrutto di Gerusalemme \u00e8 il simbolo pi\u00f9 importante della loro fede, che un giorno risorger\u00e0 nel suo antico splendore.<\/p>\n<blockquote><p><em>\"Come l'ombelico si trova al centro del corpo umano,<\/em><br \/>\n<em> Cos\u00ec la terra d'Israele, in mezzo al mondo, \u00e8 l'ombelico del mondo.<\/em><br \/>\n<em> Gerusalemme \u00e8 il centro della terra d'Israele,<\/em><br \/>\n<em> e il tempio nel centro di Gerusalemme,<\/em><br \/>\n<em> e il Santo dei Santi nel tempio,<\/em><br \/>\n<em> e l'Arca dell'Alleanza al centro del Santo dei Santi,<\/em><br \/>\n<em> e l'altare davanti al Santissimo Sacramento,<\/em><br \/>\n<em> sono il centro del mondo che \u00e8 stato fondato qui\".<\/em><br \/>\nMidrash Tanchuma, Qedoshim (traduzione dall'inglese dopo (7))<\/p><\/blockquote>\n<p><strong>I TRE TEMPLI\u00a0<\/strong><\/p>\n<p><strong>Il Tempio di Salomone<\/strong><br \/>\nAls K\u00f6nig David (ca. 1000-961 v. Chr.) die Bundeslade in das gerade eroberte Jerusalem schaffen und in einem Zelt aufstellen lie\u00df, wollte er mit diesem wichtigsten Kultgegenstand in seiner neuen Hauptstadt die Herrschaft seines K\u00f6nigtums \u00fcber die verschiedenen j\u00fcdischen St\u00e4mme festigen. Das in der Bibel ausf\u00fchrlich beschriebene &#8222;Heilige Zelt&#8220; (2. Mose, 36,8 &#8211; 38) hat, wie Forscher vermuten, wahrscheinlich nicht in dieser Form existiert (4, S. 666), und das von David auf dem Jerusalemer Tempelberg zur Aufbewahrung der Bundeslade errichtete Zelt (2, Sam. 6,17) war einfacher ausgestattet, als das, von Luther als &#8222;Stiftsh\u00fctte&#8220; bezeichnete, &#8222;Heilige Zelt&#8220;.<\/p>\n<p>Era anche chiaro che l'Arca dell'Alleanza non poteva rimanere in una tenda per un tempo indefinito, e gi\u00e0 durante la vita di Davide era prevista la costruzione di un tempio, la cui esecuzione fu lasciata al figlio Salomone.<br \/>\nQuesto <strong>I templi di Salomone<\/strong> era molto apprezzato nei circoli culturali ebraici e cristiani, molto pi\u00f9 di altri edifici dell'antichit\u00e0, decisamente pi\u00f9 grandiosi. In questo tempio, infatti, veniva venerato il Dio degli ebrei, dei cristiani e dei musulmani. Qui si trovava il \"Santo dei Santi\", una stanza buia in cui solo il sommo sacerdote poteva entrare una volta all'anno (nel Giorno dell'Espiazione = Yom Kippur) per chiedere perdono a Dio. Secondo la tradizione, Dio era presente in questo Santo dei Santi; in altre parole, era possibile un contatto diretto tra l'uomo e Dio. Gli studiosi di religione vedono un parallelo con i templi egizi, dove il faraone poteva parlare con il suo Dio.<br \/>\nOltre alla funzione cultuale, il Tempio aveva anche una funzione politica. Come \"cappella reale\", doveva diventare il centro religioso delle due parti dell'impero, Israele e Giuda.<\/p>\n<p>La costruzione del tempio, non troppo grande, che si suppone fosse il doppio del tabernacolo e quindi circa 33 x 11 m (4, p. 663), fu un'impresa per il piccolo regno che mise a dura prova il suo potere economico. Gli ambiziosi progetti edilizi di Salomone richiedevano un lavoro faticoso, anche ai suoi stessi sudditi, mentre Davide aveva solo obbligato i popoli sottomessi ai lavori forzati. Questo sovraccarico delle capacit\u00e0 dei suoi popoli, che dovettero costruire un palazzo oltre al tempio, gett\u00f2 le basi per la disgregazione del regno dopo la morte di Salomone.<\/p>\n<p>Come riporta la Bibbia nel Primo Libro dei Re, per la costruzione fu necessario l'aiuto del re fenicio Hiram, che invi\u00f2 costruttori e artigiani oltre al legno di cedro. Con grande stupore degli israeliti, i fenici, tecnologicamente superiori, sapevano, ad esempio, tagliare la pietra: <em>\"Per la costruzione della casa furono utilizzate pietre gi\u00e0 sbozzate nella cava...\".<\/em> (1 Re 6:7).<\/p>\n<p>Numerose leggende si intrecciano intorno alla costruzione di questo tempio. Per esempio, nell'esoterismo massonico, il costruttore di templi fenicio Hiram-Abi, \"il figlio della vedova\", con le sue vaste conoscenze tecniche, gioca un ruolo importante.<\/p>\n<p>La fine di questo leggendario primo tempio avvenne con la conquista babilonese nel 586 a.C. La citt\u00e0 di Gerusalemme fu distrutta insieme al tempio e la maggior parte della popolazione fu deportata a Babilonia.<\/p>\n<p><strong>Il Tempio di Serubbabele<\/strong><em><br \/>\n<\/em>Fu una fortuna per gli ebrei che il tollerante Ciro II diventasse re dei persiani nel 559 a.C.. Sconfisse i Medi e conquist\u00f2 l'Impero babilonese. Permise agli ebrei deportati di tornare in patria intorno al 538 a.C. e ordin\u00f2 persino la ricostruzione del Tempio.<\/p>\n<p>Il Regno del Nord, che non \u00e8 centrale nella Bibbia e che \u00e8 stato pi\u00f9 importante per secoli, \u00e8 stato il pi\u00f9 importante del mondo. <strong>Israele<\/strong> era gi\u00e0 stata distrutta dagli Assiri nel 722 a.C.. I suoi abitanti deportati scomparvero dalla storia come le \"dieci trib\u00f9 perdute di Israele\". Solo il regno meridionale<strong> Giuda<\/strong> potrebbe risorgere come provincia persiana, con Gerusalemme come capitale. Tuttavia, la sua costruzione richiedeva tempo e difficolt\u00e0. Sotto il governatore Zorobabele, il Secondo Tempio fu costruito e consacrato nel 515 a.C.. La vita religiosa si \u00e8 rimessa in moto. Il Secondo Tempio aveva probabilmente le stesse dimensioni del Tempio di Salomone, ma mancava l'Arca dell'Alleanza e l'arredamento non poteva essere paragonato al precedente splendore. Cos\u00ec, nessuno \u00e8 stato in grado di riprodurre i pilastri d'ingresso Jachin e Boaz, fusi da Hiram-Abi con il miglior bronzo, il famoso mare di bronzo (1 Re 7,23; 2 Re 25,13) e molti altri oggetti di culto di grande valore.<br \/>\nSolo decenni dopo, quando Neemia*), che lavorava alla corte persiana, fu inviato nella provincia persiana di Giuda come governatore nel 445 a.C., le mura di Gerusalemme poterono finalmente essere restaurate.<\/p>\n<p>Ma ora sono sorte tensioni religiose. La conquista e la distruzione di Gerusalemme da parte dei Babilonesi avevano lasciato un profondo trauma. Molti, secondo l'antica tradizione profetica, incolpavano di questo il popolo, che si era presumibilmente allontanato dalla vera fede. Infatti, le ribellioni sconsiderate dei re Jaiakim e soprattutto Zidkia contro i Babilonesi avevano provocato la loro vendetta.<br \/>\nNella diaspora, molti ebrei erano entrati in contatto con altri insegnamenti. I vittoriosi persiani erano poi seguaci di Zarathustra, la cui filosofia arricch\u00ec la religione ebraica ma sfid\u00f2 il sacerdozio ortodosso del tempio. Inoltre, c'erano molti matrimoni tra ebrei e non ebrei; e questi ultimi erano sospettati di adorare ancora vecchi dei, come Baal.<\/p>\n<p>I signori persiani erano tolleranti in termini religiosi e Neemia fu in grado di avviare un ritorno alla Legge mosaica per alleviare le tensioni religiose.<br \/>\nPoi Esdra (nato intorno al 397 a.C. nell'esilio babilonese) apparve a Gerusalemme intorno al 458 a.C., sacerdote e scriba. Fu incaricato dai Persiani di porre fine al tumulto religioso. Esdra, un fanatico religioso, promosse la fede in Yahweh e richiese una stretta osservanza delle leggi religiose. Gli ebrei dovevano separarsi dalle donne non ebree e ai non ebrei era vietato l'accesso al Monte del Tempio. Chiunque si opponesse a questa vittoria dell'ortodossia veniva minacciato di confisca dei beni, di esilio e persino di morte.<\/p>\n<p>Nel confronto con l'ellenismo, nel II secolo a.C. si form\u00f2 un gruppo religioso ortodosso, gli \"Ashkenazim\", che si dedicava alla rigorosa osservanza delle leggi degli antenati. Queste persone \"pie\" o \"riverenti\" continuarono l'opera iniziata da Esdra.<br \/>\nAncora oggi si parla di Sephardim (Sefarditi), gli ebrei pi\u00f9 orientati intellettualmente che furono espulsi dalla Spagna e dal Portogallo nel XV e XVI secolo, e dell'ebraismo strettamente religioso e in parte mistico degli Ashkenazim, a cui gli ebrei della Germania e dell'Europa orientale appartenevano ancora nel XX secolo. Cos\u00ec come i Chassidim, un gruppo pi\u00f9 orientato al misticismo che probabilmente emerse in Polonia nel XVIII secolo.<br \/>\nOggi si ritiene che gli ortodossi abbiano un'influenza sulla politica dello Stato di Israele da non sottovalutare.<\/p>\n<p><strong>Il Tempio di Erode<\/strong><br \/>\nDer Sieg der Orthodoxie st\u00e4rkte die Tempelpriesterschaft, erzwang im Inneren die religi\u00f6se Einheit, und schottete Juden von Nichtjuden rituell ab. \u00c4u\u00dferen Einfl\u00fcssen hingegen konnte die Provinz Juda mangels milit\u00e4rischer St\u00e4rke sich nicht verschlie\u00dfen. Nach der Zerst\u00f6rung des Persischen Reiches durch Alexander den Gro\u00dfen (356-323 v. Chr.) kam Juda unter \u00c4gyptische (Ptolem\u00e4er), Griechische (Seleukiden) und zuletzt R\u00f6mische Herrschaft. Zwischendurch gab es, durch den erfolgreichen, religi\u00f6s motivierten Makkab\u00e4er-Aufstand, eine kurze Periode der labilen Selbst\u00e4ndigkeit.**) Als Jesus geboren wurde, war Herodes der Gro\u00dfe (73 &#8211; 4 v. Chr.)***) mit r\u00f6mischer Unterst\u00fctzung K\u00f6nig von Jud\u00e4a.<\/p>\n<p>Nel tumulto bellico dei secoli, il Secondo Tempio fu saccheggiato e danneggiato pi\u00f9 volte; un restauro vicino a una nuova costruzione era dovuto. Cos\u00ec, sotto Erode, fu costruito l'imponente edificio del tempio dove un tempo insegnava Ges\u00f9.<\/p>\n<blockquote><p><em>\"L'esterno del tempio aveva tutto per stupire il cuore e gli occhi. Il tempio, infatti, era tutto ricoperto di lastre d'oro e, quando il sole sorgeva, emanava una luce come di fuoco, tanto che chi guardava, anche se volutamente, distoglieva lo sguardo come dai raggi del sole. In effetti, gli stranieri che si avvicinavano a Gerusalemme avevano l'impressione di una cima innevata; infatti, dove mancava l'oro, era di un bianco brillante\".<\/em><br \/>\nLo storico ebreo Flavio Giuseppe (I secolo d.C.) sul tempio di Erode, citato da (3, p. 32).<\/p><\/blockquote>\n<p>Alcuni parlano del Tempio di Erode come del \"Terzo Tempio\" dove predic\u00f2 il Messia, ma nel censimento ebraico, a prescindere dalle varie ristrutturazioni e dalle generose ricostruzioni ed espansioni di Erode, si tratta ancora del Secondo Tempio.<br \/>\nIl Tempio di Erode, un edificio molto ammirato dell'antichit\u00e0, rimase in piedi solo fino all'anno 70, quando il comandante romano Tito conquist\u00f2 Gerusalemme per sedare una rivolta ebraica scoppiata nel 66. Nel frattempo, i legionari infuriati bruciarono la citt\u00e0 e il tempio contro la volont\u00e0 del comandante.<\/p>\n<p><strong>Il Terzo Tempio<\/strong><br \/>\nDalla distruzione del Tempio erodiano, nel corso dei secoli ci sono stati vari tentativi di ricostruzione, tutti falliti (cfr. ad es. 3). Con la conquista di Gerusalemme da parte di Israele nella Guerra dei Sei Giorni (1967), le speranze secolari degli ebrei ortodossi per la restaurazione del Tempio acquistarono nuova forza. Nell'esoterismo ebraico si trovano profezie bibliche ed extrabibliche che annunciano la ricostruzione del Tempio nell'era del Messia e che impegnano i fedeli a impegnarsi pienamente nella ricostruzione (cfr. ad es. 3).<br \/>\nL'esatta ubicazione dell'antico tempio, e quindi del luogo in cui sarebbe stato costruito il futuro \"Terzo Tempio\", \u00e8 nota solo approssimativamente. Spesso si presume che il Santo dei Santi fosse situato al centro dell'attuale Cupola della Roccia. Finch\u00e9 gli scavi archeologici sul Monte del Tempio non saranno fattibili, molte domande sul Monte del Tempio e sui passaggi sotterranei al suo interno dovranno rimanere senza risposta.<\/p>\n<p><strong>IL FUTURO DELLA COLLINA DEL TEMPIO<\/strong><br \/>\nSul Monte del Tempio, dove un tempo sorgevano gli antichi santuari ebraici, oggi si trovano la Cupola della Roccia islamica (Moschea di Omar, del VII secolo) e la Moschea di Al-Aksa. I musulmani considerano la \"Sacra Roccia\" della Moschea di Omar come il luogo da cui Maometto fu catturato nei sette cieli. Un'altra leggenda vuole che Abramo abbia sacrificato qui. I santuari cristiani della \"Terra Promessa\" non si trovano sul Monte del Tempio.<\/p>\n<p>Dopo la Guerra dei Sei Giorni, il moderato ministro della Difesa israeliano Moshe Dayan (1915-1981) lasci\u00f2 il Monte del Tempio al controllo musulmano; un atto diplomatico di tolleranza che ancora oggi indigna sionisti ed ebrei ortodossi. A quanto si sa, negli ultimi decenni ci sono stati quattro tentativi di far esplodere la Cupola della Roccia da parte di ebrei ultraortodossi (1, p. 11). Tentativi di assassinio che, se fossero andati a buon fine, avrebbero profondamente indignato l'intero mondo islamico.<br \/>\nAgli ebrei rimase solo una parte del Muro occidentale del Tempio erodiano, il \"Muro del Pianto\", come luogo di preghiera e di memoria.<\/p>\n<p>Oggi, sul Monte del Tempio, le rivendicazioni di due religioni si scontrano ferocemente, una parla della <em>\"I metri quadrati pi\u00f9 esplosivi del mondo\".<\/em> (New York Times, 3, p. 9).<br \/>\nI musulmani si riferiscono al potere dei fatti, ai fatti creati pi\u00f9 di un millennio fa con la costruzione della Cupola della Roccia e della Moschea di Al-Aksa. La Cupola della Roccia, la cupola dorata che sovrasta la Santa Roccia creata non tanto per le funzioni di preghiera quanto per le processioni di pellegrinaggio, \u00e8 uno degli edifici pi\u00f9 apprezzati dall'umanit\u00e0 in termini di cultura e storia dell'arte.<\/p>\n<p>Questi edifici, eretti dai musulmani molti secoli fa sul Monte del Tempio, ora ostacolano il desiderio di molti ebrei devoti di ricostruire il tempio ebraico, un tempo defunto, sul suo vecchio sito, nel modo pi\u00f9 fedele possibile. Questo tempio era stato il centro della religiosit\u00e0 ebraica per un millennio. Dopo la sua distruzione, i fedeli ebrei, sparsi in tutto il mondo, hanno desiderato per due millenni il centro cultuale perduto e hanno sperato nella sua promessa profetica resurrezione. Dopo che lo Stato di Israele ha preso possesso di Gerusalemme, la realizzazione di questo antico desiderio sembrava a portata di mano.<\/p>\n<p>Wie kann ein Kompromiss aussehen, der die Hoffnungen der gl\u00e4ubigen Juden befriedigt, ohne die religi\u00f6sen Gef\u00fchle von mehr als einer Milliarde Muslimen zu verletzen, als eine Voraussetzung f\u00fcr die von allen Parteien angestrebte friedliche Zukunft des so oft von Krieg und Zerst\u00f6rung gequ\u00e4lten &#8222;Heiligen Landes&#8220;?<br \/>\nZwei Weltreligionen haben hier die Chance, die friedenstiftende Kraft ihres Glaubens zu beweisen, und zu zeigen, dass sie beide dem einen Gott dienen, der ein Gott des Friedens ist.<\/p>\n<p><strong>Note di chiusura:<br \/>\n<\/strong>*) Neemia, proveniente da una famiglia di Gerusalemme, divenne eunuco alla corte persiana e coppiere del re nel 445 a.C. (1).<br \/>\n** ) Cfr. \"Un capriccio influenza la storia del mondo\" in \"Breve, conciso, curioso\" pag. 279.<br \/>\n***) Ges\u00f9 \u00e8 nato probabilmente nel 7 a.C. (cfr. 5). Cfr. anche <a href=\"https:\/\/www.siegfriedhagl.com\/it\/storia\/dallinizio-del-nostro-tempo\/\">\"Dall'inizio del nostro tempo<\/a>, sotto \"Storia\"). Al momento della sua crocifissione (30 d.C.), Erode Antipa (20 a.C.-39 d.C.) era re della Giudea.<\/p>\n<p><strong>Letteratura:<\/strong><br \/>\n(1) Andrews, Richard \"Temple of Promise\", Gustav L\u00fcbbe, Bergisch Gladbach, 1999.<br \/>\n(2) Freedman, David Noel\/Robinson, Thomas L. \"1000 domande alle Sacre Scritture\", Das Beste, Stoccarda 1992.<br \/>\n(3) Liebi, Roger \"Gerusalemme - Hindernis f\u00fcr den Weltfrieden?\", Schwengeler, CH-9442 Berneck, 1995.<br \/>\n(4) Mertens, Heinrich A. \"Handbuch der Bibelkunde\", Bechterm\u00fcnz, Augsburg 1997.<br \/>\n(5) Naredi-Rainer, Paul v. \"Salomons Tempel\", Dumont, Colonia 1994.<br \/>\n(6) Negev, Avraham \"Arch\u00e4ologisches Bibellexikon\", H\u00e4nssler, Neuhausen-Stuttgart, 1991.<br \/>\n(7) http:\/\/www.templemount.org\/.<\/p>","protected":false},"excerpt":{"rendered":"<p>(Ver\u00f6ffentlicht in GralsWelt 26\/2002) DAS HEILIGE LAND Ein Landstreifen am \u00dcbergang von Afrika nach Asien, die einzige Landbr\u00fccke zwischen diesen gro\u00dfen Kontinenten, ist seit Jahrtausenden Durchgangs- und Verbindungsstelle zwischen V\u00f6lkern, L\u00e4ndern, Nationen, Kulturkreisen: Pal\u00e4stina. Handel und Kulturaustausch bereicherten, Kriegsz\u00fcge verheerten das Land, das wie die meisten Transitl\u00e4nder, eingezw\u00e4ngt zwischen gr\u00f6\u00dferen Reichen, nur vor\u00fcbergehend Ruhe fand. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-235","post","type-post","status-publish","format-standard","hentry","category-religionsgeschichte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Tempel zu Jerusalem &#8211; SiegfriedHagl.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siegfriedhagl.com\/it\/storia-religiosa\/il-tempio-di-gerusalemme\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Tempel zu Jerusalem &#8211; SiegfriedHagl.com\" \/>\n<meta property=\"og:description\" content=\"(Ver\u00f6ffentlicht in GralsWelt 26\/2002) DAS HEILIGE LAND Ein Landstreifen am \u00dcbergang von Afrika nach Asien, die einzige Landbr\u00fccke zwischen diesen gro\u00dfen Kontinenten, ist seit Jahrtausenden Durchgangs- und Verbindungsstelle zwischen V\u00f6lkern, L\u00e4ndern, Nationen, Kulturkreisen: Pal\u00e4stina. Handel und Kulturaustausch bereicherten, Kriegsz\u00fcge verheerten das Land, das wie die meisten Transitl\u00e4nder, eingezw\u00e4ngt zwischen gr\u00f6\u00dferen Reichen, nur vor\u00fcbergehend Ruhe fand. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siegfriedhagl.com\/it\/storia-religiosa\/il-tempio-di-gerusalemme\/\" \/>\n<meta property=\"og:site_name\" content=\"SiegfriedHagl.com\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-25T11:57:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T12:28:14+00:00\" \/>\n<meta name=\"author\" content=\"siegfriedhagl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"siegfriedhagl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/religionsgeschichte\\\/der-tempel-zu-jerusalem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/religionsgeschichte\\\/der-tempel-zu-jerusalem\\\/\"},\"author\":{\"name\":\"siegfriedhagl\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"headline\":\"Der Tempel zu Jerusalem\",\"datePublished\":\"2009-03-25T11:57:04+00:00\",\"dateModified\":\"2026-02-02T12:28:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/religionsgeschichte\\\/der-tempel-zu-jerusalem\\\/\"},\"wordCount\":2417,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"articleSection\":[\"Religionsgeschichte\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/religionsgeschichte\\\/der-tempel-zu-jerusalem\\\/\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/religionsgeschichte\\\/der-tempel-zu-jerusalem\\\/\",\"name\":\"Der Tempel zu Jerusalem &#8211; SiegfriedHagl.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\"},\"datePublished\":\"2009-03-25T11:57:04+00:00\",\"dateModified\":\"2026-02-02T12:28:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/religionsgeschichte\\\/der-tempel-zu-jerusalem\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siegfriedhagl.com\\\/religionsgeschichte\\\/der-tempel-zu-jerusalem\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/religionsgeschichte\\\/der-tempel-zu-jerusalem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Tempel zu Jerusalem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#website\",\"url\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/\",\"name\":\"SiegfriedHagl.com\",\"description\":\"Artikel und Blog von Siegfried Hagl\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.siegfriedhagl.com\\\/#\\\/schema\\\/person\\\/263c4a916fa13b3e7eda58f6c8c2695f\",\"name\":\"siegfriedhagl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\",\"caption\":\"siegfriedhagl\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.hagl.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Tempio di Gerusalemme - SiegfriedHagl.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siegfriedhagl.com\/it\/storia-religiosa\/il-tempio-di-gerusalemme\/","og_locale":"it_IT","og_type":"article","og_title":"Der Tempel zu Jerusalem &#8211; SiegfriedHagl.com","og_description":"(Ver\u00f6ffentlicht in GralsWelt 26\/2002) DAS HEILIGE LAND Ein Landstreifen am \u00dcbergang von Afrika nach Asien, die einzige Landbr\u00fccke zwischen diesen gro\u00dfen Kontinenten, ist seit Jahrtausenden Durchgangs- und Verbindungsstelle zwischen V\u00f6lkern, L\u00e4ndern, Nationen, Kulturkreisen: Pal\u00e4stina. Handel und Kulturaustausch bereicherten, Kriegsz\u00fcge verheerten das Land, das wie die meisten Transitl\u00e4nder, eingezw\u00e4ngt zwischen gr\u00f6\u00dferen Reichen, nur vor\u00fcbergehend Ruhe fand. [&hellip;]","og_url":"https:\/\/www.siegfriedhagl.com\/it\/storia-religiosa\/il-tempio-di-gerusalemme\/","og_site_name":"SiegfriedHagl.com","article_published_time":"2009-03-25T11:57:04+00:00","article_modified_time":"2026-02-02T12:28:14+00:00","author":"siegfriedhagl","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"siegfriedhagl","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siegfriedhagl.com\/religionsgeschichte\/der-tempel-zu-jerusalem\/#article","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/religionsgeschichte\/der-tempel-zu-jerusalem\/"},"author":{"name":"siegfriedhagl","@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"headline":"Der Tempel zu Jerusalem","datePublished":"2009-03-25T11:57:04+00:00","dateModified":"2026-02-02T12:28:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siegfriedhagl.com\/religionsgeschichte\/der-tempel-zu-jerusalem\/"},"wordCount":2417,"publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"articleSection":["Religionsgeschichte"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.siegfriedhagl.com\/religionsgeschichte\/der-tempel-zu-jerusalem\/","url":"https:\/\/www.siegfriedhagl.com\/religionsgeschichte\/der-tempel-zu-jerusalem\/","name":"Il Tempio di Gerusalemme - SiegfriedHagl.com","isPartOf":{"@id":"https:\/\/www.siegfriedhagl.com\/#website"},"datePublished":"2009-03-25T11:57:04+00:00","dateModified":"2026-02-02T12:28:14+00:00","breadcrumb":{"@id":"https:\/\/www.siegfriedhagl.com\/religionsgeschichte\/der-tempel-zu-jerusalem\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siegfriedhagl.com\/religionsgeschichte\/der-tempel-zu-jerusalem\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siegfriedhagl.com\/religionsgeschichte\/der-tempel-zu-jerusalem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.siegfriedhagl.com\/"},{"@type":"ListItem","position":2,"name":"Der Tempel zu Jerusalem"}]},{"@type":"WebSite","@id":"https:\/\/www.siegfriedhagl.com\/#website","url":"https:\/\/www.siegfriedhagl.com\/","name":"SiegfriedHagl.com","description":"Articolo e blog di Siegfried Hagl","publisher":{"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siegfriedhagl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.siegfriedhagl.com\/#\/schema\/person\/263c4a916fa13b3e7eda58f6c8c2695f","name":"siegfriedhagl","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g","caption":"siegfriedhagl"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/45b010d0734a07d6fa163753be02d78684ff4128f419d6ee0a0370de54233f1c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.hagl.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/comments?post=235"}],"version-history":[{"count":32,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts\/235\/revisions"}],"predecessor-version":[{"id":12162,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/posts\/235\/revisions\/12162"}],"wp:attachment":[{"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/media?parent=235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/categories?post=235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siegfriedhagl.com\/it\/wp-json\/wp\/v2\/tags?post=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}